{"id":10316,"date":"2011-08-09T15:37:48","date_gmt":"2011-08-09T20:07:48","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=10316"},"modified":"2019-09-01T03:22:04","modified_gmt":"2019-09-01T07:22:04","slug":"cmas-zona-america-realiza-la-propuesta-de-su-calendario-deportivo-2012","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/cmas-zona-america-realiza-la-propuesta-de-su-calendario-deportivo-2012\/","title":{"rendered":"\ud83c\udf0e CMAS Zona Am\u00e9rica realiza la propuesta de su Calendario Deportivo 2012"},"content":{"rendered":"<p><img decoding=\"async\" class=\"alignnone size-full wp-image-10317\" title=\"cmas-zona-america\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/08\/cmas-zona-america.jpg\" alt=\"\" width=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/08\/cmas-zona-america.jpg 640w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/08\/cmas-zona-america-300x225.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/08\/cmas-zona-america-320x240.jpg 320w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/p>\n<p>(Especial Sportalsub.net \/ CMAS Zona Am\u00e9rica)<br \/>\nDe manera exclusiva para <a href=\"http:\/\/www.sportalsub.net\">www.sportalsub.net<\/a> el Presidente del Comit\u00e9 Deportivo de la CMAS Zona Am\u00e9rica, el cubano Orestes Garc\u00eda nos env\u00eda la propuesta de Calendario de eventos avalados por la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas para la Zona Americana del pr\u00f3ximo a\u00f1o 2012. La propuesta a\u00fan est\u00e1 a la espera de la aprobaci\u00f3n definitiva de las Federaciones y el Directorio del organismo subacu\u00e1tico panamericano, pero sirve desde ya para que Federaciones, Entrenadores y Deportistas fijen los eventos en sus cronogramas anuales e inicien la preparaci\u00f3n para estos campeonatos que permitir\u00e1n el encuentro y sana competencia entre las naciones del continente.<\/p>\n<table border=\"0\" cellspacing=\"2\" cellpadding=\"2\">\n<tbody>\n<tr>\n<td><strong>EVENTO<\/strong><\/td>\n<td><strong>PA\u00cdS<\/strong><\/td>\n<td><strong>FECHA<\/strong><\/td>\n<td><strong>MODALIDADES<\/strong><\/td>\n<\/tr>\n<tr>\n<td>Fotosub 2012<\/td>\n<td><img decoding=\"async\" src=\"http:\/\/es.fifa.com\/imgml\/flags\/s\/cub.gif\" alt=\"chi Eventos\" \/>\u00a0Cuba<\/td>\n<td>10 al 12 de Mayo<\/td>\n<td>Fotograf\u00eda Submarina<\/td>\n<\/tr>\n<tr>\n<td>Copa Panamericana<\/td>\n<td><img decoding=\"async\" src=\"http:\/\/es.fifa.com\/imgml\/flags\/s\/col.gif\" alt=\"chi Eventos\" \/>\u00a0Colombia<\/td>\n<td>30 de Marzo al 4 de Abril<\/td>\n<td>Apnea y Nataci\u00f3n con Aletas<\/td>\n<\/tr>\n<tr>\n<td>Copa de Hockey Subacu\u00e1tico<\/td>\n<td><img decoding=\"async\" src=\"http:\/\/es.fifa.com\/imgml\/flags\/s\/col.gif\" alt=\"chi Eventos\" \/>\u00a0Colombia<\/td>\n<td>8 al 11 de Junio<\/td>\n<td>Hockey Subacu\u00e1tico<\/td>\n<\/tr>\n<tr>\n<td>Copa de Rugby Subacu\u00e1tico<\/td>\n<td><img decoding=\"async\" src=\"http:\/\/es.fifa.com\/imgml\/flags\/s\/col.gif\" alt=\"chi Eventos\" \/>\u00a0Colombia<\/td>\n<td>15 al 18 de Junio<\/td>\n<td>Rugby Subacu\u00e1tico<\/td>\n<\/tr>\n<tr>\n<td>Festival de Jump Blue<\/td>\n<td><img decoding=\"async\" src=\"http:\/\/es.fifa.com\/imgml\/flags\/s\/ecu.gif\" alt=\"chi Eventos\" \/>\u00a0Ecuador<\/td>\n<td><\/td>\n<td>Apnea Jump Blue<\/td>\n<\/tr>\n<tr>\n<td>Copa Internacional<\/td>\n<td><img decoding=\"async\" src=\"http:\/\/es.fifa.com\/imgml\/flags\/s\/cub.gif\" alt=\"chi Eventos\" \/>\u00a0Cuba<\/td>\n<td>12 al 17 de Octubre<\/td>\n<td>Apnea y Nataci\u00f3n con Bialetas<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>M\u00e1s informaci\u00f3n:<\/strong> Orestes Garc\u00eda &#8211; <a href=\"mailto:orestesgm30@hotmail.com\">orestesgm30@hotmail.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Especial Sportalsub.net \/ CMAS Zona Am\u00e9rica) De manera exclusiva para www.sportalsub.net el Presidente del Comit\u00e9 Deportivo de la CMAS Zona Am\u00e9rica, el cubano Orestes Garc\u00eda nos env\u00eda la propuesta de Calendario de eventos avalados por la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas para la Zona Americana del pr\u00f3ximo a\u00f1o 2012. La propuesta a\u00fan est\u00e1 a la espera de la aprobaci\u00f3n definitiva [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":10317,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,4,101,177,83,148,3,80,133,176,19,2,98,12,119,7,204,8],"tags":[],"class_list":["post-10316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-argentina","category-brasil","category-canada","category-chile","category-cmas-organizaciones","category-colombia","category-cuba","category-destacados-anteriores","category-estados-unidos","category-fotografia-submarina","category-hockey-subacuatico","category-mexico","category-natacion-con-aletas","category-peru","category-rugby-subacuatico","category-uruguay","category-venezuela"],"modified_by":"Sportalsub.net","views":6379,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-2Go","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":3466,"url":"https:\/\/www.sportalsub.net\/blog\/natacion-con-aletas-rumbo-a-los-juegos-sudamericanos-odesur-2014-en-chile\/","url_meta":{"origin":10316,"position":0},"title":"\ud83c\udf0e Nataci\u00f3n con Aletas rumbo a los Juegos Sudamericanos ODESUR 2014 en Chile","author":"Sportalsub.net","date":"4 diciembre 2009","format":false,"excerpt":"Juan Jos\u00e9 Maldonado, Oscar Ruiz Cubill\u00e1n y Miguel Cede\u00f1o (Viernes 4 de diciembre - Especial Sportalsub.net) El pasado mi\u00e9rcoles 2 de diciembre, en la sede de la Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas se reunieron Oscar Ruiz, Vicepresidente de la CMAS Zona Am\u00e9rica y miembro del Boureau Ejecutivo de la CMAS,\u2026","rel":"","context":"En \u00abArgentina\u00bb","block_context":{"text":"Argentina","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/argentina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/reunion.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":24274,"url":"https:\/\/www.sportalsub.net\/blog\/continuan-las-actividades-subacuaticas-en-el-continente-americano-cmas-zona-america\/","url_meta":{"origin":10316,"position":1},"title":"\ud83c\udf0e Contin\u00faan las Actividades Subacu\u00e1ticas en el Continente Americano  de la mano de CMAS Zona Am\u00e9rica","author":"Sportalsub.net","date":"26 mayo 2016","format":false,"excerpt":"Especial Sportalsub.net \/ CMAS Zona Am\u00e9rica \/ Miguel A. Cede\u00f1o O. La Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas Zona Am\u00e9rica (CMAS Zona Am\u00e9rica), agrupa a las Federaciones Nacionales, Asociaciones u Organismos afiliados a la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (C.M.A.S) en la zona americana y se encarga de fomentar las actividades\u2026","rel":"","context":"En \u00abActividades Subacu\u00e1ticas\u00bb","block_context":{"text":"Actividades Subacu\u00e1ticas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/cmas-zonaamericafeat-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/cmas-zonaamericafeat-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/cmas-zonaamericafeat-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/cmas-zonaamericafeat-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":41233,"url":"https:\/\/www.sportalsub.net\/blog\/1er-encuentro-fvas-venezuela-2020","url_meta":{"origin":10316,"position":2},"title":"\ud83c\uddfb\ud83c\uddea Realizado 1er Encuentro FVAS Venezuela 2020: Las Actividades Subacu\u00e1ticas. Antes, durante y despu\u00e9s del Covid-19","author":"Sportalsub.net","date":"20 agosto 2020","format":false,"excerpt":"(Sportalsub.net \/ FVAS) La Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas organiz\u00f3 con todo \u00e9xito el\u00a01er Encuentro FVAS 2020: Las Actividades Subacu\u00e1ticas y nuestra Federaci\u00f3n. Antes, durante y despu\u00e9s del Covid-19, realizado el\u00a0s\u00e1bado 15 de agosto\u00a0de 2020 de\u00a09:00am a 2:15pm, v\u00eda Zoom y Facebook Live de la Federaci\u00f3n, en donde se realizaron\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/08\/1encuentrofvas2020-S.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/08\/1encuentrofvas2020-S.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/08\/1encuentrofvas2020-S.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/08\/1encuentrofvas2020-S.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":27965,"url":"https:\/\/www.sportalsub.net\/blog\/cmas-zona-america-asamblea-cmas-2018","url_meta":{"origin":10316,"position":3},"title":"\ud83c\uddf9\ud83c\udded CMAS Zona Am\u00e9rica presente en la Asamblea General CMAS 2018 en Tailandia","author":"Sportalsub.net","date":"26 abril 2018","format":false,"excerpt":"(Sportalsub.net \/ CMAS Zona Am\u00e9rica) Del 25 al 27 de abril de 2018 se lleva a cabo en Phuket, Tailandia, la Asamblea General Ordinaria Anual de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS), en la que el m\u00e1ximo ente rector de las Actividades Subacu\u00e1ticas ofrece el\u00a0Informe de las actividades del\u2026","rel":"","context":"En \u00abActividades Subacu\u00e1ticas\u00bb","block_context":{"text":"Actividades Subacu\u00e1ticas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/cmas-tailandia-2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/cmas-tailandia-2018.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/cmas-tailandia-2018.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/cmas-tailandia-2018.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4008,"url":"https:\/\/www.sportalsub.net\/blog\/3ra-copa-panamericana-de-actividades-subacuaticas-de-cmas-zona-america\/","url_meta":{"origin":10316,"position":4},"title":"\ud83c\udde8\ud83c\uddfa 3ra Copa Panamericana de Actividades Subacu\u00e1ticas de CMAS Zona Am\u00e9rica","author":"Sportalsub.net","date":"9 febrero 2010","format":false,"excerpt":"Foto: Ronald Laurens @ Sportalsub.net La Federaci\u00f3n Cubana de Actividades Subacu\u00e1ticas, con el aval del Comit\u00e9 Deportivo CMAS de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas y de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas Zona Am\u00e9rica, a trav\u00e9s de su Comit\u00e9 Deportivo, convoca a las Federaciones afiliadas a la C.M.A.S. a\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/02\/RUTH_ESTATICA.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/02\/RUTH_ESTATICA.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/02\/RUTH_ESTATICA.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":39368,"url":"https:\/\/www.sportalsub.net\/blog\/finswimming-fisu-cmas-2020","url_meta":{"origin":10316,"position":5},"title":"\ud83c\udf0e Nataci\u00f3n con Aletas tendr\u00e1 Eventos Mundiales Universitarios FISU a partir de 2022","author":"Sportalsub.net","date":"28 septiembre 2020","format":false,"excerpt":"(Sportalsub.net \/ FISU \/ CMAS \/ CMAS Zona Am\u00e9rica) - Read in English La Federaci\u00f3n Internacional de Deportes Universitarios (FISU) otorg\u00f3 el pasado martes 3 de marzo de 2020 el reconocimiento oficial a la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS) y a las Actividades Subacu\u00e1ticas, en la modalidad de Nataci\u00f3n\u2026","rel":"","context":"En \u00abDestacados\u00bb","block_context":{"text":"Destacados","link":"https:\/\/www.sportalsub.net\/blog\/category\/mas\/destacados\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/fisu-cmas-2020.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/fisu-cmas-2020.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/fisu-cmas-2020.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/fisu-cmas-2020.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/08\/cmas-zona-america.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/10316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=10316"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/10316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/10317"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=10316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=10316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=10316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}