{"id":11336,"date":"2011-11-21T12:05:11","date_gmt":"2011-11-21T16:35:11","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=11336"},"modified":"2019-09-01T01:37:48","modified_gmt":"2019-09-01T05:37:48","slug":"seleccion-colombia-sub-21-obtuvo-el-3er-lugar-en-la-copa-nordica-de-rugby-subacuatico-2011","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/seleccion-colombia-sub-21-obtuvo-el-3er-lugar-en-la-copa-nordica-de-rugby-subacuatico-2011\/","title":{"rendered":"\ud83c\udde8\ud83c\uddf4 Selecci\u00f3n Colombia Sub-21 obtuvo el 3er lugar en la Copa N\u00f3rdica de Rugby Subacu\u00e1tico 2011"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11338\" title=\"\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/copa-nordicasub21.jpg\" alt=\"\" width=\"600\" height=\"268\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/copa-nordicasub21.jpg 600w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/copa-nordicasub21-300x134.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/copa-nordicasub21-364x164.jpg 364w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>(Especial Sportalsub.net)<br \/>\nLa Selecci\u00f3n Sub-21 de Colombia obtuvo el 3er lugar en la Copa N\u00f3rdica de Rugby Subacu\u00e1tico 2011 efectuada del 18 al 20 de noviembre en la localidad de Oxel\u00f6sund, Suecia. Colombia logr\u00f3 el 3er puesto al superar por marcador de 4 goles a 1 al combinado de Noruega en el partido que otorgaba la medalla de Bronce. El primer lugar fue para la Selecci\u00f3n de Alemania que venci\u00f3 en el partido final por 5 goles a 0 a la Selecci\u00f3n de Suecia.<\/p>\n<p>Colombia se situ\u00f3 en el 3er puesto en la primera ronda del torneo, con 2 victorias: (2-1 sobre Noruega, 2-0 sobre Dinamarca y 2 derrotas: (1-2 ante Suecia y 0-5 ante Alemania) y tambi\u00e9n venci\u00f3 a la Selecci\u00f3n de la Rep\u00fablica Checa 8-1 en partido fuera del torneo, ya que el equipo checo contaba con jugadores de mayor edad a la permitida.<\/p>\n<p>En conclusi\u00f3n la actuaci\u00f3n para Colombia en el evento registr\u00f3 un balance favorable y positivo de 4 partidos ganados, 2 perdidos con 17 goles a favor y 10 en contra.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/pdf.gif\" alt=\"\" \/>\u00a0<a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/Junior-Nordic-Cup-2011-Results-and-statistics.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Resultados y estad\u00edsticas del Campeonato<\/a><\/strong><\/p>\n<p>Fuente:<\/p>\n<p><strong><a href=\"http:\/\/iof3.idrottonline.se\/SvenskaSportdykarforbundet\/UV-rugby\/Nyheter\/NyheterUV-rugby\/JNM2011iOxelosund\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Sitio Oficial<\/a>\u00a0<\/strong><br \/>\n<strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/fb.png\" alt=\"Facebook\" \/>\u00a0<a href=\"http:\/\/www.facebook.com\/pages\/U-21-Underwater-Rugby-Nordic-Cup-Oxel%C3%B6sund-2011\/293281404022018?sk=wall\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Evento en Facebook\u00a0<\/a><\/strong><\/p>\n<p>Con informaci\u00f3n de:\u00a0<strong><a href=\"http:\/\/www.6alagua.com\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">6alagua.com<\/a>\u00a0<\/strong><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/profile.ak.fbcdn.net\/hprofile-ak-snc4\/277034_293281404022018_663081876_n.jpg\" alt=\"U-21 Underwater Rugby Nordic Cup Oxel\u00f6sund 2011\" \/><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/a6.sphotos.ak.fbcdn.net\/hphotos-ak-snc7\/s720x720\/390869_325620614121430_293281404022018_1538882_1404102840_n.jpg\" alt=\"\" width=\"600\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Especial Sportalsub.net) La Selecci\u00f3n Sub-21 de Colombia obtuvo el 3er lugar en la Copa N\u00f3rdica de Rugby Subacu\u00e1tico 2011 efectuada del 18 al 20 de noviembre en la localidad de Oxel\u00f6sund, Suecia. Colombia logr\u00f3 el 3er puesto al superar por marcador de 4 goles a 1 al combinado de Noruega en el partido que otorgaba la medalla de Bronce. El [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":11338,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[167,3,221,211,120,7,212],"tags":[],"class_list":["post-11336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alemania","category-colombia","category-colombia-rugbysub-2011","category-noruega","category-resultados","category-rugby-subacuatico","category-suecia"],"modified_by":"Sportalsub.net","views":3942,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-2WQ","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":16851,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-dia-2-campeonato-nordico-y-abierto-de-rugby-subacuatico-sub-21-dinamarca-2013\/","url_meta":{"origin":11336,"position":0},"title":"\ud83c\udde9\ud83c\uddf0 Finaliza el Campeonato N\u00f3rdico y Abierto de Rugby Subacu\u00e1tico Sub-21 Dinamarca 2013","author":"Sportalsub.net","date":"17 noviembre 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ Campeonato Sub-21 Rugby Subacu\u00e1tico) Finaliz\u00f3 el Campeonato Sub-21 de Rugby Subacu\u00e1tico en Dinamarca. \u00a0Colombia\u00a0finaliza en el 4to lugar Luego de la ronda todos contra todos se jugaron los partidos finales con los siguientes resultados: Final por el 1er lugar: NORUEGA 3 - 1 FINLANDIA Partido por el\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/dia2rugbysub.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/dia2rugbysub.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/dia2rugbysub.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/dia2rugbysub.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16816,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-dia-1-campeonato-nordico-y-abierto-de-rugby-subacuatico-sub-21-dinamarca-2013\/","url_meta":{"origin":11336,"position":1},"title":"\ud83c\udde9\ud83c\uddf0 Resultados D\u00eda 1 Campeonato N\u00f3rdico y Abierto de Rugby Subacu\u00e1tico Sub-21 Dinamarca 2013","author":"Sportalsub.net","date":"16 noviembre 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ Campeonato Sub-21 Rugby Subacu\u00e1tico) Resultados D\u00eda 1, S\u00e1bado 16 de Noviembre. Campeonato N\u00f3rdico y Abierto de Rugby Subacu\u00e1tico Sub-21 Dinamarca 2013 DINAMARCA 2 - 1 SUECIA ALEMANIA 2 - 1 COLOMBIA NORUEGA 5 - 1 FINLANDIA DINAMARCA 1 - 5 COLOMBIA ALEMANIA 2 - 3 FINLANDIA NORUEGA\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/dia1-sub21.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/dia1-sub21.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/dia1-sub21.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/dia1-sub21.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":21569,"url":"https:\/\/www.sportalsub.net\/blog\/2007\/08\/04\/bari-2007-rugbysub-finales","url_meta":{"origin":11336,"position":2},"title":"\ud83c\uddee\ud83c\uddf9 Bari 2007: Campeonato Mundial de Rugby Subacu\u00e1tico &#8211; Finales","author":"Sportalsub.net","date":"4 agosto 2007","format":false,"excerpt":"(Sportalsub.net \/ CMAS Games Bari 2007) Finaliza el 8vo Campeonato Mundial de Rugby Subacu\u00e1tico, realizado en los CMAS Games de Bari, Italia. En la categor\u00eda masculina, Finlandia se titula campe\u00f3n, mientras que Alemania obtuvo el primer lugar femenino. Masculino: Finlandia Campe\u00f3n Mundial En un cerrado partido final, la Selecci\u00f3n de\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/07\/cmas-bari-2007.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/07\/cmas-bari-2007.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/07\/cmas-bari-2007.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/07\/cmas-bari-2007.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":16771,"url":"https:\/\/www.sportalsub.net\/blog\/campeonato-nordico-y-abierto-de-rugby-subacuatico-sub-21-dinamarca-2013\/","url_meta":{"origin":11336,"position":3},"title":"\ud83c\udde8\ud83c\uddf4 Colombia estar\u00e1 en Campeonato N\u00f3rdico y Abierto de Rugby Subacu\u00e1tico Sub-21 Dinamarca 2013","author":"Sportalsub.net","date":"14 noviembre 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ DSF \/ CMAS \/ ) La Selecci\u00f3n Colombiana de Rugby Subacu\u00e1tico Sub-21 estar\u00e1 participando en el Campeonato\u00a0N\u00f3rdico y Abierto de la categor\u00eda, a realizarse los d\u00edas 16 y 17 de noviembre en la ciudad de Copenhagen bajo la organizaci\u00f3n de la\u00a0Federaci\u00f3n Danesa de Actividades Subacu\u00e1ticas En el\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/opennordic.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/opennordic.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/opennordic.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":6642,"url":"https:\/\/www.sportalsub.net\/blog\/colombia-obtiene-el-segundo-lugar-en-campeonato-sub21-open-de-rugby-subacuatico-cmas-en-alemania\/","url_meta":{"origin":11336,"position":4},"title":"\ud83c\udde8\ud83c\uddf4 Colombia obtiene el Segundo Lugar en Campeonato Sub21 Open de Rugby Subacu\u00e1tico CMAS en Alemania","author":"Sportalsub.net","date":"21 noviembre 2010","format":false,"excerpt":"(Especial Sportalsub.net) En lo que podr\u00eda ser considerado el Campeonato Mundial Sub21 de Rugby Subacu\u00e1tico, ya que cont\u00f3 con la participaci\u00f3n de 7 selecciones europeas del m\u00e1s alto nivel, Colombia hace historia, al obtener, en su primera participaci\u00f3n en la 5ta edici\u00f3n de este torneo de selecciones nacionales, el 2do\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/11\/colombiarugby.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/11\/colombiarugby.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/11\/colombiarugby.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/11\/colombiarugby.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10524,"url":"https:\/\/www.sportalsub.net\/blog\/noruega-se-titula-doble-campeon-mundial-de-rugby-subacuatico-2011\/","url_meta":{"origin":11336,"position":5},"title":"\ud83c\uddf3\ud83c\uddf4 Noruega se titula doble Campe\u00f3n Mundial de Rugby Subacu\u00e1tico 2011","author":"Sportalsub.net","date":"20 agosto 2011","format":false,"excerpt":"(Especial Sportalsub.net \/ Prensa Mundial Rugbysub 2011) La Selecci\u00f3n de Noruega, se titul\u00f3 Campeona en las ramas femenina y masculina en el 9no Campeonato Mundial de Rugby Subacu\u00e1tico de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas, realizado desde el pasado martes 16 hasta este s\u00e1bado 20 de agosto en Helsinki, Finlandia.\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/08\/finalmundial.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/08\/finalmundial.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/08\/finalmundial.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/copa-nordicasub21.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/11336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=11336"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/11336\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/11338"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=11336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=11336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=11336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}