{"id":11356,"date":"2011-11-28T13:08:02","date_gmt":"2011-11-28T17:38:02","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=11356"},"modified":"2019-09-01T01:37:12","modified_gmt":"2019-09-01T05:37:12","slug":"club-orcas-de-colombia-logro-el-3er-lugar-en-la-copa-de-campeones-de-rugby-subacuatico-en-alemania","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/club-orcas-de-colombia-logro-el-3er-lugar-en-la-copa-de-campeones-de-rugby-subacuatico-en-alemania\/","title":{"rendered":"\ud83c\udde8\ud83c\uddf4 Club Orcas de Colombia logr\u00f3 el 3er lugar en la Copa de Campeones 2011 de Rugby Subacu\u00e1tico en Alemania"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11619\" title=\"orcas-berlin\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/orcas-berlin.jpg\" alt=\"\" width=\"600\" height=\"268\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/orcas-berlin.jpg 600w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/orcas-berlin-300x134.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/orcas-berlin-364x164.jpg 364w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>(Especial Sportalsub.net)<br \/>\nEl equipo Orcas de Medell\u00edn, en representaci\u00f3n de Colombia obtuvo el 3er lugar en la edici\u00f3n 2011 de la Copa de Campeones de Rugby Subacu\u00e1tico, realizada del 25 al 27 de noviembre en Alemania.<\/p>\n<p>El equipo masculino de Orcas logr\u00f3 subirse nuevamente al podio, luego de haber obtenido el subcampeonato en la edici\u00f3n 2010 del torneo, que agrup\u00f3 en esta oportunidad a los clubes campeones de 12 pa\u00edses: Alemania, Suiza, Finlandia, Suecia, Colombia, Espa\u00f1a, Dinamarca, Rusia, Italia, Rep\u00fablica Checa, Noruega y Austria. El equipo Campe\u00f3n fue el Molde UVK de Noruega, mientras que el segundo puesto lo ocup\u00f3 el TC Bamberg de Alemania. \u00a0Espa\u00f1a estuvo nuevamente representada por el equipo Pira\u00f1as, que se ubic\u00f3 en el 8vo puesto.<\/p>\n<p>En la categor\u00eda femenina, Colombia no tuvo participaci\u00f3n, a pesar de que Orcas hab\u00eda logrado el t\u00edtulo de Campeonas en 2010, resultando las ganadoras de la edici\u00f3n 2011 las integrantes del equipo TSC Shark Manheim de Alemania, el segundo lugar fue para BSI Boblen de Noruega, mientras que el tercer puesto lo ocup\u00f3 FIRS de Italia. Espa\u00f1a estuvo representada por BNC Rugbysub que ocup\u00f3 el 5to puesto, siendo superadas en la tabla por el equipo campe\u00f3n de Rusia (Betta) y quedando por encima de Black Mermaids de Suecia, que completaron los 6 equipos femeninos del torneo.<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/xls.gif\" alt=\"\" width=\"16\" height=\"16\" \/>\u00a0<a href=\"http:\/\/www.facebook.com\/l.php?u=https%3A%2F%2Fdocs.google.com%2Fspreadsheet%2Fpub%3Fkey%3D0AvZWdOvj6VgmdFkyY3FZV2lnOWJsYlF4OEp1Z25zWFE%26single%3Dtrue%26gid%3D0%26output%3Dhtml&amp;h=FAQHPH9TPAQFucluBhPUY9YU9exbV7Ri6DhYhShV66qfi1A\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Resultados y tabla de posiciones del evento<\/a><\/strong><\/p>\n<p><strong>M\u00e1s informaci\u00f3n:<\/strong><\/p>\n<p><strong><a href=\"http:\/\/www.uwr24.de\/championscup\/index.html\" target=\"_blank\">Sitio Oficial<\/a><\/strong><\/p>\n<p><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/fb.png\" alt=\"Facebook\" \/>\u00a0<a href=\"http:\/\/www.facebook.com\/pages\/UWR-Championscup-2011\/112352555519219?sk=wall\" target=\"_blank\">Evento en Facebook<\/a>\u00a0<\/strong><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/profile.ak.fbcdn.net\/hprofile-ak-snc4\/211124_112352555519219_5196436_n.jpg\" alt=\"UWR-Championscup 2011\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Especial Sportalsub.net) El equipo Orcas de Medell\u00edn, en representaci\u00f3n de Colombia obtuvo el 3er lugar en la edici\u00f3n 2011 de la Copa de Campeones de Rugby Subacu\u00e1tico, realizada del 25 al 27 de noviembre en Alemania. El equipo masculino de Orcas logr\u00f3 subirse nuevamente al podio, luego de haber obtenido el subcampeonato en la edici\u00f3n 2010 del torneo, que agrup\u00f3 [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":11619,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[167,3,221,133,10,118,211,120,7],"tags":[],"class_list":["post-11356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alemania","category-colombia","category-colombia-rugbysub-2011","category-destacados-anteriores","category-espana","category-italia","category-noruega","category-resultados","category-rugby-subacuatico"],"modified_by":"Sportalsub.net","views":5501,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-2Xa","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":14372,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-copa-de-campeones-rugby-subacuatico-2012-alemania-23-25-de-noviembre\/","url_meta":{"origin":11356,"position":0},"title":"\ud83c\udde9\ud83c\uddea Resultados Copa de Campeones Rugby Subacu\u00e1tico 2012 Alemania. 23-25 de Noviembre","author":"Sportalsub.net","date":"19 diciembre 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ Champions Cup UWR) Los Clubes Molde UVK de Noruega y \u00a0TSC Shark Mannheim de Alemania se titularon Campeones en las categor\u00edas femenina y masculina, respectivamente en la edici\u00f3n 2012 de la Copa de Campeones de Rugby Subacu\u00e1tico que reuni\u00f3 a los mejores clubes de la modalidad del\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/12\/championscup2012.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/12\/championscup2012.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/12\/championscup2012.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":22840,"url":"https:\/\/www.sportalsub.net\/blog\/orcas-colombia-copa-de-campeones-rugbysub-2015","url_meta":{"origin":11356,"position":1},"title":"\ud83c\udde8\ud83c\uddf4 Orcas de Colombia nuevamente en el podio de la Copa de Campeones de Rugby Subacu\u00e1tico 2015 en Alemania","author":"Sportalsub.net","date":"29 noviembre 2015","format":false,"excerpt":"(Sportalsub.net \/ Club Orcas UW Rugby) El Club Orcas de Rugby Subacu\u00e1tico de Colombia ha logrado otra destacada actuaci\u00f3n en la\u00a0Copa de Campeones de Rugby Subacu\u00e1tico 2015 realizada este fin de semana en Berl\u00edn, Alemania; en la que el equipo Masculino logr\u00f3 el Sub-Campeonato y la medalla de plata,\u00a0mientras que\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/orcas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/orcas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/orcas.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/orcas.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":18771,"url":"https:\/\/www.sportalsub.net\/blog\/copa-de-campeones-rugbysub-2014","url_meta":{"origin":11356,"position":2},"title":"\ud83c\udde8\ud83c\uddf4 Resultados Copa de Campeones de Rugby Subacu\u00e1tico 2014. Orcas de Colombia de nuevo en el Podio","author":"Sportalsub.net","date":"1 diciembre 2014","format":false,"excerpt":"(Sportalsub.net \/ UWR CCup) El Club BUR Berlin e.V. convoc\u00f3\u00a0como cada a\u00f1o a los equipos Campeones Nacionales a la Copa de Campeones de Rugby Subacu\u00e1tico, para equipos masculinos y femeninos, la cual se llev\u00f3 a cabo del 28 al 30 de noviembre en Berlin, Alemania y en la que se\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/10\/uwrchampionscup2014.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/10\/uwrchampionscup2014.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/10\/uwrchampionscup2014.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":11282,"url":"https:\/\/www.sportalsub.net\/blog\/colombia-estara-presente-en-los-proximos-campeonatos-internacionales-de-rugby-subacuatico-nuevo-reglamento-2011\/","url_meta":{"origin":11356,"position":3},"title":"\ud83c\udde8\ud83c\uddf4 Colombia estar\u00e1 presente en los pr\u00f3ximos Campeonatos Internacionales de Rugby Subacu\u00e1tico &#8211; Nuevo Reglamento 2011","author":"Sportalsub.net","date":"10 noviembre 2011","format":false,"excerpt":"(Especial Sportalsub.net) Durante el mes de noviembre, Colombia tendr\u00e1 nuevamente participaci\u00f3n en importantes Campeonatos Internacionales de Rugby Subacu\u00e1tico a realizarse en Europa. Copa N\u00f3rdica Sub-21 En primer lugar, la Selecci\u00f3n Colombia Sub-21 estar\u00e1 presente en la Copa N\u00f3rdica Abierta, a realizarse del 18 al 20 de noviembre en Oxel\u00f6sund, Suecia,\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/colombia-rugbysub2011.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/colombia-rugbysub2011.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/colombia-rugbysub2011.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":26779,"url":"https:\/\/www.sportalsub.net\/blog\/uwrccup2017","url_meta":{"origin":11356,"position":4},"title":"\ud83c\udde9\ud83c\uddea Resultados &#8211; Copa de Campeones de Rugby Subacu\u00e1tico 2017 en Berlin, Alemania","author":"Sportalsub.net","date":"28 noviembre 2017","format":false,"excerpt":"(Sportalsub.net \/ Champions Cup UWR 2017) - Read in English Cada a\u00f1o se lleva a cabo en Alemania la Copa de Campeones de Rugby Subacu\u00e1tico, como ha sido tradici\u00f3n en los \u00faltimos a\u00f1os, la ciudad sede fue Berlin, Alemania en donde los equipos campeones de cada pa\u00eds se disputaron del\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/finalchampionscup2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/finalchampionscup2017.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/finalchampionscup2017.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/finalchampionscup2017.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22272,"url":"https:\/\/www.sportalsub.net\/blog\/uwr-ccup-2015","url_meta":{"origin":11356,"position":5},"title":"\ud83c\udde9\ud83c\uddea Resultados Copa de Campeones de Rugby Subacu\u00e1tico 2015 Alemania","author":"Sportalsub.net","date":"29 noviembre 2015","format":false,"excerpt":"(Sportalsub.net \/ UWR CCup) - Read in English El torneo Internacional de Clubes de Rugby Subacu\u00e1tico m\u00e1s grande del mundo, la Copa de Campeones 2015 cont\u00f3\u00a0con la participaci\u00f3n de los equipos campeones Nacionales de 13 Pa\u00edses, que se disputaron la Copa por el mejor Club del Mundo de Rugby Subacu\u00e1tico.\u00a013\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/champions-feat.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/champions-feat.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/champions-feat.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/champions-feat.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/11\/orcas-berlin.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/11356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=11356"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/11356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/11619"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=11356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=11356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=11356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}