{"id":11693,"date":"2012-02-06T16:11:57","date_gmt":"2012-02-06T20:41:57","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=11693"},"modified":"2024-01-06T09:50:54","modified_gmt":"2024-01-06T13:50:54","slug":"chequeo-nacional-selectivo-natacion-con-aletas-fvas-venezuela-2012","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/chequeo-nacional-selectivo-natacion-con-aletas-fvas-venezuela-2012\/","title":{"rendered":"\ud83c\uddfb\ud83c\uddea Resultados &#8211; Chequeo Nacional Selectivo Nataci\u00f3n con Aletas FVAS Venezuela 2012"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-11694\" title=\"chequeo-aletas2012\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/01\/chequeo-aletas2012.jpg\" alt=\"\" width=\"500\" height=\"300\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/01\/chequeo-aletas2012.jpg 500w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/01\/chequeo-aletas2012-300x180.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>(Especial Sportalsub.net \/ FVAS)<\/p>\n<p>La\u00a0<strong>Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas\u00a0<\/strong>(FVAS), conjuntamente con la Direcci\u00f3n Deportiva y Comisi\u00f3n T\u00e9cnica Nacional de Nataci\u00f3n con Aletas, cumple con invitar a los atletas preseleccionados de Nataci\u00f3n con Aletas, al\u00a0<strong>Chequeo Nacional Selectivo al Panamericano Colombia 2012 y Preselectivo al Mundial Junior Austria 2012<\/strong>.<\/p>\n<p><strong>Fecha del evento<\/strong>:\u00a0Domingo 5 de febrero 2011<br \/>\n&#8211; Congresillo t\u00e9cnico: 8:00am.<br \/>\n&#8211; 1ra Jornada: 9:00am a 12:00m.<br \/>\n&#8211; 2da Jornada: 2:00pm a 5:00pm<\/p>\n<p><strong>Lugar:\u00a0<\/strong>Centro de Alto Rendimiento La Rinconada \u201cPoliedrito\u201d. Caracas, D.C<\/p>\n<p><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/pdf.gif\" alt=\"\" \/><\/strong>\u00a0<a href=\"https:\/\/www.fvas.com.ve\/wp-content\/uploads\/2012\/01\/2012-CHEQUEO-NATACION-CON-ALETAS-resultados.pdf\" target=\"_blank\" rel=\"noopener\" target=\"_blank\"><strong>RESULTADOS OFICIALES<\/strong><\/a><\/p>\n<p><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/pdf.gif\" alt=\"\" \/>\u00a0<a href=\"http:\/\/www.fvas.com.ve\/wp-content\/uploads\/2012\/01\/Invitaci%C3%B3n-Chequeo-Nacional-Selectivo-Nataci%C3%B3n-con-aletas-2012.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Invitaci\u00f3n y Convocatoria Oficial<\/a><\/strong><\/p>\n<p><span style=\"font-weight: 900;\"><strong><strong><strong><strong><strong><strong><a href=\"http:\/\/www.fvas.com.ve\/wp-content\/uploads\/2011\/04\/fichajesfvas2011.xls\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/xls.gif\" alt=\"\" width=\"16\" height=\"16\" \/><\/a>\u00a0<\/strong><\/strong><\/strong><\/strong><\/strong><a href=\"http:\/\/www.fvas.com.ve\/wp-content\/uploads\/2012\/01\/Planilla_Inscripcion_chequeo.xls\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Planilla de Inscripci\u00f3n Chequeo<\/a><\/strong><\/span><\/p>\n<p><strong>M\u00e1s informaci\u00f3n:<\/strong><\/p>\n<p><strong><a href=\"http:\/\/www.fvas.com.ve\/2012\/01\/proceso-de-fichaje-deportivo-2012\/\" rel=\"prev\" target=\"_blank\">PROCESO DE FICHAJE DEPORTIVO 2012<\/a><\/strong><\/p>\n<p><strong><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/pdf.gif\" alt=\"\" \/>\u00a0<\/strong><a href=\"http:\/\/www.fvas.com.ve\/wp-content\/uploads\/2012\/01\/FINSWIMMING-2010-01-Es.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Reglamento Internacional Nataci\u00f3n con Aletas CMAS<\/a><\/strong><\/p>\n<p><strong><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/pdf.gif\" alt=\"\" \/>\u00a0<\/strong><a href=\"http:\/\/www.fvas.com.ve\/wp-content\/uploads\/2012\/01\/LIST-OF-HOMOLOGATED-FINS-110101.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Listado de Bialetas Homologadas CMAS<\/a><\/strong><\/p>\n<p><strong><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/pdf.gif\" alt=\"\" \/>\u00a0<\/strong><a href=\"http:\/\/www.fvas.com.ve\/wp-content\/uploads\/2012\/01\/Finsuits-Carta-CMAS-traducida.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Reglamento de Trajes de Ba\u00f1o para competencias CMAS<\/a><\/strong><\/p>\n<p><strong><strong><strong><strong><strong><a href=\"http:\/\/www.fvas.com.ve\/wp-content\/uploads\/2011\/04\/fichajesfvas2011.xls\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/xls.gif\" alt=\"\" width=\"16\" height=\"16\" \/><\/a><\/strong><\/strong><\/strong>\u00a0<a href=\"http:\/\/www.fvas.com.ve\/wp-content\/uploads\/2012\/01\/fichajesfvas2012.xls\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Planilla de Fichaje FVAS 2012 por Asociaci\u00f3n\u00a0<strong>\u00a0<\/strong><\/a><\/strong><\/strong><\/p>\n<p>Fuente: <a href=\"http:\/\/www.fvas.com.ve\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">www.fvas.com.ve<\/a><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.fvas.com.ve\/wp-content\/uploads\/2010\/05\/fvashead1.png\" alt=\"\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Especial Sportalsub.net \/ FVAS) La\u00a0Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas\u00a0(FVAS), conjuntamente con la Direcci\u00f3n Deportiva y Comisi\u00f3n T\u00e9cnica Nacional de Nataci\u00f3n con Aletas, cumple con invitar a los atletas preseleccionados de Nataci\u00f3n con Aletas, al\u00a0Chequeo Nacional Selectivo al Panamericano Colombia 2012 y Preselectivo al Mundial Junior Austria 2012. Fecha del evento:\u00a0Domingo 5 de febrero 2011 &#8211; Congresillo t\u00e9cnico: 8:00am. &#8211; 1ra [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":11694,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"no","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[12,120,8],"tags":[477],"class_list":["post-11693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-natacion-con-aletas","category-resultados","category-venezuela","tag-miguelsportsub"],"modified_by":"Sportalsub.net","views":3041,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-32B","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":11704,"url":"https:\/\/www.sportalsub.net\/blog\/chequeo-nacional-selectivo-apnea-en-piscina-fvas-venezuela-2012\/","url_meta":{"origin":11693,"position":0},"title":"\ud83c\uddfb\ud83c\uddea Chequeo Nacional Selectivo Apnea en piscina FVAS Venezuela 2012","author":"Sportalsub.net","date":"23 enero 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ FVAS) La\u00a0Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas\u00a0(FVAS), conjuntamente con la Direcci\u00f3n Deportiva y Comisi\u00f3n T\u00e9cnica Nacional de Apnea, cumple con invitar a los atletas preseleccionados de Apnea, al\u00a0Chequeo Nacional Selectivo al Panamericano Colombia 2012 Fecha del evento: S\u00e1bado 11 y Domingo 12 de febrero 2012 - Sabado 11\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/01\/chequeo-apnea-fvas.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":25730,"url":"https:\/\/www.sportalsub.net\/blog\/i-chequeo-de-natacion-con-aletas-venezuela-2017\/","url_meta":{"origin":11693,"position":1},"title":"\ud83c\uddfb\ud83c\uddea Resultados I Chequeo Nacional de Nataci\u00f3n con Aletas Venezuela 2017","author":"Sportalsub.net","date":"10 febrero 2017","format":false,"excerpt":"(Sportalsub.net \/ Comisi\u00f3n Nataci\u00f3n con Aletas Venezuela \/ FVAS) Cumpli\u00e9ndose el calendario nacional 2017, \u00a0la Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas (FVAS), a trav\u00e9s de su Comisi\u00f3n T\u00e9cnica de Aletas, realizaron los d\u00edas 3, 4 y 5 de Febrero 2017 el Chequeo Nacional de Nataci\u00f3n con Aletas en las piscinas \u00a0del\u2026","rel":"","context":"En \u00abNataci\u00f3n con Aletas\u00bb","block_context":{"text":"Nataci\u00f3n con Aletas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/natacion-con-aletas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/chequeo-aletas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/chequeo-aletas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/chequeo-aletas.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/chequeo-aletas.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":64063,"url":"https:\/\/www.sportalsub.net\/blog\/chequeo-nacional-nadosub-venezuela-2023","url_meta":{"origin":11693,"position":2},"title":"\ud83c\uddfb\ud83c\uddea Resultados &#8211; Chequeo Nacional Nataci\u00f3n con Aletas en piscina FVAS Venezuela 2023 \u2013 Los Salias, Miranda","author":"Sportalsub.net","date":"5 junio 2023","format":false,"excerpt":"(Sportalsub.net \/ FVAS) La Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas a trav\u00e9s de su Direcci\u00f3n T\u00e9cnica Deportiva y Comisi\u00f3n T\u00e9cnica Nacional de Nataci\u00f3n con Aletas, organizaron el Chequeo Nacional en piscina realizado los d\u00edas S\u00e1bado 3 y Domingo 4 de Junio de 2023 en la Piscina Municipal de San Antonio de\u2026","rel":"","context":"En \u00abNataci\u00f3n con Aletas\u00bb","block_context":{"text":"Nataci\u00f3n con Aletas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/natacion-con-aletas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/06\/resultadoschequeoaletas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/06\/resultadoschequeoaletas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/06\/resultadoschequeoaletas.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/06\/resultadoschequeoaletas.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":39,"url":"https:\/\/www.sportalsub.net\/blog\/chequeo-nacional-juvenil-de-natacion-con-aletas-en-venezuela\/","url_meta":{"origin":11693,"position":3},"title":"\ud83c\uddfb\ud83c\uddea Chequeo Nacional Juvenil de Nataci\u00f3n con Aletas en Venezuela","author":"Sportalsub.net","date":"26 mayo 2008","format":false,"excerpt":"Resultados del Chequeo Nacional Juvenil de Nataci\u00f3n con Aletas en piscina\u00a0FVAS 2008 realizado los d\u00edas 23, 24 y 25 de Mayo en Caracas, Distrito Capital. FECHA:\u00a023, 24 Y 25 de Mayo LUGAR: Distrito Capital ORGANIZADOR: FVAS Resultados Oficiales (Formato PDF) Documentos relacionados: R\u00e9cords Nacionales Nataci\u00f3n con Aletas FVAS Ranking Nacional\u2026","rel":"","context":"En \u00abNataci\u00f3n con Aletas\u00bb","block_context":{"text":"Nataci\u00f3n con Aletas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/natacion-con-aletas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2008\/05\/chequeojuvenil.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2776,"url":"https:\/\/www.sportalsub.net\/blog\/campeonato-nacional-de-actividades-subacuaticas-fvas-2009\/","url_meta":{"origin":11693,"position":4},"title":"\ud83c\uddfb\ud83c\uddea Campeonato Nacional de Actividades Subacu\u00e1ticas en Venezuela FVAS 2009","author":"Sportalsub.net","date":"15 septiembre 2009","format":false,"excerpt":"Fotos: Ronald Laurens @ Sportalsub.net La Federaci\u00f3n Venezolana de Actividades Subacuaticas, El Comit\u00e9 Deportivo FVAS, La Comisi\u00f3n Nacional de Jueces FVAS y la Asociaci\u00f3n de Actividades Subacuaticas del Estado Lara, ASUBLAR, se dirigen a Uds. en la oportunidad de invitarles a participar en el evento de CAMPEONATO NACIONAL DE ACTIVIDADES\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/09\/apneafvas.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":68919,"url":"https:\/\/www.sportalsub.net\/blog\/chequeo-aletas-fvas-venezuela-2024","url_meta":{"origin":11693,"position":5},"title":"\ud83c\uddfb\ud83c\uddea Resultados &#8211; Chequeo Nacional por categor\u00edas de Nataci\u00f3n con Aletas FVAS 2024 &#8211; Caracas, Venezuela","author":"Sportalsub.net","date":"29 enero 2024","format":false,"excerpt":"(Sportalsub.net \/ FVAS) La Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas y la Comisi\u00f3n Nacional de Nataci\u00f3n con aletas, organizaron el CHEQUEO NACIONAL POR CATEGOR\u00cdAS DE NATACI\u00d3N CON ALETAS realizado los d\u00edas viernes 26, s\u00e1bado 27 y domingo 28 de enero 2024 en el Complejo de piscinas \u201cGregorio Goyo Tavio\u201d Parque Naciones\u2026","rel":"","context":"En \u00abNataci\u00f3n con Aletas\u00bb","block_context":{"text":"Nataci\u00f3n con Aletas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/natacion-con-aletas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/01\/1erchequeopiscina2024fvas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/01\/1erchequeopiscina2024fvas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/01\/1erchequeopiscina2024fvas.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/01\/1erchequeopiscina2024fvas.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/01\/chequeo-aletas2012.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/11693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=11693"}],"version-history":[{"count":2,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/11693\/revisions"}],"predecessor-version":[{"id":68918,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/11693\/revisions\/68918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/11694"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=11693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=11693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=11693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}