{"id":12163,"date":"2012-04-07T23:39:33","date_gmt":"2012-04-08T04:09:33","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=12163"},"modified":"2019-09-01T13:35:28","modified_gmt":"2019-09-01T17:35:28","slug":"alejandro-guedez-uno-con-el-oceano","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/alejandro-guedez-uno-con-el-oceano\/","title":{"rendered":"\ud83c\uddfb\ud83c\uddea Alejandro Gu\u00e9dez: Uno con el oc\u00e9ano"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-12164\" title=\"entrevista-alejandro\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/entrevista-alejandro.jpg\" alt=\"\" width=\"600\" height=\"268\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/entrevista-alejandro.jpg 600w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/entrevista-alejandro-300x134.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/entrevista-alejandro-364x164.jpg 364w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>(Especial Sportalsub.net \/\u00a0<\/strong><strong>Loys Leso<\/strong><strong> <a href=\"http:\/\/twitter.com\/loysleso\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">@loysleso<\/a>)<\/strong><\/p>\n<p><strong>Comenc\u00e9 a hacer apnea por esa atracci\u00f3n intr\u00ednseca que siempre sent\u00ed hacia el mar y sus profundidades. Es algo dif\u00edcil de explicar con palabras, es como un sentimiento que te mantiene ligado a un entorno donde experimentas una profunda paz y serenidad\u2026<\/strong><\/p>\n<p>Si algo caracteriza al ser humano, es su af\u00e1n por conquistar aquellos espacios que en teor\u00eda\u00a0 no le son propios, al menos no adecuados naturalmente a su condici\u00f3n f\u00edsica. Sin embargo, su esp\u00edritu explorador, su curiosidad por experimentar nuevas sensaciones lo impuls\u00f3 al viento para sentirse p\u00e1jaro y al oc\u00e9ano para sentirse pez; en este \u00faltimo, misterioso, desconocido, pero fascinante cuerpo de agua profunda fue donde el buzo a pulm\u00f3n Alejandro Gu\u00e9dez, hoy segunda mejor marca latinoamericana de apnea profunda\u00a0 peso constante, desaf\u00edo sus l\u00edmites con apenas una sola bocanada de aire en los pulmones y en el que espera tocar los100 metrosde profundidad, una marca reservada solo a pocos en el mundo.<\/p>\n<p>Actualmente es due\u00f1o de los 90 metros y aspira, adem\u00e1s de lograr los 100 en el desaf\u00edo Vertical Blue de las Bahamas a finales de este a\u00f1o, alcanzar los200 metrosde apnea din\u00e1mica en piscina.<\/p>\n<p>Es evidente que los desaf\u00edos dif\u00edciles son objetivos para Gu\u00e9dez. Se concentra en ellos y trabaja para alcanzarlos, con \u00e9l conversamos sobre esa especial atracci\u00f3n al mar que confiesa siempre le gener\u00f3 bienestar\u00a0 y sobre este deporte acu\u00e1tico que cada vez m\u00e1s tiene la atenci\u00f3n de nuevos adeptos.<\/p>\n<p><strong>\u00bfPor qu\u00e9 decidiste hacer apnea?<\/strong><\/p>\n<p>Comenc\u00e9 a hacer apnea por esa atracci\u00f3n intr\u00ednseca que siempre sent\u00ed hacia el mar y sus profundidades. Es algo dif\u00edcil de explicar con palabras, es como un sentimiento que te mantiene ligado a un entorno donde experimentas una profunda paz y serenidad\u2026 Luego que comenc\u00e9 a practicarlo como deporte, la motivaci\u00f3n que me ha permitido continuar siempre ha sido la misma, y es\u00a0 la pasi\u00f3n por superarme cada vez m\u00e1s, de redefinir mis l\u00edmites y de practicar y disfrutar del deporte que amo, esa es mi motivaci\u00f3n: la pasi\u00f3n por lo que hago.<\/p>\n<p><strong>\u00bfQu\u00e9 es lo que m\u00e1s disfrutas al hacer apnea?<\/strong><\/p>\n<p>La profunda relajaci\u00f3n y bienestar que se experimenta, adem\u00e1s del contacto con el entorno acu\u00e1tico. Esa sensaci\u00f3n de sentirse uno con el oc\u00e9ano, esa especie de fusi\u00f3n que se alcanza por unos instantes con el mar, de verdad que es \u00fanica e indescriptible.<\/p>\n<p><strong>\u00bfCu\u00e1les son las sensaciones que experimentas cuando realizas una apnea profunda, en el mar?<\/strong><\/p>\n<p>Para m\u00ed la parte de la bajada es lo m\u00e1s importante, es donde busco la m\u00e1xima relajaci\u00f3n, es donde intento estar enfocado y tener la mente lo m\u00e1s en blanco posible y experimentar ese reflejo mam\u00edfero que se est\u00e1 activando, el nivel de relajaci\u00f3n y placer que se experimenta en la bajada es alta, por la cantidad de endorfinas que se liberan, la meta es disfrutar lo m\u00e1ximo la bajada, realizar la marca y tener un ascenso exitoso.<\/p>\n<p><strong>\u00bfQu\u00e9 piensas mientras vas bajando?<\/strong><\/p>\n<p>Nada, voy muy concentrado en la apnea y en cada paso del trayecto. Vas en una especie de trance, lo m\u00e1s relajado posible para que el cuerpo act\u00fae en piloto autom\u00e1tico, que haga todo lo que debe hacer sin que eso cause estr\u00e9s, ni tengas que pensar demasiado en lo que tiene que hacer.<\/p>\n<p><strong>\u00bfCu\u00e1l es tu rutina minutos antes en una competencia?<\/strong><\/p>\n<p>Calentamiento previo para activar el reflejo mam\u00edfero un poco m\u00e1s r\u00e1pido (<em>El reflejo mam\u00edferos es aquel con el cual se optimizan la respiraci\u00f3n para lograr permanecer debajo del agua por per\u00edodos extensos de tiempo<\/em>) y simular ciertas sensaciones que uno va a experimentar en esa apnea m\u00e1xima, en esa marca. Esto lo hago minutos antes. Y, por supuesto, una visualizaci\u00f3n de lo que voy a realizar en la m\u00e1xima, desde la salida, la respiraci\u00f3n, la llegada, el protocolo de superficie. Todo esto lo hago antes y a la hora de hacer la marca es como activar un piloto autom\u00e1tico.<\/p>\n<p><strong>\u00bfEn qu\u00e9 consiste tu entrenamiento?<\/strong><\/p>\n<p>El entrenamiento incluye estiramiento, algo de yoga, luego nataci\u00f3n y ejercicios espec\u00edficos de apnea. Aparte, visito el gimnasio y juego f\u00fatbol, es importante fortalecer el cuerpo con alguna actividad cardiovascular. Todos los d\u00edas hago ejercicios de respiraci\u00f3n. Pr\u00e1ctico el yoga pranayana, espec\u00edfico para la apnea porque se basa en la respiraci\u00f3n.<\/p>\n<p><strong>\u00bfQu\u00e9 se necesita para hacer apnea?<\/strong><\/p>\n<p>Sentirse c\u00f3modo en el agua, aprender a respirar correctamente, saber nadar, entrenar, saber o aprender a ecualizar o compensar los espacios de aire, que se refiere a t\u00e9cnicas de compensaci\u00f3n o ecualizaci\u00f3n de la presi\u00f3n hidrost\u00e1tica, que es lo que te permite igualar la presi\u00f3n de los espacios a\u00e9reos internos con el exterior a medida que se va descendiendo, con pr\u00e1ctica y entrenamiento se logra dominarlo y siempre practicar apnea con un compa\u00f1ero.<\/p>\n<p><strong>\u00bfQu\u00e9 significa respirar correctamente?<\/strong><\/p>\n<p>Es utilizar concientemente todas las etapas de la respiraci\u00f3n: la respiraci\u00f3n abdominal, del diafragma y clavicular, de manera natural, sin esfuerzo.<\/p>\n<p><strong>\u00bfQu\u00e9 beneficios ofrece la pr\u00e1ctica de apnea?<\/strong><\/p>\n<p>El principal beneficio de la apnea es que las personas aprenden a respirar correctamente y esto trae m\u00faltiples ventajas a la salud como el manejo del estr\u00e9s, de la ansiedad, se aprende a relajarse, entre muchos otros beneficios. Adem\u00e1s, la apnea perdura con los a\u00f1os de pr\u00e1ctica, se puede perder la condici\u00f3n f\u00edsica pero la apnea no se pierde.<\/p>\n<p><em>Las empresas que apoyan al\u00a0 apneista Alejandro Gu\u00e9dez son: Ceramicas Valcro., Cantv (patrocinante 2011) No Limits Dive Center., y tambi\u00e9n colaboran con \u00e9l: Agua Mineral San Fernando y la Alcald\u00eda de Naguanagua<\/em><\/p>\n<p><strong><em>(Publicado en la Revista del Domingo de Notitarde., el pasado 25 de marzo. <a href=\"http:\/\/www.notitarde.com\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">www.notitarde.com<\/a>)<\/em><\/strong><\/p>\n<p><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/twitter.png\" alt=\"Twitter\" \/>\u00a0Sigue a Alejandro Gu\u00e9dez en twitter: <a href=\"https:\/\/twitter.com\/#!\/alejofreedive\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">@alejofreedive<\/a><\/strong><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/twimg0-a.akamaihd.net\/profile_images\/1835474900\/298151_10150304250817727_615802726_8431164_596712085_n_reasonably_small.jpg\" alt=\"Alejandro Guedez\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Especial Sportalsub.net \/\u00a0Loys Leso @loysleso) Comenc\u00e9 a hacer apnea por esa atracci\u00f3n intr\u00ednseca que siempre sent\u00ed hacia el mar y sus profundidades. Es algo dif\u00edcil de explicar con palabras, es como un sentimiento que te mantiene ligado a un entorno donde experimentas una profunda paz y serenidad\u2026 Si algo caracteriza al ser humano, es su af\u00e1n por conquistar aquellos espacios [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":12164,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,133,153,8],"tags":[],"class_list":["post-12163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-destacados-anteriores","category-entrevistas","category-venezuela"],"modified_by":"Sportalsub.net","views":2785,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/entrevista-alejandro.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-3ab","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":77554,"url":"https:\/\/www.sportalsub.net\/blog\/pacifico-profundo-chile-2025","url_meta":{"origin":12163,"position":0},"title":"\ud83c\udde8\ud83c\uddf1 Resultados &#8211; AIDA Pac\u00edfico Profundo 2025 &#8211; 3er Abierto Internacional de Apnea de profundidad. Robinson Crusoe, Chile","author":"Sportalsub.net","date":"31 marzo 2025","format":false,"excerpt":"(Sportalsub.net \/ Soloapnea) Read in English Pac\u00edfico Profundo en Robinson Crusoe - Un homenaje a la Pel\u00edcula Azul Profundo La tercera versi\u00f3n de Pac\u00edfico Profundo lleg\u00f3 a la m\u00e1gica isla Robinson Crusoe de Chile del 24 al 30 de Marzo de 2025, donde los apneistas participantes pudieron descubrir sus l\u00edmites,\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/01\/pacifico-profundo-2025.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/01\/pacifico-profundo-2025.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/01\/pacifico-profundo-2025.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/01\/pacifico-profundo-2025.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19257,"url":"https:\/\/www.sportalsub.net\/blog\/torneo-apnea-robinson-crusoe-chile","url_meta":{"origin":12163,"position":1},"title":"\ud83c\udde8\ud83c\uddf1 Realizado con \u00e9xito South Pacific Deep, Primer torneo de apnea en Robinson Crusoe, Chile","author":"Sportalsub.net","date":"6 marzo 2015","format":false,"excerpt":"(Sportalsub.net \/ South Pacific Deep \/ BiobioChile) En un ambiente de hermandad deportiva, se vivi\u00f3 la primera versi\u00f3n del torneo de apnea South Pacific Deep, realizado en la isla Robinson Crusoe la \u00faltima semana de febrero. El ganador en categor\u00eda hombres, el marquista venezolano Carlos Coste, super\u00f3 los 50 metros\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/12\/apnea-chile-2015.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/12\/apnea-chile-2015.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/12\/apnea-chile-2015.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/12\/apnea-chile-2015.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3827,"url":"https:\/\/www.sportalsub.net\/blog\/audrey-mestre-la-mujer-del-oceano\/","url_meta":{"origin":12163,"position":2},"title":"\ud83c\uddeb\ud83c\uddf7 Audrey Mestre &#8211; La mujer del oc\u00e9ano","author":"Sportalsub.net","date":"12 octubre 2015","format":false,"excerpt":"(Sportalsub.net \/ Miguel A. Cede\u00f1o O.) Un d\u00eda como hoy, 12 de octubre (hace 13 a\u00f1os) fallec\u00eda en un intento de r\u00e9cord mundial la apneista francesa Audrey Mestre. Hoy recordamos parte de su vida y su carrera deportiva con una biograf\u00eda que publicamos inicialmente en el a\u00f1o 2002. Una de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/10\/audreymestre.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/10\/audreymestre.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/10\/audreymestre.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/10\/audreymestre.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/10\/audreymestre.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":77186,"url":"https:\/\/www.sportalsub.net\/blog\/la-creciente-popularidad-del-freediving-nuevos-desafios-y-records\/","url_meta":{"origin":12163,"position":3},"title":"La creciente popularidad del freediving: nuevos desaf\u00edos y r\u00e9cords","author":"Sportalsub.net","date":"12 diciembre 2024","format":false,"excerpt":"En los \u00faltimos a\u00f1os, el freediving, o buceo libre, ha experimentado un crecimiento significativo en popularidad a nivel global. Este deporte, que combina resistencia f\u00edsica, control mental y una profunda conexi\u00f3n con el entorno marino, atrae tanto a aficionados como a profesionales. Sin embargo, con esta creciente atenci\u00f3n surgen tambi\u00e9n\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/12\/popularidad-freediving.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/12\/popularidad-freediving.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/12\/popularidad-freediving.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/12\/popularidad-freediving.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":26052,"url":"https:\/\/www.sportalsub.net\/blog\/deepsea-challenge-2017","url_meta":{"origin":12163,"position":4},"title":"\ud83c\udde7\ud83c\uddf6 DeepSea Challenge 2017 Competencia Internacional de Apnea Bonaire realizada con todo \u00e9xito","author":"Sportalsub.net","date":"30 septiembre 2017","format":false,"excerpt":"(Sportalsub.net \/ DeepSea Bonaire) - Read in English BONAIRE DEEPSEA CHALLENGE COMPETENCIA INTERNACIONAL DE APNEA REALIZADA CON \u00c9XITO Carolina Schrappe rompe R\u00e9cord Continental y otros atletas logran m\u00faltiples marcas personales durante 10 d\u00edas (15-25Sept) Kralendijk, Bonaire. La Escuela de Apnea Deepsea Freediving se complace en anunciar que la edici\u00f3n de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/09\/DEN_8599.1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/09\/DEN_8599.1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/09\/DEN_8599.1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/09\/DEN_8599.1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3816,"url":"https:\/\/www.sportalsub.net\/blog\/jaques-mayol-el-delfin-humano\/","url_meta":{"origin":12163,"position":5},"title":"\ud83c\uddeb\ud83c\uddf7 Jacques Mayol &#8211; El Delf\u00edn Humano","author":"Sportalsub.net","date":"1 abril 2020","format":false,"excerpt":"El llamado Delf\u00edn Humano, fu\u00e9 uno de los primeros grandes apneistas de todos los tiempos, su muerte conmocion\u00f3 a todos los seguidores del fascinante mundo de la apnea. SPORTALSUB rinde homenaje a esta leyenda deportiva subacu\u00e1tica. Jacques Mayol fu\u00e9 un franc\u00e9s, nacido en Shangai, China el 1 de abril de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/07\/dolphinman.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/07\/dolphinman.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/07\/dolphinman.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/07\/dolphinman.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/12163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=12163"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/12163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/12164"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=12163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=12163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=12163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}