{"id":12903,"date":"2012-07-03T01:44:36","date_gmt":"2012-07-03T06:14:36","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=12903"},"modified":"2019-08-31T21:02:15","modified_gmt":"2019-09-01T01:02:15","slug":"fotos-interclubes","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/fotos-interclubes\/","title":{"rendered":"\ud83c\uddfb\ud83c\uddea Fotos Campeonato Nacional Interclubes por categor\u00edas de Nataci\u00f3n con Aletas, FVAS 2012. Caracas, Venezuela"},"content":{"rendered":"<p>Fotos exclusivas de Ronald Laurens del\u00a0Campeonato Nacional Interclubes por categor\u00edas de Nataci\u00f3n con Aletas, FVAS 2012. Caracas, Venezuela.<\/p>\n<p>Si est\u00e1s interesado en adquirir alguna de las fotos en mejor resoluci\u00f3n y sin marca de agua, escribe a: <a href=\"maitlo:ronald@sportalsub.net\">ronald@sportalsub.net<\/a><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/fb.png\" alt=\"Facebook\" \/>\u00a0<a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.10151080978912065.484591.72773737064&amp;type=1\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Galer\u00eda de Fotos completa en nuestra p\u00e1gina Facebook<\/a><\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-12903 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0072.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0072-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0072-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0072-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0070.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0070-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0070-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0070-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0069.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0069-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0069-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0069-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0062.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0062-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0062-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0062-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0060.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0060-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0060-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0060-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0052.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0052-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0052-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0052-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0051.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0051-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0051-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0051-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0039.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0039-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0039-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0039-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0038.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0038-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0038-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0038-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0035.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0035-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0035-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0035-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0024.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0024-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0024-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0024-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0023.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0023-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0023-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0023-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0020.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0020-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0020-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0020-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0019.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0019-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0019-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0019-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0018.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0018-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0018-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0018-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0015.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0015-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0015-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0015-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0013.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0013-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0013-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0013-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0012.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0012-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0012-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0012-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0010.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0010-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0010-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0010-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0009.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0009-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0009-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0009-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Fotos exclusivas de Ronald Laurens del\u00a0Campeonato Nacional Interclubes por categor\u00edas de Nataci\u00f3n con Aletas, FVAS 2012. Caracas, Venezuela. Si est\u00e1s interesado en adquirir alguna de las fotos en mejor resoluci\u00f3n y sin marca de agua, escribe a: ronald@sportalsub.net \u00a0Galer\u00eda de Fotos completa en nuestra p\u00e1gina Facebook<\/p>\n","protected":false},"author":1,"featured_media":12913,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[133,12,8],"tags":[],"class_list":["post-12903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados-anteriores","category-natacion-con-aletas","category-venezuela"],"modified_by":"Sportalsub.net","views":3586,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-3m7","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":12641,"url":"https:\/\/www.sportalsub.net\/blog\/campeonato-nacional-interclubes-por-categorias-de-natacion-con-aletas-fvas-venezuela-2012\/","url_meta":{"origin":12903,"position":0},"title":"\ud83c\uddfb\ud83c\uddea Campeonato Nacional Interclubes por Categor\u00edas de Nataci\u00f3n con Aletas FVAS, Venezuela 2012","author":"Sportalsub.net","date":"4 junio 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ FVAS) Reciban un cordial saludo de la\u00a0Federaci\u00f3n Venezolana\u00a0de Actividades Subacu\u00e1ticas\u00a0(FVAS) conjuntamente con el Club\u00a0Tritons Warriors, nos dirigimos a ustedes en la oportunidad de hacerles llegar nuestra invitaci\u00f3n formal a participar en el\u00a0Campeonato Nacional Interclubes por Categor\u00edas de Nataci\u00f3n con Aletas 2012\u00a0a efectuarse del d\u00eda viernes 29 de\u2026","rel":"","context":"En \u00abNataci\u00f3n con Aletas\u00bb","block_context":{"text":"Nataci\u00f3n con Aletas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/natacion-con-aletas\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/interclubes-sportalsub.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/interclubes-sportalsub.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/interclubes-sportalsub.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":12680,"url":"https:\/\/www.sportalsub.net\/blog\/curso-nacional-de-jueces-y-personal-tecnico-de-natacion-con-aletas-fvas-venezuela-2012\/","url_meta":{"origin":12903,"position":1},"title":"\ud83c\uddfb\ud83c\uddea Curso Nacional de Jueces y Personal T\u00e9cnico de Nataci\u00f3n con Aletas FVAS Venezuela 2012","author":"Sportalsub.net","date":"8 junio 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ FVAS) Reciban un cordial saludo de la\u00a0Federaci\u00f3n Venezolana\u00a0de Actividades Subacu\u00e1ticas\u00a0(FVAS), nos dirigimos a ustedes en la oportunidad de hacerles llegar nuestra invitaci\u00f3n formal a participar en el\u00a0Curso Nacional de Jueces y Personal T\u00e9cnico de Nataci\u00f3n con Aletas FVAS\u00a0a efectuarse del d\u00eda mi\u00e9rcoles 27 de junio al domingo\u2026","rel":"","context":"En \u00abCursos, Cl\u00ednicas y Talleres\u00bb","block_context":{"text":"Cursos, Cl\u00ednicas y Talleres","link":"https:\/\/www.sportalsub.net\/blog\/category\/cursos-y-talleres\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/jueces-sportalsub.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/jueces-sportalsub.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/jueces-sportalsub.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":14842,"url":"https:\/\/www.sportalsub.net\/blog\/campeonato-nacional-interclubes-de-natacion-con-aletas-fvas-venezuela-2013\/","url_meta":{"origin":12903,"position":2},"title":"\ud83c\uddfb\ud83c\uddea Resultados del Campeonato Nacional Interclubes de Nataci\u00f3n con Aletas FVAS Venezuela 2013","author":"Sportalsub.net","date":"31 mayo 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ FVAS) La Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas publica los Resultados oficiales del Campeonato Nacional Interclubes de Nataci\u00f3n con Aletas FVAS 2013, realizado del 10 al 12 de mayo 2013 en el Complejo de Piscinas Bolivarianas, Barquisimeto, Estado Lara con la organizaci\u00f3n del Club de Actividades Subacu\u00e1ticas Tard\u00edgrados\u2026","rel":"","context":"En \u00abDestacados Anteriores\u00bb","block_context":{"text":"Destacados Anteriores","link":"https:\/\/www.sportalsub.net\/blog\/category\/coberturas-especiales\/destacados-anteriores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/03\/interclubesaletasvenezuela.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/03\/interclubesaletasvenezuela.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/03\/interclubesaletasvenezuela.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":12781,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-del-campeonato-nacional-interclubes-por-categorias-de-natacion-con-aletas-fvas-2012-caracas-venezuela\/","url_meta":{"origin":12903,"position":3},"title":"\ud83c\uddfb\ud83c\uddea Resultados Campeonato Nacional Interclubes por categor\u00edas de Nataci\u00f3n con Aletas, FVAS 2012. Caracas, Venezuela","author":"Sportalsub.net","date":"29 junio 2012","format":false,"excerpt":"(Especial Sportalsub.net) Desde el viernes 29 de junio y hasta el domingo 1 de julio se realiz\u00f3 en el Complejo de Piscinas del Parque Naciones Unidas, en Caracas, Venezuela el\u00a0Campeonato Nacional Interclubes por categor\u00edas de Nataci\u00f3n con Aletas de la Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas, evento organizado por el Club\u2026","rel":"","context":"En \u00abDestacados Anteriores\u00bb","block_context":{"text":"Destacados Anteriores","link":"https:\/\/www.sportalsub.net\/blog\/category\/coberturas-especiales\/destacados-anteriores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/resultados-sportalsub.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/resultados-sportalsub.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/resultados-sportalsub.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":9137,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-campeonato-nacional-interclubes-de-natacion-con-aletas-fvas-2011\/","url_meta":{"origin":12903,"position":4},"title":"\ud83c\uddfb\ud83c\uddea Resultados Campeonato Nacional Interclubes de Nataci\u00f3n con Aletas Venezuela FVAS 2011","author":"Sportalsub.net","date":"2 mayo 2011","format":false,"excerpt":"Especial Sportalsub.net. Este fin de semana 30 de abril y 1 de mayo se realiz\u00f3 en el Complejo Cultural y Deportivo Los Salias en San Antonio de los Altos, Estado Miranda; el Campeonato Nacional Interclubes de Nataci\u00f3n con Aletas de Venezuela FVAS 2011. Con la participaci\u00f3n de m\u00e1s de 150\u2026","rel":"","context":"En \u00abDestacados Anteriores\u00bb","block_context":{"text":"Destacados Anteriores","link":"https:\/\/www.sportalsub.net\/blog\/category\/coberturas-especiales\/destacados-anteriores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/05\/copa_aletas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/05\/copa_aletas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/05\/copa_aletas.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":13176,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-campeonatos-nacionales-de-apnea-y-natacion-con-aletas-fvas-2012-lara-venezuela\/","url_meta":{"origin":12903,"position":5},"title":"\ud83c\uddfb\ud83c\uddea Resultados Campeonatos Nacionales de Apnea y Nataci\u00f3n con Aletas FVAS 2012. Lara, Venezuela","author":"Sportalsub.net","date":"17 agosto 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ FVAS) Con todo \u00e9xito se realizaron los\u00a0Campeonatos Nacionales de Apnea y Nataci\u00f3n con Aletas categor\u00edas Junior-Senior en piscina,\u00a0de la Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas, efectuados los d\u00edas\u00a0viernes 10, s\u00e1bado 11 y domingo 12 de agosto\u00a0en las\u00a0Piscinas Bolivarianas de Barquisimeto, Estado Lara. En el evento, en el cual\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/08\/lara-2012.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/08\/lara-2012.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/08\/lara-2012.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/07\/0024.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/12903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=12903"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/12903\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/12913"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=12903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=12903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=12903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}