{"id":14303,"date":"2012-12-19T11:00:28","date_gmt":"2012-12-19T15:30:28","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=14303"},"modified":"2019-08-30T07:18:36","modified_gmt":"2019-08-30T11:18:36","slug":"1er-campeonato-nacional-de-fotografia-subacuatica-fmas-1-y-2-de-diciembre-en-acapulco-mexico","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/1er-campeonato-nacional-de-fotografia-subacuatica-fmas-1-y-2-de-diciembre-en-acapulco-mexico\/","title":{"rendered":"\ud83c\uddf2\ud83c\uddfd Resultados del 1er Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica FMAS 1 y 2 de Diciembre en Acapulco, M\u00e9xico"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14380\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/12\/Valeria-Gran-Angular-Ambiente1.jpg\" alt=\"Valeria-Gran-Angular-Ambiente\" width=\"393\" height=\"591\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/12\/Valeria-Gran-Angular-Ambiente1.jpg 393w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/12\/Valeria-Gran-Angular-Ambiente1-199x300.jpg 199w\" sizes=\"auto, (max-width: 393px) 100vw, 393px\" \/><\/p>\n<p>(Especial Sportalsub.net \/ FMAS)<\/p>\n<p>Destacan Valeria Mas y Juan Barnard en el Primer Campeonato Fotosub<\/p>\n<div>M\u00e9xico, D.F. A 13 de diciembre de 2012.- Rogelio Flores Aguilera, presidente de la Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas, dio a conoce los resultados del primer Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica FMAS-CMAS Acapulco 2012 -1 y 2 de diciembre de 2012- tras la deliberaci\u00f3n del jurado, el cual presidi\u00f3 Alejandro Salazar, tambi\u00e9n representante de Espacio Profundo.<\/div>\n<div><\/div>\n<div>Flores Aguilera resalt\u00f3 que la organizaci\u00f3n de este primer certamen nacional de fotograf\u00eda subacu\u00e1tica permiti\u00f3 generar la estructura del reglamento de competencia invitando a personalidades destacadas en esta \u00e1rea para integrar el jurado calificador, entre ellos: Fernando Olivares (Chile), Francisco Andrade (Espa\u00f1a), Oscar Rulli (Argentina) e Iv\u00e1n Salazar (M\u00e9xico).<\/div>\n<div><\/div>\n<div>Luego entonces, los resultados arrojaron a la ganadora, Valeria Mas, en la categor\u00eda Ambiente, en segundo lugar a Juan Barnard, y en el tercer puesto qued\u00f3 Roger Mas; en la categor\u00eda Ambiente con Modelo, una vez m\u00e1s se apoder\u00f3 del primer lugar Valeria Mas, en el segundo esca\u00f1o repiti\u00f3 Juan Barnard y en el tercero se ubic\u00f3 Carlos Igashida.<\/div>\n<div><\/div>\n<div>En fotograf\u00eda de la categor\u00eda Peces, Carlos Higashida logr\u00f3 el sitio de honor, mientras que Francisco Echeverr\u00eda alcanz\u00f3 el segundo puesto y Valeria Mas el tercer lugar; en la categor\u00eda Macro, Valeria Mas alcanz\u00f3 el sitio de honor, Juan Barnard, el segundo, y Francisco Echeverr\u00eda el tercer lugar; en la categor\u00eda Macro Erizos, Juan Barnard conquist\u00f3 el primer lugar, Valeria Mas, el segundo y Carlos Higashida el tercer sitio.<\/div>\n<div><\/div>\n<div>Ante estos resultados, el jurado, en base a la contabilidad de puntos determin\u00f3 otorgar el primer y segundo lugar absolutos a Valeria Mas y Juan Barnard, respectivamente.<\/div>\n<div><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/fbcdn-sphotos-f-a.akamaihd.net\/hphotos-ak-snc6\/215165_430677083664626_542127533_n.jpg\" alt=\"\" width=\"600\" \/><br \/>\nValeria Mas &#8211; 1er Lugar Absoluto<\/div>\n<div><\/div>\n<div><img decoding=\"async\" src=\"https:\/\/fbcdn-sphotos-c-a.akamaihd.net\/hphotos-ak-ash4\/205114_430675970331404_945629719_n.jpg\" alt=\"\" width=\"600\" \/><br \/>\nJuan Barnard &#8211; 2do Lugar Absoluto<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"fmas-concurso-foto\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/11\/fmas-concurso-foto.jpg\" alt=\"\" width=\"589\" height=\"589\" \/><\/p>\n<p><strong>Fuente: <a href=\"http:\/\/www.fmas.com.mx\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">FMAS<\/a><\/strong><\/p>\n<p><strong>Enviado por:<\/strong><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" title=\"Alfredo Ponce\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/05\/Alfredo-150x150.jpg\" alt=\"\" width=\"80\" height=\"80\" \/><\/strong><\/p>\n<p><strong>Alfredo Ponce Reyes (M\u00e9xico)\u00a0<strong><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/es.fifa.com\/imgml\/flags\/s\/mex.gif\" alt=\"chi Eventos\" width=\"19\" height=\"13\" \/><br \/>\n<\/strong><\/strong>Experiencia en la cobertura deportiva por m\u00e1s de 25 a\u00f1os, editor de\u00a0<a href=\"http:\/\/www.ikkosports.com.mx\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Ikkosports<\/a>\u00a0es actualmente coordinador de medios de la\u00a0<a href=\"http:\/\/www.fmas.com.mx\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas<\/a>\u00a0encargado de la difusi\u00f3n de las actividades de este organismo en el \u00e1mbito nacional e internacional en prensa escrita, radio televisi\u00f3n y medios electr\u00f3nicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Especial Sportalsub.net \/ FMAS) Destacan Valeria Mas y Juan Barnard en el Primer Campeonato Fotosub M\u00e9xico, D.F. A 13 de diciembre de 2012.- Rogelio Flores Aguilera, presidente de la Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas, dio a conoce los resultados del primer Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica FMAS-CMAS Acapulco 2012 -1 y 2 de diciembre de 2012- tras la deliberaci\u00f3n del [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":14380,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[19,98,120],"tags":[],"class_list":["post-14303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotografia-submarina","category-mexico","category-resultados"],"modified_by":"Sportalsub.net","views":5659,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-3IH","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":17065,"url":"https:\/\/www.sportalsub.net\/blog\/viento-en-popa-el-2-campeonato-nacional-de-fotografia-subacuatica-fmas-acapulco-mexico\/","url_meta":{"origin":14303,"position":0},"title":"\ud83c\uddf2\ud83c\uddfd Viento en popa el 2\u00b0 Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica FMAS. Acapulco, M\u00e9xico","author":"Sportalsub.net","date":"3 diciembre 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ FMAS) Ciudad de M\u00e9xico. A 3 de diciembre de 2013.- Lleg\u00f3 a su fin, con buenas expectativas, el 2\u00ba. Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica Acapulco 2013, celebrada en tan importante localidad de Guerrero realizado los d\u00edas 28 y 29 de noviembre pasados, inform\u00f3 el presidente de la\u2026","rel":"","context":"En \u00abDestacados Anteriores\u00bb","block_context":{"text":"Destacados Anteriores","link":"https:\/\/www.sportalsub.net\/blog\/category\/coberturas-especiales\/destacados-anteriores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/12\/fotosub-mexico-2013.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/12\/fotosub-mexico-2013.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/12\/fotosub-mexico-2013.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":18798,"url":"https:\/\/www.sportalsub.net\/blog\/fotosub-fmas-mexico-2014","url_meta":{"origin":14303,"position":1},"title":"\ud83c\uddf2\ud83c\uddfd Resultados del 3er Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica en Formato Digital FOTOSUB FMAS 2014 M\u00e9xico","author":"Sportalsub.net","date":"3 diciembre 2014","format":false,"excerpt":"(Sportalsub.net \/ FMAS) Obtiene Valeria Mas Campeonato Nacional Fotograf\u00eda Subacu\u00e1tica Ciudad de M\u00e9xico. A 3 de diciembre de 2014. La buceadora Valeria Mas conquist\u00f3 el primer lugar general del Tercer Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica Foto Sub FMAS 2014, del 27 al 30 de noviembre de 2014 en Acapulco, Guerrero\u2026","rel":"","context":"En \u00abFotograf\u00eda Subacu\u00e1tica\u00bb","block_context":{"text":"Fotograf\u00eda Subacu\u00e1tica","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/fotografia-submarina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/10\/fotosubfmas2014.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/10\/fotosubfmas2014.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/10\/fotosubfmas2014.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":16288,"url":"https:\/\/www.sportalsub.net\/blog\/2-campeonato-nacional-de-fotografia-subacuatica-fmas-acapulco-mexico\/","url_meta":{"origin":14303,"position":2},"title":"\ud83c\uddf2\ud83c\uddfd 2\u00b0 Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica FMAS. Acapulco, M\u00e9xico","author":"Sportalsub.net","date":"8 noviembre 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ FMAS) La Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas A.C. a trav\u00e9s de su Comit\u00e9 Deportivo en coordinaci\u00f3n con la Comisi\u00f3n de Foto y Video Subacu\u00e1tico convoca a las Asociaciones, Delegaciones, entidades afiliadas y buceadores independientes a participar en el\u00a02do. CAMPEONATO NACIONAL DE FOTOGRAF\u00cdA SUBACU\u00c1TICA EN FORMATO DIGITAL\u201cACAPULCO 2013\u201d\u2026","rel":"","context":"En \u00abFotograf\u00eda Subacu\u00e1tica\u00bb","block_context":{"text":"Fotograf\u00eda Subacu\u00e1tica","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/fotografia-submarina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/Fotografia-2013.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/Fotografia-2013.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/Fotografia-2013.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/Fotografia-2013.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22171,"url":"https:\/\/www.sportalsub.net\/blog\/4to-campeonato-nacional-de-fotografia-subacuatica-fmas-2015-mexico\/","url_meta":{"origin":14303,"position":3},"title":"\ud83c\uddf2\ud83c\uddfd 4to Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica FMAS 2015 M\u00e9xico","author":"Sportalsub.net","date":"24 noviembre 2015","format":false,"excerpt":"(Sportalsub.net \/ FMAS) La Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas A.C. a trav\u00e9s de su Comit\u00e9 Deportivo en coordinaci\u00f3n con la Comisi\u00f3n de Foto y Video Subacu\u00e1tico convoca a las Asociaciones, Delegaciones, entidades afiliadas y buceadores independientes a participar en \u00e9l: 4\u00ba CAMPEONATO NACIONAL DE FOTOGRAF\u00cdA SUBACU\u00c1TICA EN FORMATO DIGITAL \u201cACAPULCO\u2026","rel":"","context":"En \u00abFotograf\u00eda Subacu\u00e1tica\u00bb","block_context":{"text":"Fotograf\u00eda Subacu\u00e1tica","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/fotografia-submarina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/10\/4tofotosubmexico.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":13275,"url":"https:\/\/www.sportalsub.net\/blog\/9-records-mexicanos-en-campeonato-de-apnea-peso-constante-inmersion-libre-y-estatica-fmas-cmas-2012\/","url_meta":{"origin":14303,"position":4},"title":"\ud83c\uddf2\ud83c\uddfd 9 R\u00e9cords Mexicanos en Campeonato de Apnea Peso Constante, Inmersi\u00f3n Libre y Est\u00e1tica FMAS-CMAS 2012","author":"Sportalsub.net","date":"7 septiembre 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ FMAS) Bacalar, Quintana Roo. Con \u00e9xito finaliz\u00f3 el primer Campeonato Nacional de Apnea en Peso Constante y Apnea Est\u00e1tica celebrado en el Cenote Azul del 24 al 26 de agosto, en donde se impusieron varios r\u00e9cords nacionales rumbo a certamen internacional de CMAS coment\u00f3 Rogelio Flores Aguilera,\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/09\/peso-constante-mexico.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/09\/peso-constante-mexico.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/09\/peso-constante-mexico.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":16113,"url":"https:\/\/www.sportalsub.net\/blog\/realizado-congreso-tecnico-nacional-2013-de-fmas-mexico\/","url_meta":{"origin":14303,"position":5},"title":"\ud83c\uddf2\ud83c\uddfd Realizado Congreso T\u00e9cnico Nacional 2013 de FMAS M\u00e9xico","author":"Sportalsub.net","date":"23 septiembre 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ FMAS) Ciudad de M\u00e9xico. La Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas (FMAS), la cual es dirigida por Rogelio Flores Aguilera, celebr\u00f3 la edici\u00f3n 39 del Congreso T\u00e9cnico Nacional en el Puerto de Veracruz del 5 al 7 de septiembre del a\u00f1o en curso. El dicho congreso, inform\u00f3 Flores\u2026","rel":"","context":"En \u00abM\u00e9xico\u00bb","block_context":{"text":"M\u00e9xico","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/mexico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/09\/congreso-fmas-2013.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/09\/congreso-fmas-2013.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/09\/congreso-fmas-2013.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/09\/congreso-fmas-2013.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/12\/Valeria-Gran-Angular-Ambiente1.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/14303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=14303"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/14303\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/14380"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=14303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=14303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=14303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}