{"id":14688,"date":"2003-09-10T15:13:11","date_gmt":"2003-09-10T19:13:11","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=14688"},"modified":"2019-08-29T23:40:00","modified_gmt":"2019-08-30T03:40:00","slug":"mauricio-fernandez-castillo-1ra-medalla-de-oro-mundial-para-la-natacion-con-aletas-de-colombia-en-korea-2003","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/mauricio-fernandez-castillo-1ra-medalla-de-oro-mundial-para-la-natacion-con-aletas-de-colombia-en-korea-2003\/","title":{"rendered":"\ud83c\udde8\ud83c\uddf4 Mauricio Fern\u00e1ndez Castillo, 1ra Medalla de Oro Mundial para la Nataci\u00f3n con Aletas de Colombia en Korea 2003"},"content":{"rendered":"<p><a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/03\/mauricio2003.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-14689\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/03\/mauricio2003.jpg\" alt=\"mauricio2003\" width=\"600\" height=\"481\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/03\/mauricio2003.jpg 600w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/03\/mauricio2003-300x241.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><br \/>\n<\/a>Foto: Cortes\u00eda Mauricio Fern\u00e1ndez Castillo<\/p>\n<p>(Especial Sportalsub.net)<\/p>\n<p>El nadador con aletas colombiano <strong>Mauricio Fern\u00e1ndez Castillo<\/strong> obtuvo la primera medalla de oro oficial en Campeonatos Mundiales de Actividades Subacu\u00e1ticas en piscina para su pa\u00eds, en la 7ma edici\u00f3n del Campeonato Mundial Junior de Nataci\u00f3n con Aletas CMAS, realizado en Jeju, Korea, del 30 de agosto al 7 de septiembre de 2003.<\/p>\n<p>Fern\u00e1ndez , con 16 a\u00f1os de edad, obtuvo la medalla de oro para titularse Campe\u00f3n Mundial en la prueba de 50 metros superficie, con tiempo de 17:08, superando a los chinos Jian Kun Lu (17:42) y Hui Li (17:49) logrando el hist\u00f3rico resultado para su pa\u00eds &#8211; <a href=\"http:\/\/www.kua.or.kr\/kua\/7th_world_jr_champ\/result\/details\/WJ206.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Resultados finales 50SF<\/a><\/p>\n<p>Mauricio tambi\u00e9n obtuvo otra presea, esta vez de bronce, en la prueba de 50 metros apnea, en donde registr\u00f3 tiempo de 15:82, siendo superado por el ruso Andrey Burakov (15:19) y el coreano Tae Kyun Kim &#8211; <a href=\"http:\/\/www.kua.or.kr\/kua\/7th_world_jr_champ\/result\/details\/WC608.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Resultados finales 50AP<\/a><\/p>\n<p>A este evento\u00a0asistieron\u00a022 selecciones nacionales, incluyendo las de Colombia, M\u00e9xico y Espa\u00f1a, por parte de los pa\u00edses hispanos.<\/p>\n<p><strong>Medallas de oro anteriores en la nataci\u00f3n con aletas colombiana<\/strong><br \/>\nCabe destacar, que en en 1996 en el Campeonato Mundial de Hungr\u00eda se realiz\u00f3 una competencia de\u00a0exhibici\u00f3n\u00a0para infantiles y la medalla de oro la gan\u00f3 Juan Guillermo Romero, en la prueba de 100 metros superficie, sin embargo fue una prueba de exhibici\u00f3n.<\/p>\n<p>Igualmente, en el Campeonato Mundial de Nataci\u00f3n con Aletas de Larga Distancia realizado en 1999 en San Andr\u00e9s-Colombia, los relevos tanto de damas como varones en la categor\u00eda juvenil ganaron la medalla de oro en los relevos 4&#215;2000<\/p>\n<p>La primera medalla por un colombiano en un mundial de nataci\u00f3n con aletas en piscina fue de Oscar Diego Cuartas en Don Guan (China) en el a\u00f1o de 1994, bronce en 100 metros inmersion (36,11)<\/p>\n<p><strong>Sitio Web Oficial del evento:\u00a0<a href=\"http:\/\/www.kua.or.kr\/kua\/7th_world_jr_champ\/jr_world_01.htm\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">http:\/\/www.kua.or.kr\/kua\/7th_world_jr_champ\/jr_world_01.htm<\/a><\/strong><\/p>\n<p><strong>Resultados Sitio Web CMAS:\u00a0<a href=\"http:\/\/www.cmas.org\/finswimming\/114-28181.php\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">http:\/\/www.cmas.org\/finswimming\/114-28181.php<\/a><\/strong><\/p>\n<p>Publicado por:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"miguel\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/05\/miguel-150x150.jpg\" alt=\"\" width=\"80\" height=\"80\" \/><\/p>\n<p><strong>Miguel Alberto Cede\u00f1o Ortiz (Venezuela)\u00a0<strong><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/es.fifa.com\/imgml\/flags\/s\/ven.gif\" alt=\"chi Eventos\" width=\"19\" height=\"13\" \/><br \/>\n<\/strong><\/strong>Nacido y residenciado en Caracas, Venezuela es el creador, director y editor de Sportalsub.net. Su experiencia como deportista, entrenador, juez y dirigente de las actividades subacu\u00e1ticas le han permitido establecer una red de contactos en todo el mundo para dar a conocer e informar todas las novedades sobre el deporte subacu\u00e1tico en habla hispana.<br \/>\n<strong><strong><a href=\"http:\/\/www.facebook.com\/miguelsportsub\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/fb.png\" alt=\"Facebook\" \/><\/a>\u00a0<\/strong><strong><a href=\"http:\/\/www.twitter.com\/miguelsportsub\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/twitter.png\" alt=\"Twitter\" \/><\/a><\/strong><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto: Cortes\u00eda Mauricio Fern\u00e1ndez Castillo (Especial Sportalsub.net) El nadador con aletas colombiano Mauricio Fern\u00e1ndez Castillo obtuvo la primera medalla de oro oficial en Campeonatos Mundiales de Actividades Subacu\u00e1ticas en piscina para su pa\u00eds, en la 7ma edici\u00f3n del Campeonato Mundial Junior de Nataci\u00f3n con Aletas CMAS, realizado en Jeju, Korea, del 30 de agosto al 7 de septiembre de 2003. [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":14689,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Mauricio Fern\u00e1ndez Castillo, 1ra Medalla de Oro Mundial para la Nataci\u00f3n con Aletas de Colombia. en Korea 2003","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,12,120],"tags":[],"class_list":["post-14688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colombia","category-natacion-con-aletas","category-resultados"],"modified_by":"Sportalsub.net","views":3535,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-3OU","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":24590,"url":"https:\/\/www.sportalsub.net\/blog\/nueva-medalla-de-oro-y-2-records-mundiales-para-colombia-en-mundial-de-natacion-con-aletas-en-grecia-videos\/","url_meta":{"origin":14688,"position":0},"title":"\ud83c\udde8\ud83c\uddf4 Nueva Medalla de Oro y 2 R\u00e9cords Mundiales para Colombia en Mundial de Nataci\u00f3n con Aletas en Grecia + Videos","author":"Sportalsub.net","date":"26 junio 2016","format":false,"excerpt":"(Sportalsub.net \/ Volos 2016) Colombia contin\u00faa brillando\u00a0en el\u00a019\u00b0 Campeonato Mundial CMAS de Nataci\u00f3n con Aletas que se lleva cabo en \u00a0Volos, Grecia\u00a0del 22 al 28 de junio de 2016\u00a0gracias a la actuaci\u00f3n de sus\u00a0deportistas, entre los que destacan Mauricio Fern\u00e1ndez y Juan Fernando Ocampo, quienes dieron nuevas alegr\u00edas al pa\u00eds\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfersalida.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfersalida.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfersalida.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfersalida.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfersalida.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfersalida.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":24571,"url":"https:\/\/www.sportalsub.net\/blog\/colombia-suma-sus-dos-primeras-medallas-de-oro-en-mundial-de-natacion-con-aletas-en-grecia-videos\/","url_meta":{"origin":14688,"position":1},"title":"\ud83c\udde8\ud83c\uddf4 Colombia suma sus dos primeras medallas de Oro en Mundial de Nataci\u00f3n con Aletas en Grecia + Videos","author":"Sportalsub.net","date":"25 junio 2016","format":false,"excerpt":"(Sportalsub.net \/ Volos 2016) Colombia inicia firme su paso por el\u00a019\u00b0 Campeonato Mundial CMAS de Nataci\u00f3n con Aletas que se lleva cabo en \u00a0Volos, Grecia\u00a0del 22 al 28 de junio de 2016\u00a0gracias a la destacada actuaci\u00f3n de sus deportistas, entre los cuales destacan las 2 medallas de oro obtenidas en\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfer2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfer2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfer2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfer2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/juanfer2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15763,"url":"https:\/\/www.sportalsub.net\/blog\/nuevo-record-mundial-para-mauricio-fernandez-de-colombia-en-50-superficie-cmas-games-kazan-rusia-2013-video\/","url_meta":{"origin":14688,"position":2},"title":"\ud83c\udde8\ud83c\uddf4 Nuevo R\u00e9cord Mundial para Mauricio Fern\u00e1ndez de Colombia en 50 superficie CMAS Games Kazan, Rusia 2013 + VIDEO","author":"Sportalsub.net","date":"7 agosto 2013","format":false,"excerpt":"(Especial Sportalsub.net \/\u00a0\u00a0CMAS Games) Tan s\u00f3lo 10 d\u00edas despu\u00e9s de haber roto el\u00a0R\u00e9cord Mundial en la prueba de 50 apnea (13.89) en los World Games Cali 2013 realizados en Colombia, el nadador con aletas colombiano\u00a0Mauricio Fern\u00e1ndez Castillo\u00a0implant\u00f3 este martes 6 de agosto, en el 17mo Campeonato Mundial de la modalidad,\u2026","rel":"","context":"En \u00abCMAS Games 2013\u00bb","block_context":{"text":"CMAS Games 2013","link":"https:\/\/www.sportalsub.net\/blog\/category\/coberturas-especiales\/cmas-games-2013\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/cmasgames2013-mauricio.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/cmasgames2013-mauricio.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/cmasgames2013-mauricio.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":15108,"url":"https:\/\/www.sportalsub.net\/blog\/excelentes-resultados-para-colombia-en-4ta-ronda-de-la-copa-del-mundo-de-natacion-con-aletas-2013-en-francia\/","url_meta":{"origin":14688,"position":3},"title":"\ud83c\udde8\ud83c\uddf4 Excelentes resultados para Colombia en 4ta Ronda de la Copa del Mundo de Nataci\u00f3n con Aletas 2013 en Francia","author":"Sportalsub.net","date":"15 abril 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ FEDECAS) Atletas de la Selecci\u00f3n Colombia de Nataci\u00f3n con Aletas, participaron este fin de semana 13 y 14 de abril en la 4ta Ronda de la VIII Copa del Mundo de Nataci\u00f3n con Aletas, realizada en Aix en Provence, Francia, con excelentes resultados y medallas, como parte\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/colombia-francia-2013.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/colombia-francia-2013.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/colombia-francia-2013.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/colombia-francia-2013.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22540,"url":"https:\/\/www.sportalsub.net\/blog\/tomsk-2016","url_meta":{"origin":14688,"position":4},"title":"\ud83c\uddf7\ud83c\uddfa Resultados Finales &#8211; Golden Final Copa Mundo CMAS Nataci\u00f3n con Aletas 2016 Tomsk, Rusia","author":"Sportalsub.net","date":"12 septiembre 2016","format":false,"excerpt":"(Sportalsub.net \/ CMAS \/ World Cup Final 2016) - Read in English La Golden Final de la Copa Mundo de Nataci\u00f3n con Aletas CMAS 2016 se realiz\u00f3 en la ciudad de Tomsk, Rusia, del 9 al 11 de septiembre, con la participaci\u00f3n de clubes y deportistas de diferentes pa\u00edses y\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/09\/cmasworldcup3.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/09\/cmasworldcup3.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/09\/cmasworldcup3.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/09\/cmasworldcup3.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/09\/cmasworldcup3.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":15785,"url":"https:\/\/www.sportalsub.net\/blog\/grace-fernandez-le-da-una-nueva-medalla-de-oro-a-colombia-en-los-cmas-games-kazan-rusia-2013-video\/","url_meta":{"origin":14688,"position":5},"title":"\ud83c\udde8\ud83c\uddf4 Grace Fern\u00e1ndez le da una nueva medalla de Oro a Colombia en los CMAS Games Kazan, Rusia 2013 + VIDEO","author":"Sportalsub.net","date":"9 agosto 2013","format":false,"excerpt":"(Especial Sportalsub.net \/\u00a0\u00a0CMAS Games \/ Foto: Oleg Pudov) La nadadora con aletas colombiana\u00a0Grace Fern\u00e1ndez Castillo\u00a0implant\u00f3 este martes 6 de agosto, en el 17mo Campeonato Mundial de la modalidad, II CMAS Games en Kazan, Rusia una nueva medalla de oro con nuevo R\u00e9cord Panamericano en los 100 metros superficie con monoaleta.\u2026","rel":"","context":"En \u00abCMAS Games 2013\u00bb","block_context":{"text":"CMAS Games 2013","link":"https:\/\/www.sportalsub.net\/blog\/category\/coberturas-especiales\/cmas-games-2013\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/cmasgames2013-grace.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/cmasgames2013-grace.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/cmasgames2013-grace.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/03\/mauricio2003.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/14688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=14688"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/14688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/14689"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=14688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=14688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=14688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}