{"id":15108,"date":"2013-04-15T12:55:31","date_gmt":"2013-04-15T17:25:31","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=15108"},"modified":"2019-08-31T21:44:57","modified_gmt":"2019-09-01T01:44:57","slug":"excelentes-resultados-para-colombia-en-4ta-ronda-de-la-copa-del-mundo-de-natacion-con-aletas-2013-en-francia","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/excelentes-resultados-para-colombia-en-4ta-ronda-de-la-copa-del-mundo-de-natacion-con-aletas-2013-en-francia\/","title":{"rendered":"\ud83c\udde8\ud83c\uddf4 Excelentes resultados para Colombia en 4ta Ronda de la Copa del Mundo de Nataci\u00f3n con Aletas 2013 en Francia"},"content":{"rendered":"<p><a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/colombia-francia-2013.jpg\" target=\"_blank\"><img decoding=\"async\" class=\"alignnone wp-image-15109\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/colombia-francia-2013.jpg\" alt=\"colombia-francia-2013\" width=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/colombia-francia-2013.jpg 700w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/colombia-francia-2013-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/colombia-francia-2013-177x118.jpg 177w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><\/a><\/p>\n<p>(Especial Sportalsub.net \/ FEDECAS)<\/p>\n<p>Atletas de la Selecci\u00f3n Colombia de Nataci\u00f3n con Aletas, participaron este fin de semana 13 y 14 de abril en la 4ta Ronda de la VIII Copa del Mundo de Nataci\u00f3n con Aletas, realizada en Aix en Provence, Francia, con excelentes resultados y medallas, como parte de su preparaci\u00f3n para los World Games 2013 a realizarse en Cali en el mes de julio.<\/p>\n<p>Gracias a la <a href=\"http:\/\/www.fedecas.net\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas (FEDECAS)<\/a> publicamos la rese\u00f1a de la actuaci\u00f3n de Colombia en este importante Campeonato Internacional.<\/p>\n<p><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/pdf.gif\" alt=\"\" \/>\u00a0<a href=\"http:\/\/www.nageavecpalmes-ffessm.com\/fr\/compet\/inter\/2013\/4-e%20round%20finswimming%20WC%202013\/resultats\/CM2013_ProtocoleComplet.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Resultados Finales Completos y Oficiales<\/a><\/strong><\/p>\n<h1>JORNADA N\u00b0 4.\u00a0\u00a0\u00a0 Domingo 14 de Abril de 2013<\/h1>\n<h4>La Selecci\u00f3n Colombia de Nataci\u00f3n con Aletas, en la tarde del d\u00eda domingo14 de abril\/13,\u00a0 participo en las pruebas 50 m. Sup., masculino y femenino,\u00a0 y\u00a0 relevo 4 X 100 femenino. En la prueba 50 Sup., la deportista Alix P\u00e9rez Rubio gano medalla de Oro y la deportista Grace Fern\u00e1ndez gano medalla de plata, en la misma\u00a0 prueba rama masculino el deportista Mauricio Fern\u00e1ndez gano medalla de plata y en el relevo 4 X 100 Femenino \u00a0las deportistas: Yesica Salazar, Kelly P\u00e9rez, Alix Victoria P\u00e9rez y\u00a0 Grace Fern\u00e1ndez, ganaron medalla de Oro.<\/h4>\n<h4>Resultados 4da. Jornada, 4ta. Ronda Copa Mundo de Nataci\u00f3n con Aletas. Aix en Provence<\/h4>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 50\u00a0 Sup.\u00a0 Femenino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>PEREZ RUBIO, Alix<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:18,91<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>FERNANDEZ CASTILLO, Grace<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:18,94<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>BARANOVSKAYA, Valeria<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:19,03<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h1><\/h1>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 50 Sup.\u00a0 Masculino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>NAVA, Andrea<\/strong><\/td>\n<td valign=\"top\" width=\"76\">00:16,05<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>FERNANDEZ CASTILLO, Mauricio<\/strong><\/td>\n<td valign=\"top\" width=\"76\">00:16,59<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>KOKOREV, Dmitrii<\/strong><\/td>\n<td valign=\"top\" width=\"76\">00:16,82<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>OCAMPO LOZADA, Juan Fernando<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">0<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">Descalificado<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h1><\/h1>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba:\u00a0 Relevo 4 x 100 Femenino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Pa\u00eds\/Club<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>COLOMBIA<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">02:48,08<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>RUSSIA<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">02:49,34<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Club Nord Padania Sub Vardo Italia<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">03:01,32<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h1><\/h1>\n<h1>JORNADA N\u00b0 3.\u00a0\u00a0\u00a0 Domingo 14 de Abril de 2013<\/h1>\n<h1><\/h1>\n<p>La Selecci\u00f3n Colombia de Nataci\u00f3n con Aletas, en la ma\u00f1ana del d\u00eda domingo particip\u00f3\u00a0en las pruebas 100 m. Sup.,\u00a0 y\u00a0 400 m.\u00a0 Sup, masculino y femenino, en la que el deportista Juan Fernando Ocampo gano medalla de Plata en la prueba 400 Superficie.<\/p>\n<p>Resultados 3da. Jornada, 4ta. Ronda Copa Mundo de Nataci\u00f3n con Aletas. Aix en Provence<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 100\u00a0 Sup.\u00a0 Femenino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>KRAVCHUK, Vasilisa<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:40,39<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>BARANOVSKAYA, Valeria<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:40,68<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>BER, Anna<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:41,39<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>FERNANDEZ CASTILLO, Grace<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:42,07<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">4\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>SALAZAR SOLORZANO, Yesica<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:43,78<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">8\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h1><\/h1>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 100 Sup.\u00a0 Masculino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>NAVA, Andrea<\/strong><\/td>\n<td valign=\"top\" width=\"76\">00:35,40<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>KOKOREV Dmitrii<\/strong><\/td>\n<td valign=\"top\" width=\"76\">00:36,06<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>NOIR, Alexandre<\/strong><\/td>\n<td valign=\"top\" width=\"76\">00:36,36<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>ROMERO RIVERA, Le\u00f3nidas<\/strong><\/td>\n<td valign=\"top\" width=\"76\">00:37,40<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">5\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h1><\/h1>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba:\u00a0 400 Sup.\u00a0 Femenino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>KRAVCHUK, Vasilisa<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">03:20,19<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>BORISOVA, Nadejda<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">03:23,35<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>OSMOLSKAIA, Elena<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">03:23,46<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>PEREZ RUBIO, Kelly<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">03:38,43<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">7\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h1><\/h1>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba:\u00a0 400 Sup.\u00a0 Masculino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>FIGINI, Stefano<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">03:02,02<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>OCAMPO LOZADA, Juan Fernando<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">03:02,54<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>REZNIKOV, Nikolay<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">03:02,65<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>JIMENEZ RAMIREZ, Alexander<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">03:09,34<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">5\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h1><\/h1>\n<h1 align=\"center\">JORNADA N\u00b0 2.\u00a0 \u00a0S\u00e1bado 13 de Abril Jornada 2<\/h1>\n<p>&nbsp;<\/p>\n<p>La Selecci\u00f3n Colombia de Nataci\u00f3n con Aletas, continu\u00f3 \u00a0cosechando triunfos en\u00a0 la Jornada de la tarde del d\u00eda 13 d abril de 2013, en las pruebas de 200 Sup., y 100 inmersi\u00f3n masculino y Femenino.<\/p>\n<p>Resultados 2da. Jornada 4ta. Ronda Copa Mundo de Nataci\u00f3n con Aletas. Aix en Provence<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 200\u00a0 Sup.\u00a0 Femenino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>BARANOVSKAYA, Valeria<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">01:29,35<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>KRAVCHUK, Vasilisa<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">01:31,02<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>FERNANDEZ CASTILLO, Grace<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">01:33,76<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>PEREZ RUBIO, Kelly<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">01:39,50<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">8\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 200 Sup.\u00a0 Masculino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>KOKOREV, Dimitri<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">01:22,33<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>OCAMPO LOZADA,\u00a0 Juan<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">01:22,77<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>REZNIKOV, Nicolay<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">01:23,24<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>JIMENEZ RAMIREZ, Alexander<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">01:26,27<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">6\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 100 Inmersi\u00f3n\u00a0 Femenino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>HEITZ, Camille<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:38,82<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>PEREZ RUBIO, Alix<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:38,58<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>ANDRIENKO, Elizaveta<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:39,32<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>SALAZAR SOLORZANO, Yesica<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:41,24<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">5\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 100 Inmersi\u00f3n\u00a0 Masculino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>FERNANDEZ CASTILLO, \u00a0Mauricio<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:33,64<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>SAPRYKIN, Igor<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:35,13<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>NOIR, Alexandre<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:35,19<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>ROMERO RIVERA, Le\u00f3nidas<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:35,33<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">4\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h1><\/h1>\n<h1>LA SELECCI\u00d3N COLOMBIA DE NATACI\u00d3N CON ALETAS\u00a0 GANO SUS DOS PRIMERAS MEDALLAS DE ORO EN LA PRUEBA DE 50 APNEA FEMENINO Y MASCULINO.<\/h1>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"599\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"599\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"599\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Los deportistas de la Selecci\u00f3n Colombia de Nataci\u00f3n con Aletas ALIX V.PEREZ RUBIO y MAURICIO FERNANDEZ CASTILLO, ganaron para Colombia las dos primeras medallas de Oro, en la 4ta. Ronda de la Copa Mundo que se est\u00e1 realizando en Aix en Provence Francia.<\/p>\n<p>Resultados 1ra. Jornada 4ta. Ronda Copa Mundo de Nataci\u00f3n con Aletas. Aix en Provence<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 50\u00a0 Apnea Femenino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>PEREZ RUBIO, Alix<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:16,90<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>HEITZ, Camille<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:17,04<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>VER, Anna<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:17,25<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">3\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Bronce<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>SALAZAR SOLORZANO,\u00a0 Jessica<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:18,15<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">7<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 50 Apnea Masculino<\/strong><\/td>\n<td colspan=\"3\" width=\"331\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\"><strong>Lugar ocupado<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\"><strong>Medallas<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>FERNANDEZ CASTILLO, Mauricio<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:14,68<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">1\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Oro<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>NOIR, Alexander<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:15,72<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">2\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\">\n<p align=\"center\">Plata<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>\u00a0<\/strong><\/td>\n<td valign=\"top\" width=\"76\"><\/td>\n<td valign=\"top\" width=\"113\"><\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>ROMERO RIVERA, Le\u00f3nidas<\/strong><\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:16,02<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p align=\"center\">4\u00b0<\/p>\n<\/td>\n<td valign=\"top\" width=\"142\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h1>NUEVO RECORD NACIONAL EN\u00a0 LAS PRUEBA 800 metros Superficie.<\/h1>\n<p>El deportista\u00a0ALEXANDER\u00a0 JIMENEZ RAM\u00cdREZ, en la primera jornada realizada el d\u00eda 13 de abril de 2013,\u00a0en la 4ta. Ronda de la Copa Mundo.\u00a0realizo un tiempo de\u00a006:41,81, imponiendo un nuevo Record Nacional.<\/p>\n<p>&nbsp;<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"225\"><strong>Prueba: 800 Superficie Masculino<\/strong><\/td>\n<td width=\"76\"><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">\n<p align=\"center\"><strong>Apellidos y Nombres<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\"><strong>Tiempo<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"225\">JIMENEZ RAM\u00cdREZ, Alexander<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">06:41,81<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<h1>INFORMACI\u00d3N\u00a0GENERAL\u00a0 SELECCI\u00d3N COLOMBIA A LOS JUEGOS\u00a0 MUNDIALES CALI 2013 (World Games 2013).<\/h1>\n<p>&nbsp;<\/p>\n<p>La Selecci\u00f3n Colombia de Nataci\u00f3n con Aletas que participar\u00e1 en los JUEGOS MUNDIALE 2013 (World Games 2013), se encuentra haciendo su preparaci\u00f3n en la ciudad de Aix en Provence Francia, participando en la 4ta. Ronda de la Copa Mundo.<\/p>\n<p>Los deportistas de la selecci\u00f3n Colombia participaran en las siguientes pruebas en los JUEGOS MUNDIALE 2013 (World Games 2013).<\/p>\n<p>DEPORTISTAS CLASIFICADOS EN LOS CAMPEONATOS SEG\u00daN\u00a0 RANKING DE LA CONFEDERACI\u00d3N MUNDIAL DE ACTIVIDADES SUBACUATICAS<\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"40\">Ord<\/td>\n<td valign=\"top\" width=\"198\">Nombres y Apellidos<\/td>\n<td valign=\"top\" width=\"66\">Prueba<\/td>\n<td valign=\"top\" width=\"76\">Tiempo<\/td>\n<td valign=\"top\" width=\"66\">Rama<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"40\">1.<\/td>\n<td valign=\"top\" width=\"198\">Alix Victoria P\u00e9rez Rubio<\/td>\n<td valign=\"top\" width=\"66\">\n<p align=\"center\">50 Ap<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:16,66<\/p>\n<\/td>\n<td valign=\"top\" width=\"66\">\n<p align=\"center\">F<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"40\">2.<\/td>\n<td valign=\"top\" width=\"198\">Mauricio Fern\u00e1ndez Castillo<\/td>\n<td valign=\"top\" width=\"66\">\n<p align=\"center\">50 Ap<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p align=\"center\">00:14,44<\/p>\n<\/td>\n<td valign=\"top\" width=\"66\">\n<p align=\"center\">M<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>RELEVO 4 X 100 FEMENINO<\/p>\n<p>RELEVO 4 x 100 MASCULINO<\/p>\n<p>DEPORTISTAS QUE FORMAN PARTE DEL RELEVO 4 X 100 metros\u00a0 INVITADAS POR LA\u00a0 CONFEDERACI\u00d3N MUNDIAL DE ACTIVIDADES SUBACUATICAS A PARTICIPAR EN PRUEBAS INDIVIDUALES EN LOS JUEGOS MUNDIALES 2013. (World Games 2013)<\/p>\n<table style=\"width: 470px;\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"40\">\n<p align=\"center\">N\u00ba<\/p>\n<\/td>\n<td valign=\"top\" nowrap=\"nowrap\" width=\"253\">\n<p align=\"center\">Nombres<\/p>\n<\/td>\n<td valign=\"top\" width=\"177\">\n<p align=\"center\">Prueba<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"40\">\n<p align=\"center\">1<\/p>\n<\/td>\n<td valign=\"top\" nowrap=\"nowrap\" width=\"253\">Grace Fern\u00e1ndez\u00a0 Castillo<\/td>\n<td valign=\"top\" width=\"177\">\n<p align=\"center\">100 Superf.<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"40\">\n<p align=\"center\">2<\/p>\n<\/td>\n<td valign=\"top\" nowrap=\"nowrap\" width=\"253\">Yesica A. Salazar Sol\u00f3rzano<\/td>\n<td valign=\"top\" width=\"177\">\n<p align=\"center\">50 Apnea<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"40\">\n<p align=\"center\">3<\/p>\n<\/td>\n<td valign=\"top\" nowrap=\"nowrap\" width=\"253\">Kelly Ximena P\u00e9rez Rubio<\/td>\n<td valign=\"top\" width=\"177\">\n<p align=\"center\">200 Superf.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Actualmente la Selecci\u00f3n Colombia de Nataci\u00f3n con Aletas e encuentra en la ciudad de Aix en Provence Francia, participando en la 4ta. Ronda de la Copa Mundo del 12 al 14 de Abril de 2013.<\/p>\n<p><strong>Fuente: <a href=\"http:\/\/www.fedecas.net\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">FEDECAS<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Especial Sportalsub.net \/ FEDECAS) Atletas de la Selecci\u00f3n Colombia de Nataci\u00f3n con Aletas, participaron este fin de semana 13 y 14 de abril en la 4ta Ronda de la VIII Copa del Mundo de Nataci\u00f3n con Aletas, realizada en Aix en Provence, Francia, con excelentes resultados y medallas, como parte de su preparaci\u00f3n para los World Games 2013 a realizarse [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":15109,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,262,12,258],"tags":[],"class_list":["post-15108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colombia","category-copa-mundo-cmas-2013","category-natacion-con-aletas","category-world-games-2013"],"modified_by":"Sportalsub.net","views":3816,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/colombia-francia-2013.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-3VG","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":15096,"url":"https:\/\/www.sportalsub.net\/blog\/viii-copa-mundo-natacion-con-aletas-cmas-4ta-ronda-2013-francia\/","url_meta":{"origin":15108,"position":0},"title":"\ud83c\uddeb\ud83c\uddf7 Resultados VIII Copa Mundo Nataci\u00f3n con Aletas CMAS \u2013 4ta Ronda 2013 \u2013 Francia","author":"Sportalsub.net","date":"13 abril 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ FFESSM \/ CMAS\/ Finswimmer) Este fin de semana, s\u00e1bado 13 y domingo 14 de abril se realiz\u00f3 en Aix en Provence, Francia;\u00a0la 4ta Ronda de la VIII Copa del Mundo de Nataci\u00f3n con Aletas CMAS con la participaci\u00f3n de m\u00e1s de 250 atletas, de 56 clubes de\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/ronda-francia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/ronda-francia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/04\/ronda-francia.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":15260,"url":"https:\/\/www.sportalsub.net\/blog\/natacion-con-aletas-esperanza-colombiana-en-los-juegos-mundiales-2013-video-instinto-natural\/","url_meta":{"origin":15108,"position":1},"title":"\ud83c\udde8\ud83c\uddf4 Nataci\u00f3n con Aletas, esperanza colombiana en Los Juegos Mundiales 2013 + VIDEO, Instinto Natural","author":"Sportalsub.net","date":"19 mayo 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ World Games Cali 2013) Mauricio Fern\u00e1ndez, Alix Victoria P\u00e9rez, Grace Fern\u00e1ndez, adem\u00e1s de los relevos masculino y femenino, son la esperanza para Colombia en las competencias de Nataci\u00f3n con Aletas, que se llevar\u00e1n a cabo durante Los Juegos Mundiales 2013 Cali; As\u00ed lo hizo saber, el presidente\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/05\/colombia-juegos-mundiales.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18250,"url":"https:\/\/www.sportalsub.net\/blog\/4ta-jornada-cartagena","url_meta":{"origin":15108,"position":2},"title":"\ud83c\udde8\ud83c\uddf4 Resultados 4ta jornada 7ma Ronda IX Copa Mundo CMAS y I Copa FEDECAS de Nataci\u00f3n con Aletas. Cartagena, Colombia","author":"Sportalsub.net","date":"10 agosto 2014","format":false,"excerpt":"(Especial Sportalsub.net \/ CMAS \/ FEDECAS \/ LASC) Este domingo 10\u00a0de agosto en la ma\u00f1ana se realiz\u00f3 la cuarta jornada y \u00faltima de las pruebas de piscina de la\u00a0VII Ronda de la IX Copa Mundo de Nataci\u00f3n con Aletas CMAS y \u00a0I Copa Fedecas de Nataci\u00f3n con Aletas, que se\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/08\/IMG_1219.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/08\/IMG_1219.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/08\/IMG_1219.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/08\/IMG_1219.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15713,"url":"https:\/\/www.sportalsub.net\/blog\/seleccion-colombia-de-natacion-con-aletas-a-confirmar-su-nivel-en-los-cmas-games-kazan-2013\/","url_meta":{"origin":15108,"position":3},"title":"\ud83c\udde8\ud83c\uddf4 Selecci\u00f3n Colombia de Nataci\u00f3n con Aletas a confirmar su nivel en los CMAS Games Kazan 2013","author":"Sportalsub.net","date":"30 julio 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ FEDECAS) Luego de la excelente actuaci\u00f3n en la que obtuvieron 3 medallas (1 de plata y 3 de bronce) y un nuevo r\u00e9cord mundial (para Mauricio Fern\u00e1ndez en los 50 apnea con 13.89), en las pruebas de nataci\u00f3n con aletas de los Juegos Mundiales World Games 2013\u2026","rel":"","context":"En \u00abCMAS Games 2013\u00bb","block_context":{"text":"CMAS Games 2013","link":"https:\/\/www.sportalsub.net\/blog\/category\/coberturas-especiales\/cmas-games-2013\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/07\/colombia-francia-2013.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/07\/colombia-francia-2013.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/07\/colombia-francia-2013.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/07\/colombia-francia-2013.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9213,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-vi-copa-mundo-natacion-con-aletas-cmas-%e2%80%93-4ta-ronda-%e2%80%93-alemania\/","url_meta":{"origin":15108,"position":4},"title":"\ud83c\udde9\ud83c\uddea Resultados VI Copa Mundo Nataci\u00f3n con Aletas CMAS \u2013 4ta Ronda \u2013 Alemania","author":"Sportalsub.net","date":"16 mayo 2011","format":false,"excerpt":"Especial Sportalsub.net Este s\u00e1bado 14 y domingo 15 de mayo se realiz\u00f3 en Leipzig, Alemania la 4ta Ronda de la VI Copa del Mundo de Nataci\u00f3n con Aletas CMAS. El evento cont\u00f3 con la participaci\u00f3n de m\u00e1s de 250 deportistas, 57 clubes y 14 pa\u00edses, entres los cuales se encontraba\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/05\/wm02.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":27236,"url":"https:\/\/www.sportalsub.net\/blog\/copa-mundo-cmas-nadosub-2018-usa","url_meta":{"origin":15108,"position":5},"title":"\ud83c\uddfa\ud83c\uddf8 Resultados Finales &#8211; XIII Copa Mundo CMAS Nataci\u00f3n Con Aletas 2018. 4ta Ronda \u2013 Coral Springs, USA","author":"Sportalsub.net","date":"15 mayo 2018","format":false,"excerpt":"(Sportalsub.net \/ CMAS) - Read in English Finaliza con todo \u00e9xito la Copa Mundo de Nataci\u00f3n con Aletas en Coral Springs, Florida. Con una excelente participaci\u00f3n, organizaci\u00f3n y nivel deportivo se realizaron las 4 sesiones de competencia de la 4ta Ronda de la Copa Mundo CMAS 2018 de Nataci\u00f3n con\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/coralspringsfinal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/coralspringsfinal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/coralspringsfinal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/coralspringsfinal.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/15108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=15108"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/15108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/15109"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=15108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=15108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=15108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}