{"id":15378,"date":"2013-06-20T08:14:00","date_gmt":"2013-06-20T12:44:00","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=15378"},"modified":"2019-08-30T07:27:37","modified_gmt":"2019-08-30T11:27:37","slug":"juegos-fedecas-2013-colombia","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/juegos-fedecas-2013-colombia\/","title":{"rendered":"\ud83c\udde8\ud83c\uddf4 Resultados Juegos FEDECAS 2013 &#8211; Colombia + VIDEO"},"content":{"rendered":"<p><a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/06\/juegosfedecas2013.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15379\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/06\/juegosfedecas2013.jpg\" alt=\"juegosfedecas2013\" width=\"600\" height=\"268\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/06\/juegosfedecas2013.jpg 600w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/06\/juegosfedecas2013-300x134.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/06\/juegosfedecas2013-364x164.jpg 364w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>(Especial Sportalsub.net \/ FEDECAS)<\/p>\n<p>Del 14 al 16 de junio de 2013 se realizaron en las ciudades de Cali y Popay\u00e1n, los Campeonatos Nacionales Interligas de la Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas \u00ab<strong>IV Juegos FEDECAS<\/strong>\u00bb en las modalidades de apnea, nataci\u00f3n con aletas y rugby subacu\u00e1tico.<\/p>\n<p>Este evento, que lleg\u00f3 a su cuarta edici\u00f3n, reuni\u00f3 a los mejores deportistas subacu\u00e1ticos de Colombia.<\/p>\n<p><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/pdf.gif\" alt=\"\" \/>\u00a0<a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/06\/Resultados-Apnea-FEDECAS-Poapayan.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Resultados Apnea<\/a><\/strong><\/p>\n<p><strong><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/pdf.gif\" alt=\"\" \/>\u00a0<a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/06\/juegos-fedecas-aletas.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Resultados Nataci\u00f3n con Aletas<\/a><\/strong><\/p>\n<p><strong>Resultados Rugby Subacu\u00e1tico<\/strong><\/p>\n<p><strong>MASCULINO:<\/strong><br \/>\nCAMPE\u00d3N: VALLE<br \/>\nSUBCAMPE\u00d3N: ANTIOQUIA<br \/>\n3ERO: BOGOTA<\/p>\n<p><strong>FEMENINO:<\/strong><br \/>\nCAMPE\u00d3N: BOGOTA<br \/>\nSUBCAMPE\u00d3N: VALLE<br \/>\n3ERO: ANTIOQUIA<\/p>\n<p><strong>Reportaje en Video TV Local Cali<\/strong><\/p>\n<p><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/0ATnIYk48jU\" width=\"600\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>En el sitio web oficial de FEDECAS pueden encontrar toda la informaci\u00f3n relacionada con este importante evento:<br \/>\n<a href=\"http:\/\/fedecas.net\/campeonatos\/index.php\/juegos-fedeca-2013\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">http:\/\/fedecas.net\/campeonatos\/index.php\/juegos-fedeca-2013<\/a><\/p>\n<p>Fuente: <a href=\"http:\/\/www.fedecas.net\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">FEDECAS<\/a><\/p>\n<p>Publicado por:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"miguel\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/05\/miguel-150x150.jpg\" alt=\"\" width=\"80\" height=\"80\" \/><\/p>\n<p><strong>Miguel Alberto Cede\u00f1o Ortiz (Venezuela)\u00a0<strong><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/es.fifa.com\/imgml\/flags\/s\/ven.gif\" alt=\"chi Eventos\" width=\"19\" height=\"13\" \/><br \/>\n<\/strong><\/strong>Nacido y residenciado en Caracas, Venezuela es el creador, director y editor de Sportalsub.net. Su experiencia como deportista, entrenador, juez y dirigente de las actividades subacu\u00e1ticas le han permitido establecer una red de contactos en todo el mundo para dar a conocer e informar todas las novedades sobre el deporte subacu\u00e1tico en habla hispana.<br \/>\n<strong><strong><a href=\"http:\/\/www.facebook.com\/miguelsportsub\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/fb.png\" alt=\"Facebook\" \/><\/a>\u00a0<\/strong><strong><a href=\"http:\/\/www.twitter.com\/miguelsportsub\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/twitter.png\" alt=\"Twitter\" \/><\/a><\/strong><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Especial Sportalsub.net \/ FEDECAS) Del 14 al 16 de junio de 2013 se realizaron en las ciudades de Cali y Popay\u00e1n, los Campeonatos Nacionales Interligas de la Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas \u00abIV Juegos FEDECAS\u00bb en las modalidades de apnea, nataci\u00f3n con aletas y rugby subacu\u00e1tico. Este evento, que lleg\u00f3 a su cuarta edici\u00f3n, reuni\u00f3 a los mejores deportistas subacu\u00e1ticos [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":15379,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,3,282,12,104,120],"tags":[],"class_list":["post-15378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-colombia","category-juegos-fedecas-2013","category-natacion-con-aletas","category-orientacion-subacuatica","category-resultados"],"modified_by":"Sportalsub.net","views":2984,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/06\/juegosfedecas2013.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-402","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":50403,"url":"https:\/\/www.sportalsub.net\/blog\/ix-juegos-fedecas-colombia-2021","url_meta":{"origin":15378,"position":0},"title":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211; IX Juegos FEDECAS Interligas con Invitaci\u00f3n Internacional. Medell\u00edn, Colombia 2021","author":"Sportalsub.net","date":"14 diciembre 2021","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS \/ LASA) La Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas convoc\u00f3 a las ligas de Colombia y a las Federaciones afiliadas a CMAS Am\u00e9rica a la IX Edici\u00f3n de los Juegos FEDECAS, Campeonatos Nacionales Interligas con Invitaci\u00f3n Internacional, en las modalidades de Apnea, Hockey Subacu\u00e1tico, Rugby Subacu\u00e1tico y Nataci\u00f3n\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/11\/juegosfededecas2021.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/11\/juegosfededecas2021.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/11\/juegosfededecas2021.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/11\/juegosfededecas2021.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":27001,"url":"https:\/\/www.sportalsub.net\/blog\/viii-juegos-fedecas-2017-colombia","url_meta":{"origin":15378,"position":1},"title":"\ud83c\udde8\ud83c\uddf4 Resultados Finales &#8211; VIII Juegos FEDECAS Colombia 40 a\u00f1os de Actividades Subacu\u00e1ticas &#8211; Cali","author":"Sportalsub.net","date":"16 diciembre 2017","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS) La Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas FEDECAS celebr\u00f3 sus 40 A\u00f1os el d\u00eda 9 de Diciembre de 2017 a las 6:00 pm, en la ciudad de Santiago de Cali, Piscinas Alberto Galindo, en marco del\u00a0Campeonato Nacional Interligas, VIII Juegos FEDECAS con\u00a0invitaci\u00f3n internacional, Categor\u00eda Abierta en las modalidades\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/12\/juegosfedecas1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/12\/juegosfedecas1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/12\/juegosfedecas1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/12\/juegosfedecas1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/12\/juegosfedecas1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/12\/juegosfedecas1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":24217,"url":"https:\/\/www.sportalsub.net\/blog\/vii-juegos-fedecas-de-actividades-subacuaticas-colombia\/","url_meta":{"origin":15378,"position":2},"title":"\ud83c\udde8\ud83c\uddf4 VII Juegos FEDECAS de Actividades Subacu\u00e1ticas Colombia 2016","author":"Sportalsub.net","date":"29 mayo 2016","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS) Del 1 al 5 de junio de 2016 se llevar\u00e1 a cabo en la ciudad de Bogot\u00e1, D.C. en Colombia, la VII edici\u00f3n de los Juegos FEDECAS de Actividades Subacu\u00e1ticas, Campeonatos Nacionales (con invitaci\u00f3n internacional) de las modalidades de piscina en Apnea, Nataci\u00f3n con Aletas, Hockey Subacu\u00e1tico\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/juegosfedecas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/juegosfedecas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/juegosfedecas.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":77166,"url":"https:\/\/www.sportalsub.net\/blog\/juegos-fedecas-colombia-2024","url_meta":{"origin":15378,"position":3},"title":"\ud83c\udde8\ud83c\uddf4 Resultados X Juegos FEDECAS Interligas 2024: Apnea, Nataci\u00f3n con Aletas, Hockey Subacu\u00e1tico, Rugby Subacu\u00e1tico \u2013 Colombia","author":"Sportalsub.net","date":"11 diciembre 2024","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS) Del 4 al 8 de Diciembre de 2024 en las ciudades de Medell\u00edn, Antioquia y Pereira, Risaralda se realizaron los X Juegos FEDECAS Interligas de Actividades Subacu\u00e1ticas,\u00a0 donde participaron las modalidades de Apnea, Nataci\u00f3n con Aletas, Hockey Subacu\u00e1tico y Rugby Subacu\u00e1tico, organizados por la Federaci\u00f3n Colombiana de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/12\/juegos-fedecas-2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/12\/juegos-fedecas-2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/12\/juegos-fedecas-2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/12\/juegos-fedecas-2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6824,"url":"https:\/\/www.sportalsub.net\/blog\/programacion-de-los-juegos-fedecas-de-actividades-subacuaticas-colombia-2010\/","url_meta":{"origin":15378,"position":4},"title":"\ud83c\udde8\ud83c\uddf4 Programaci\u00f3n de los Juegos FEDECAS de Actividades Subacu\u00e1ticas Colombia 2010","author":"Sportalsub.net","date":"2 diciembre 2010","format":false,"excerpt":"(Especial Sportalsub.net - Prensa Juegos FEDECAS) Ya todo est\u00e1 listo para que este viernes 3 de diciembre inicien las competencias subacu\u00e1ticas en la ciudad de Medell\u00edn, Departamento de Antioquia, Colombia, donde se estar\u00e1n realizando los 1ros Juegos de la Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas (FEDECAS) en las modalidades de Apnea,\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/12\/hockeyfedecas.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/12\/hockeyfedecas.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/12\/hockeyfedecas.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":6651,"url":"https:\/\/www.sportalsub.net\/blog\/juegos-fedecas-de-actividades-subacuaticas-2010-en-colombia\/","url_meta":{"origin":15378,"position":5},"title":"\ud83c\udde8\ud83c\uddf4 Juegos FEDECAS de Actividades Subacu\u00e1ticas 2010 en Colombia","author":"Sportalsub.net","date":"22 noviembre 2010","format":false,"excerpt":"(Especial Sportalsub.net) La Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas, convoca a sus Ligas Afiliados a la 1ra Edici\u00f3n de los Juegos FEDECAS de Actividades Subacu\u00e1ticas, Campeonatos Nacionales de Apnea, Nataci\u00f3n con Aletas, Hockey Subacu\u00e1tico y Rugby Subacu\u00e1tico, a realizarse en la ciudad de Medell\u00edn, del 2 al 12 de diciembre de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/11\/juegosfedecas2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/11\/juegosfedecas2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/11\/juegosfedecas2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/15378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=15378"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/15378\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/15379"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=15378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=15378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=15378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}