{"id":15917,"date":"2006-03-25T16:00:46","date_gmt":"2006-03-25T20:00:46","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=15917"},"modified":"2019-08-29T20:55:14","modified_gmt":"2019-08-30T00:55:14","slug":"stephane-mifsud-apnea-dinamica-con-aletas-213-mts-con-bialetas","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/stephane-mifsud-apnea-dinamica-con-aletas-213-mts-con-bialetas\/","title":{"rendered":"\ud83c\uddeb\ud83c\uddf7 Stephane Mifsud. Apnea Din\u00e1mica con Aletas: 213 mts con Bialetas"},"content":{"rendered":"<p><a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/rouen10.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-15918\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/rouen10.jpg\" alt=\"rouen10\" width=\"450\" height=\"300\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/rouen10.jpg 450w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/rouen10-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/rouen10-177x118.jpg 177w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<p>(Especial Sportalsub.net &#8211; Marzo 2006 \/ Foto: Fred Buyle)<\/p>\n<div align=\"\\&quot;justify\\&quot;\">\n<div>El apneista franc\u00e9s St\u00e9phane Mifsud realiz\u00f3 un impresionante registro de 213 metros en la modalidad de apnea din\u00e1mica con aletas, en el evento Apne\u00e9Ose 2006 realizado el pasado 11 de Marzo en Rouen, Francia. Lo m\u00e1s destacable de este desempe\u00f1o, es que fu\u00e9 realizado en piscina de 25 metros y con ayuda de bialetas, en lugar de las ya m\u00e1s comunmente utilizadas monoaletas.<\/div>\n<div>\n<p>Esta nueva marca supera en un metro, el actual registro mundial, avalado por la Asociaci\u00f3n Internacional para el Desarrollo de la Apnea AIDA, que se encuentra en 212 metros, en poder del alem\u00e1n Tom Sietas. Por tanto se considera un nuevo r\u00e9cord mundial no oficial, debido a la asuencia de jueces internacionales que avalaran el evento. La competencia fu\u00e9 organizada por la Asociaci\u00f3n Deportiva de la Universidad de Rouen y cont\u00f3 con el aval de la Federaci\u00f3n Francesa de Estudios y Deportes Submarinos FFESSM.<\/p>\n<p>En el evento tambi\u00e9n estuvo presente el apneista venezolano Carlos Coste, quien particip\u00f3 en la competencia a t\u00edtulo de exhibici\u00f3n, realizando una marca de 175 metros en la modalidad de din\u00e1mica con aletas; adem\u00e1s de dictar una conferencia y presentaci\u00f3n de sus r\u00e9cords mundiales en el marco del evento.<\/p>\n<p>Publicado por:<\/p>\n<p><img decoding=\"async\" title=\"miguel\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/05\/miguel-150x150.jpg\" alt=\"\" width=\"100\" \/><\/p>\n<p><strong>Miguel Alberto Cede\u00f1o Ortiz (Venezuela)\u00a0<strong><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/es.fifa.com\/imgml\/flags\/s\/ven.gif\" alt=\"chi Eventos\" width=\"19\" height=\"13\" \/><br \/>\n<\/strong><\/strong>Nacido y residenciado en Caracas, Venezuela es el creador, director y editor de Sportalsub.net. Su experiencia como deportista, entrenador, juez y dirigente de las actividades subacu\u00e1ticas por m\u00e1s de 12 a\u00f1os le han permitido establecer una red de contactos en todo el mundo para dar a conocer e informar todas las novedades sobre el deporte subacu\u00e1tico en habla hispana.<br \/>\n<strong><strong><a href=\"http:\/\/www.facebook.com\/miguelsportsub\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/fb.png\" alt=\"Facebook\" \/><\/a>\u00a0<\/strong><strong><a href=\"http:\/\/www.twitter.com\/miguelsportsub\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/twitter.png\" alt=\"Twitter\" \/><\/a><\/strong><\/strong><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>(Especial Sportalsub.net &#8211; Marzo 2006 \/ Foto: Fred Buyle) El apneista franc\u00e9s St\u00e9phane Mifsud realiz\u00f3 un impresionante registro de 213 metros en la modalidad de apnea din\u00e1mica con aletas, en el evento Apne\u00e9Ose 2006 realizado el pasado 11 de Marzo en Rouen, Francia. Lo m\u00e1s destacable de este desempe\u00f1o, es que fu\u00e9 realizado en piscina de 25 metros y con [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":15918,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,152,50,8],"tags":[],"class_list":["post-15917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-francia","category-records","category-venezuela"],"modified_by":"Sportalsub.net","views":2507,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/08\/rouen10.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-48J","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":2288,"url":"https:\/\/www.sportalsub.net\/blog\/frances-stephane-mifsud-rompe-el-record-mundial-de-apnea-estatica-con-mas-de-11-minutos\/","url_meta":{"origin":15917,"position":0},"title":"\ud83c\uddeb\ud83c\uddf7 Franc\u00e9s Stephane Mifsud rompe el r\u00e9cord mundial de apnea est\u00e1tica con m\u00e1s de 11 minutos","author":"Sportalsub.net","date":"9 junio 2009","format":false,"excerpt":"Este lunes 8 de junio, el apneista franc\u00e9s Stephane Mifsud, implant\u00f3 un nuevo r\u00e9cord mundial de apnea est\u00e1tica, con un impresionante registro de 11 minutos y 35 segundos, superando as\u00ed la marca anterior de 10 minutos y 12 segundos, realizada por el alem\u00e1n Tom Sietas el 6 de junio de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"MIFSUD_21","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/06\/MIFSUD_21.gif?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":30381,"url":"https:\/\/www.sportalsub.net\/blog\/estos-son-los-records-mundiales-de-apnea-por-disciplina\/","url_meta":{"origin":15917,"position":1},"title":"\ud83c\udf0e Estos son los r\u00e9cords mundiales de apnea por disciplina (AIDA)","author":"Sportalsub.net","date":"29 junio 2026","format":false,"excerpt":"(Sportalsub.net \/ AIDA International) La apnea, buceo libre (o freediving en ingl\u00e9s) tiene varias disciplinas y existen r\u00e9cords establecidos en cada una de ellas. Hoy en d\u00eda, existen un n\u00famero creciente de organizaciones que supervisan la pr\u00e1ctica de apnea y, gracias a ello, tambi\u00e9n surgen diferentes cursos, clases y programas\u2026","rel":"","context":"En \u00abAIDA\u00bb","block_context":{"text":"AIDA","link":"https:\/\/www.sportalsub.net\/blog\/category\/mas\/organizaciones\/aida\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/07\/freediving-records.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/07\/freediving-records.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/07\/freediving-records.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/07\/freediving-records.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1125,"url":"https:\/\/www.sportalsub.net\/blog\/apneista-frances-stephane-mifsud-anuncia-intento-de-record-mundial-de-apnea-estatica\/","url_meta":{"origin":15917,"position":2},"title":"\ud83c\uddeb\ud83c\uddf7 Apneista Franc\u00e9s Stephane Mifsud anuncia intento de r\u00e9cord mundial de apnea est\u00e1tica","author":"Sportalsub.net","date":"16 febrero 2009","format":false,"excerpt":"El apneista Franc\u00e9s Stephane Mifsud ha anunciado un intento de r\u00e9cord mundial en la modalidad de apnea est\u00e1tica para el d\u00eda mundial del oc\u00e9ano (8 de Junio de 2009), durante el cual intentar\u00e1 batir el r\u00e9cord mundial actual, en poder del apneista alem\u00e1n Tom Sietas, el cual se encuentra en\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.wikidive.com\/Photo\/Images\/Mifsud.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":14488,"url":"https:\/\/www.sportalsub.net\/blog\/tom-sietas-nuevo-record-mundial-apnea-dinamica-sin-aletas-180mts\/","url_meta":{"origin":15917,"position":3},"title":"\ud83c\udde9\ud83c\uddea Tom Sietas: Nuevo R\u00e9cord Mundial Apnea Din\u00e1mica sin Aletas: 180mts","author":"Sportalsub.net","date":"5 marzo 2006","format":false,"excerpt":"El apneista alem\u00e1n Tom Sietas implant\u00f3 un nuevo r\u00e9cord mundial de apnea din\u00e1mica sin aletas, al registrar una marca de 180 metros, con un tiempo de 3 min 30 seg en un evento internacional realizado en Tokyo, Jap\u00f3n. El r\u00e9cord fu\u00e9 avalado por jueces de la Asociaci\u00f3n Internacional para el\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/01\/recordtomsinequipo.gif?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/01\/recordtomsinequipo.gif?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/01\/recordtomsinequipo.gif?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/01\/recordtomsinequipo.gif?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/01\/recordtomsinequipo.gif?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/01\/recordtomsinequipo.gif?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":3532,"url":"https:\/\/www.sportalsub.net\/blog\/herbert-nitsch-implanta-3-nuevos-records-mundiales-de-apnea\/","url_meta":{"origin":15917,"position":4},"title":"\ud83c\udde6\ud83c\uddf9 Herbert Nitsch implanta 3 nuevos r\u00e9cords mundiales de apnea","author":"Sportalsub.net","date":"27 diciembre 2009","format":false,"excerpt":"Foto: Frederic Buyle @ VerticalBlue Entre los d\u00edas 7 y 9 de diciembre de 2009, en el Blue Hole de las Islas Bahamas, escenario del Campeonato Mundial de Apnea de Profundidad AIDA 2009, el apneista Austr\u00edaco Herbert Nitsch implant\u00f3 3 nuevos r\u00e9cords mundiales, en las modalidades de Peso Variable (142\u2026","rel":"","context":"En \u00abAIDA\u00bb","block_context":{"text":"AIDA","link":"https:\/\/www.sportalsub.net\/blog\/category\/mas\/organizaciones\/aida\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/nitsch3records.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1721,"url":"https:\/\/www.sportalsub.net\/blog\/competencia-internacional-de-apnea-estatica\/","url_meta":{"origin":15917,"position":5},"title":"\ud83c\uddf2\ud83c\udde8 Competencia Internacional de Apnea Est\u00e1tica","author":"Sportalsub.net","date":"24 julio 2005","format":false,"excerpt":"El\u00a0s\u00e1bado 23 de Julio se realiz\u00f3 en el principado de M\u00f3naco una de las competencias m\u00e1s interesantes de apnea de los \u00faltimos tiempos, denominada el IWC (World Static Apnea Contest), evento que por primera vez reuni\u00f3 a 12 de los mejores exponentes de esta modalidad de la apnea. El grupo\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/155070_10150110939462065_72773737064_7110457_4370243_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/15917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=15917"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/15917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/15918"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=15917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=15917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=15917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}