{"id":19309,"date":"2015-01-19T08:20:55","date_gmt":"2015-01-19T12:50:55","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=19309"},"modified":"2021-01-07T08:06:46","modified_gmt":"2021-01-07T12:06:46","slug":"denes-kanyo-el-hungaro-que-aun-se-mantiene-en-la-elite-de-la-natacion-con-aletas-mundial","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/denes-kanyo","title":{"rendered":"\ud83c\udded\ud83c\uddfa Denes Kanyo, el h\u00fangaro que a\u00fan se mantiene en la \u00e9lite de la nataci\u00f3n con aletas Mundial"},"content":{"rendered":"<p><a href=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/denes-kanyo.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-19310\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/denes-kanyo.jpg\" alt=\"denes-kanyo\" width=\"600\" height=\"268\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/denes-kanyo.jpg 600w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/denes-kanyo-300x134.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/denes-kanyo-364x164.jpg 364w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>(Especial Sportalsub.net)<br \/>\n<a href=\"http:\/\/www.sportalsub.net\/en\/denes-kanyo\/\" target=\"_blank\" rel=\"noopener noreferrer\">Read this article in English<\/a>\u00a0\/\u00a0<strong>\u00a0<\/strong><a href=\"http:\/\/www.sportalsub.net\/en\/denes-kanyo\/2\/\" target=\"_blank\" rel=\"noopener noreferrer\">lvassa el ezt a cikket magyarul<\/a><\/p>\n<p>Denes Kanyo es un nadador con aletas de alto nivel nacido en la ciudad de Szeged, Hungr\u00eda el 26 de agosto de 1976 que a\u00fan a la edad de 38 a\u00f1os se mantiene en el tope del deporte subacu\u00e1tico a nivel Mundial.<\/p>\n<p>Sportalsub.net convers\u00f3 de manera exclusiva con este importante atleta del mundo de la nataci\u00f3n con aletas para conocer m\u00e1s detalles de su vida y trayectoria en el deporte subacu\u00e1tico.<\/p>\n<p>Denes se inici\u00f3 en la nataci\u00f3n con aletas en el a\u00f1o 1984 cuando apenas ten\u00eda 8 a\u00f1os y empez\u00f3 a competir en el a\u00f1o 1987 a la edad de 11.<\/p>\n<p>Luego de casi 30 a\u00f1os de carrera deportiva en la nataci\u00f3n con aletas a\u00fan sigue participando y compitiendo en importantes eventos y campeonatos internacionales con un alto rendimiento siendo uno de los atletas de mayor edad que a\u00fan compite en la categor\u00eda \u00e9lite a nivel mundial en la actualidad.<\/p>\n<p>Ingres\u00f3 a la Selecci\u00f3n Nacional de Hungr\u00eda en el a\u00f1o 1991 y desde ese entonces ha sido una de las grandes figuras de la nataci\u00f3n con aletas de su pa\u00eds, que lo ha llevado a competir en m\u00faltiples Campeonatos Mundiales, Campeonatos Europeos, Juegos Mundiales, adem\u00e1s de las diferentes rondas de la Copa del Mundo logrando acumular un importante n\u00famero de medallas y r\u00e9cords nacionales para su pa\u00eds.<\/p>\n<p>Entre sus m\u00e1s importantes logros se cuentan el haberse titulado Campe\u00f3n Mundial en los 400 metros inmersi\u00f3n en 2011 con r\u00e9cord mundial de 2:42,90 a\u00fan vigente, adem\u00e1s de Campe\u00f3n Mundial en 200 superficie en el 2009, medalla de plata en los World Games 1997, bronce en los World Games 2009 y cuatro veces Campe\u00f3n Europeo entre 1997 y 2003. Logr\u00f3 tambi\u00e9n la medalla de plata en el Campeonato Europeo 2012 en los 400 metros superficie con 2:57,20 y bronce en los 200 metros superficie con 1:21,35.<\/p>\n<p>En sus m\u00e1s recientes participaciones en Campeonatos Internacionales en los \u00faltimos a\u00f1os destaca su actuaci\u00f3n en los World Games de Cali, Colombia en 2013 en donde logr\u00f3 el 4to lugar en los 200 metros superficie (1:22,15) y en tambi\u00e9n en los 400 metros superficie (3:02,77). En el Campeonato Mundial CMAS Games en Kazan, Rusia 2013 gan\u00f3 la medalla de bronce en 400 superficie (2:58,85).<\/p>\n<p>En el a\u00f1o 2014 Denes particip\u00f3 en la 1ra Ronda de la Copa del Mundo en Hungr\u00eda as\u00ed como en el Campeonato Europeo realizado en Lignano, Italia en el mes de agosto en donde logr\u00f3 el 4to lugar en los 1500 metros superficie (12:28,94) el 5to lugar en los 800 metros superficie (6:23,28) y el 6to lugar en 200 metros superficie (1:22,45) marcas que evidencian su alto nivel competitivo en un deporte en donde el promedio de edad de los nadadores con los que compiti\u00f3 no superaba los 23 a\u00f1os.<\/p>\n<p>En este a\u00f1o 2015 Denes seguir\u00e1 compitiendo en los Campeonatos Internacionales, iniciando su participaci\u00f3n en la 2da Ronda de la Copa del Mundo a realizarse en Eger, Hungr\u00eda en el mes de Marzo, as\u00ed como en el Campeonato Mundial a realizarse en Yantai, China en el mes de julio en donde integrar\u00e1 nuevamente el equipo nacional h\u00fangaro, luego de haber clasificado tras realizar una marca de 6:28 en los 800 metros superficie en el mes de noviembre de 2014.<\/p>\n<p>Adem\u00e1s de su faceta como deportista de alto rendimiento, Denes Kanyo ha sido su propio entrenador desde 2005 y tambi\u00e9n se ha desempe\u00f1ado como entrenador de otros atletas, habiendo clasificado actualmente a 7 de sus deportistas al equipo nacional de Hungr\u00eda en este a\u00f1o 2015.<\/p>\n<p>Denes ha competido durante toda su carrera deportiva con el club Murena Szeged <a href=\"http:\/\/www.szbk.eu\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">www.szbk.eu<\/a> un club con 47 a\u00f1os de historia que form\u00f3 parte de la Armada de Hungr\u00eda desde 1968 hasta 1991 y que luego se constituy\u00f3 como un club deportivo regular.<\/p>\n<p>As\u00ed mismo, Denes es fundador de la marca MurenaFin <a href=\"http:\/\/www.murenafin.com\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">www.murenafin.com<\/a> que desarrolla tambi\u00e9n bialetas y equipos para la pr\u00e1ctica de la nataci\u00f3n con aletas, el nombre de la marca viene de su club.<\/p>\n<blockquote><p>\u201cEspero que m\u00e1s y m\u00e1s gente escoja este deporte y tener m\u00e1s participantes en las competiciones. Espero que mi salud me permita poder disfrutar del entrenamiento y competiciones de nataci\u00f3n con aletas por \u00a0mucho tiempo m\u00e1s y poder seguir practicando el deporte tambi\u00e9n por mi salud\u201d\u00a0<em> &#8211; <\/em>Denes Kanyo<\/p><\/blockquote>\n<p>No cabe duda de que Denes Kanyo ha sido uno de los m\u00e1s importantes promotores e impulsores del deporte de su pa\u00eds y ejemplo para las nuevas generaciones de nataci\u00f3n con aletas no s\u00f3lo de Hungr\u00eda sino de todo el mundo que ven en \u00e9l un ejemplo de constancia y dedicaci\u00f3n a toda una vida en la nataci\u00f3n con aletas como un verdadero \u00abSer Subacu\u00e1tico\u00bb<\/p>\n<p>Denes Kanyo en Facebook: <a href=\"https:\/\/www.facebook.com\/denes.kanyo\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/www.facebook.com\/denes.kanyo<\/a><\/p>\n<p><a href=\"https:\/\/www.sportalsub.net\/blog\/?s=denes+kanyo\" target=\"_blank\" rel=\"noopener noreferrer\">M\u00e1s noticias de Denes Kanyo en Sportalsub<\/a><\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-19309 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-19313\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo1-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo1-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-19313'>\n\t\t\t\tFoto:  Ronila\u010dki klub Bosna\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-19314\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo2-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo2-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-19314'>\n\t\t\t\tFoto:  Ronila\u010dki klub Bosna\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo2-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-19315\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo2-1-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo2-1-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-19315'>\n\t\t\t\tFoto:  Ronila\u010dki klub Bosna\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-19316\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo3-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo3-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-19316'>\n\t\t\t\tFoto:  Ronila\u010dki klub Bosna\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo4-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-19317\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo4-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo4-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-19317'>\n\t\t\t\tPhoto:  Ronila\u010dki klub Bosna\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo5-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-19318\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo5-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo5-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-19318'>\n\t\t\t\tFoto: Alexander Zolotov\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo6-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-19319\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo6-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo6-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-19319'>\n\t\t\t\tFoto: Oleg Pudov\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo7-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-19320\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo7-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo7-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-19320'>\n\t\t\t\tFoto: Oleg Pudov\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo8-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-1-19321\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo8-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/deneskanyo8-65x65.jpg 65w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-19321'>\n\t\t\t\tFoto: Zoltan Vas\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>Publicado por:<\/p>\n<p><img decoding=\"async\" title=\"miguel\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/05\/miguel-150x150.jpg\" alt=\"\" width=\"80\" \/><\/p>\n<p><strong>Miguel A. Cede\u00f1o O. (miguelsportsub) de \u00a0Venezuela<strong><br \/>\n<\/strong><\/strong>Nacido y residenciado en Caracas, Venezuela es el creador, director y editor de Sportsub &amp; Sportalsub.net. Su experiencia como deportista, entrenador, juez y dirigente de las actividades subacu\u00e1ticas le han permitido establecer una red de contactos en todo el mundo para dar a conocer e informar todas las novedades sobre el deporte subacu\u00e1tico en habla hispana.<br \/>\n<strong><a href=\"http:\/\/www.facebook.com\/miguelsportsub\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/fb.png\" alt=\"Facebook\" \/>\/miguelsportsub<\/a>\u00a0<a href=\"http:\/\/www.twitter.com\/miguelsportsub\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/12\/twitter.png\" alt=\"Twitter\" \/>\u00a0@miguelsportsub<\/a><br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">PUBLICIDAD<br \/>\n<a href=\"http:\/\/www.murenafin.com\/index_eng.html\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img decoding=\"async\" title=\"MurenaFins\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/03\/murenafin2013.jpg\" alt=\"\" border=\"0\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Especial Sportalsub.net) Read this article in English\u00a0\/\u00a0\u00a0lvassa el ezt a cikket magyarul Denes Kanyo es un nadador con aletas de alto nivel nacido en la ciudad de Szeged, Hungr\u00eda el 26 de agosto de 1976 que a\u00fan a la edad de 38 a\u00f1os se mantiene en el tope del deporte subacu\u00e1tico a nivel Mundial. Sportalsub.net convers\u00f3 de manera exclusiva con [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":19310,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Denes Kanyo, el h\u00fangaro que a\u00fan se mantiene en la \u00e9lite de la nataci\u00f3n con aletas Mundial http:\/\/wp.me\/pf9lN-51r","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[257,347,153,231,12],"tags":[],"class_list":["post-19309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-editoriales-miguel-cedeno","category-destacados","category-entrevistas","category-hungria","category-natacion-con-aletas"],"modified_by":"Sportalsub.net","views":4469,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-51r","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":43804,"url":"https:\/\/www.sportalsub.net\/blog\/denes-kanyo-nominado-a-mejor-atleta-de-todos-los-tiempos-de-los-world-games\/","url_meta":{"origin":19309,"position":0},"title":"\ud83c\udded\ud83c\uddfa Denes Kanyo nominado a Mejor Atleta de todos los tiempos de los World Games","author":"Sportalsub.net","date":"8 enero 2021","format":false,"excerpt":"(Sportalsub.net \/ The World Games) - Read in English La Asociaci\u00f3n Internacional de los Juegos Mundiales (IWGA) ha nominado este mes de enero 2021, al Nadador con Aletas Denes Kanyo de Hungr\u00eda como candidato al Mejor Atleta de todos los tiempos de los World Games, votaci\u00f3n que se llevar\u00e1 a\u2026","rel":"","context":"En \u00abHungr\u00eda\u00bb","block_context":{"text":"Hungr\u00eda","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/hungria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/deneskanyowg2021.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/deneskanyowg2021.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/deneskanyowg2021.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/deneskanyowg2021.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15056,"url":"https:\/\/www.sportalsub.net\/blog\/material-deportivo-murena-rubber-fin-la-nueva-dimension-en-el-agua\/","url_meta":{"origin":19309,"position":1},"title":"\ud83c\udded\ud83c\uddfa Material Deportivo: Murena Rubber Fin, la nueva dimensi\u00f3n en el agua","author":"Sportalsub.net","date":"5 noviembre 2024","format":false,"excerpt":"(Especial Sportalsub.net \/Murena Fin) - Read in English Las bialetas de goma Murena, dise\u00f1adas por el m\u00faltiple Campe\u00f3n Mundial de Nataci\u00f3n con aletas, Denes Kanyo de Hungr\u00eda, son una excelente opci\u00f3n para la pr\u00e1ctica, entrenamientos y competencias de actividades subacu\u00e1ticas. Su creador nos explica las ventajas y diversos usos que\u2026","rel":"","context":"En \u00abHockey Subacu\u00e1tico\u00bb","block_context":{"text":"Hockey Subacu\u00e1tico","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/hockey-subacuatico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/murena2021.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/murena2021.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/murena2021.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/murena2021.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":45720,"url":"https:\/\/www.sportalsub.net\/blog\/rusia-hungria-y-grecia-dominaron-en-el-mundial-juvenil-de-natacion-con-aletas-cmas-2021-en-italia\/","url_meta":{"origin":19309,"position":2},"title":"\ud83c\uddf7\ud83c\uddfa Rusia, \ud83c\udded\ud83c\uddfa Hungr\u00eda y \ud83c\uddec\ud83c\uddf7 Grecia dominaron en el Mundial Juvenil de Nataci\u00f3n con Aletas CMAS 2021 en Italia \ud83c\uddee\ud83c\uddf9","author":"Sportalsub.net","date":"20 junio 2021","format":false,"excerpt":"(Especial Sportalsub.net \/ Miguel A. Cede\u00f1o O.) - Read in English Con la participaci\u00f3n de 21 pa\u00edses de 4 continentes: Alemania, Austria, B\u00e9lgica, Colombia, Corea del Sur, Croacia, Egipto, Eslovaquia, Espa\u00f1a, Estonia, Francia, Grecia, Hungr\u00eda, Italia, Jordania, Lituania, Polonia, Rep\u00fablica Checa, Rusia, Turqu\u00eda y Ucrania; se llev\u00f3 a cabo la\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/06\/teamrussia2021.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/06\/teamrussia2021.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/06\/teamrussia2021.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/06\/teamrussia2021.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":25835,"url":"https:\/\/www.sportalsub.net\/blog\/chile-tendra-participacion-en-copa-del-mundo-de-nado-con-aletas-en-hungria\/","url_meta":{"origin":19309,"position":3},"title":"\ud83c\udde8\ud83c\uddf1 Chile tendr\u00e1 participaci\u00f3n en Copa del Mundo de Nado con Aletas en Hungr\u00eda","author":"Sportalsub.net","date":"21 febrero 2017","format":false,"excerpt":"(Sportalsub.net \/ FEDESUB) La Federaci\u00f3n Deportiva Nacional de Actividades Subacu\u00e1ticas y Salvamento Acu\u00e1tico de Chile FEDESUB agradece al Comit\u00e9 Ol\u00edmpico de Chile y Team Chile por el apoyo y financiamiento para la participaci\u00f3n de la deportista Javiera Charrie en la 1ra Ronda de la Copa del Mundo de Nado con\u2026","rel":"","context":"En \u00abChile\u00bb","block_context":{"text":"Chile","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/chile\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/javierachile.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/javierachile.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/javierachile.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/javierachile.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/javierachile.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/javierachile.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":27236,"url":"https:\/\/www.sportalsub.net\/blog\/copa-mundo-cmas-nadosub-2018-usa","url_meta":{"origin":19309,"position":4},"title":"\ud83c\uddfa\ud83c\uddf8 Resultados Finales &#8211; XIII Copa Mundo CMAS Nataci\u00f3n Con Aletas 2018. 4ta Ronda \u2013 Coral Springs, USA","author":"Sportalsub.net","date":"15 mayo 2018","format":false,"excerpt":"(Sportalsub.net \/ CMAS) - Read in English Finaliza con todo \u00e9xito la Copa Mundo de Nataci\u00f3n con Aletas en Coral Springs, Florida. Con una excelente participaci\u00f3n, organizaci\u00f3n y nivel deportivo se realizaron las 4 sesiones de competencia de la 4ta Ronda de la Copa Mundo CMAS 2018 de Nataci\u00f3n con\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/coralspringsfinal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/coralspringsfinal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/coralspringsfinal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/coralspringsfinal.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":14554,"url":"https:\/\/www.sportalsub.net\/blog\/colombia-se-prepara-para-recibir-los-world-games-2013-en-cali-natacion-con-aletas-sera-deporte-estelar\/","url_meta":{"origin":19309,"position":5},"title":"\ud83c\udde8\ud83c\uddf4 Colombia se prepara para recibir los World Games 2013 en Cali. Nataci\u00f3n con Aletas ser\u00e1 deporte estelar","author":"Sportalsub.net","date":"22 enero 2013","format":false,"excerpt":"(Especial Sportalsub.net) Nuevamente, como cada 4 a\u00f1os, la \u00e9lite de la nataci\u00f3n con aletas tendr\u00e1 su m\u00e1xima cita deportiva en la 9na edici\u00f3n de los Juegos Mundiales (World Games), a realizarse en esta ocasi\u00f3n en la ciudad de Cali, Colombia entre el 25 de julio el 4 de agosto 2013.\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/01\/world-games2013.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/01\/world-games2013.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/01\/world-games2013.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/01\/denes-kanyo.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/19309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=19309"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/19309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/19310"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=19309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=19309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=19309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}