{"id":21990,"date":"2015-09-08T15:23:46","date_gmt":"2015-09-08T19:53:46","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=21990"},"modified":"2019-08-30T20:28:52","modified_gmt":"2019-08-31T00:28:52","slug":"taller-de-seguridad-en-la-pesca-submarina-en-caracas-venezuela","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/taller-seguridad-pescasub","title":{"rendered":"\ud83c\uddfb\ud83c\uddea Taller de seguridad en la Pesca Submarina en Caracas, Venezuela"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-21995\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/09\/taller-caciqueros-pescasub.jpg\" alt=\"taller-caciqueros-pescasub\" width=\"480\" height=\"478\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/09\/taller-caciqueros-pescasub.jpg 480w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/09\/taller-caciqueros-pescasub-150x150.jpg 150w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/09\/taller-caciqueros-pescasub-300x300.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/09\/taller-caciqueros-pescasub-65x65.jpg 65w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/p>\n<p>(Sportalsub.net \/ Caciqueros Pescasub)<\/p>\n<p>El Club Caciqueros Pescasub invita al Taller de Seguridad en la Pesca \u00a0Submarina, a realizarse el 20 de septiembre en Caracas, Venezuela.<\/p>\n<p>El taller ser\u00e1 dictado por Antonio del Duca e incluir\u00e1 temas como:<\/p>\n<ul>\n<li>T\u00e9cnicas avanzadas de respiraci\u00f3n y relajaci\u00f3n<\/li>\n<li>Fisiolog\u00eda de la apnea<\/li>\n<li>Primeros auxilios<\/li>\n<\/ul>\n<p>M\u00e1s informaci\u00f3n:<br \/>\nemail:\u00a0<a href=\"mailto:caciquerospescasub@gmail.com\">caciquerospescasub@gmail.com<\/a>\u00a0\/ Facebook <a href=\"https:\/\/www.facebook.com\/casiqueros.pescasub\">Caciqueros Pescasub<br \/>\n<\/a>Telf:\u00a00414-3266818<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ Caciqueros Pescasub) El Club Caciqueros Pescasub invita al Taller de Seguridad en la Pesca \u00a0Submarina, a realizarse el 20 de septiembre en Caracas, Venezuela. El taller ser\u00e1 dictado por Antonio del Duca e incluir\u00e1 temas como: T\u00e9cnicas avanzadas de respiraci\u00f3n y relajaci\u00f3n Fisiolog\u00eda de la apnea Primeros auxilios M\u00e1s informaci\u00f3n: email:\u00a0caciquerospescasub@gmail.com\u00a0\/ Facebook Caciqueros Pescasub Telf:\u00a00414-3266818 &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":21991,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[112,18,8],"tags":[],"class_list":["post-21990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-y-talleres","category-pesca-submarina","category-venezuela"],"modified_by":"Sportalsub.net","views":4604,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-5IG","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":23588,"url":"https:\/\/www.sportalsub.net\/blog\/curso-tres-en-uno-pescasub-apnea-monitor-venezuela","url_meta":{"origin":21990,"position":0},"title":"\ud83c\uddfb\ud83c\uddea Realizado con \u00e9xito Curso Tres en Uno: Pesca Submarina, Apnea y Monitor en Venezuela","author":"Sportalsub.net","date":"4 mayo 2016","format":false,"excerpt":"(Sportalsub.net \/ Caciqueros \/ Aletas de Miranda) Los dias 21, 22 , 23, 24 , 30 abril y 1 de mayo se llev\u00f3 a cabo el curso 3 en uno 1 ofrecido por Los Clubes de\u00a0Actividades Subacu\u00e1ticas\u00a0Caciqueros y Aletas de Miranda\u00a0(Aliados de Sportsub & Sportalsub.net), en las modalidades de\u00a0Apnea estrella\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/04\/curso6.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/04\/curso6.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/04\/curso6.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/04\/curso6.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24408,"url":"https:\/\/www.sportalsub.net\/blog\/1er-taller-de-iniciacion-a-las-actividades-subacuaticas-2016-en-caracas-venezuela\/","url_meta":{"origin":21990,"position":1},"title":"\ud83c\uddfb\ud83c\uddea Realizado con \u00e9xito 1er Taller de Iniciaci\u00f3n a las Actividades Subacu\u00e1ticas 2016 en Caracas, Venezuela","author":"Sportalsub.net","date":"20 junio 2016","format":false,"excerpt":"(Sportalsub.net \/ Pescaloapulmon) Con el fin de \u00a0seguir apoyando al fortalecimiento y reimpulso de la Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas, se di\u00f3\u00a0inicio \u00a0a los talleres \u00a0de iniciaci\u00f3n las actividades subacu\u00e1ticas a nivel nacional en Venezuela. Este 1er Taller de 2016, actividad organizada por Pescaloapulmon y el Club de Actividades Subacu\u00e1ticas\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/taller2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/taller2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/taller2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/taller2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":23240,"url":"https:\/\/www.sportalsub.net\/blog\/1er-curso-monitores-entrenadores-2016-sportsub-nadosub-venezuela","url_meta":{"origin":21990,"position":2},"title":"\ud83c\uddfb\ud83c\uddea Realizado con \u00e9xito 1er Curso 2016 de Monitores y Entrenadores de Nataci\u00f3n con Aletas Nivel 1 Sportsub en Venezuela","author":"Sportalsub.net","date":"23 febrero 2016","format":false,"excerpt":"(Sportsub & Sportalsub \/ Club Caciqueros \/ CASA-UCV \/ Aletas de Miranda) Sportsub & Sportalsub.net conjuntamente con el\u00a0Club Caciqueros de Actividades Subacu\u00e1ticas,\u00a0el Centro de Actividades Subacu\u00e1ticas de la Universidad Central de Venezuela (CASA-UCV)\u00a0y el Club Escuela de Iniciaci\u00f3n Deportiva Aletas\u00a0de Miranda organizaron y realizaron el 1er Curso 2016 de Monitores\u2026","rel":"","context":"En \u00abArt\u00edculos por Miguel Cede\u00f1o @miguelsportsub\u00bb","block_context":{"text":"Art\u00edculos por Miguel Cede\u00f1o @miguelsportsub","link":"https:\/\/www.sportalsub.net\/blog\/category\/mas\/editoriales-miguel-cedeno\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/cursonotafinal.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/cursonotafinal.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/cursonotafinal.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/cursonotafinal.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":76840,"url":"https:\/\/www.sportalsub.net\/blog\/3ra-pescasub-fvas-venezuela-2024","url_meta":{"origin":21990,"position":3},"title":"\ud83c\uddfb\ud83c\uddea Resultados \u2013 3ra V\u00e1lida Nacional y Campeonato Nacional Pesca Submarina FVAS 2024 \u2013 Miranda, Venezuela","author":"Sportalsub.net","date":"9 noviembre 2024","format":false,"excerpt":"(Sportalsub.net \/ FVAS) La Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas (FVAS) conjuntamente con la Organizaci\u00f3n Pescaloapulm\u00f3n, organizaron la 3ra V\u00e1lida Nacional de Pesca Submarina 2024 \u00a8COPA DAEX\u00a8 efectuada los d\u00edas 1, 2 y 3 de noviembre 2024 en el Pueblo de Chirimena, Edo. Miranda. \u00a0RESULTADOS OFICIALES 3RA V\u00c1LIDA NACIONAL (publicados el\u2026","rel":"","context":"En \u00abPesca Submarina\u00bb","block_context":{"text":"Pesca Submarina","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/pesca-submarina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/11\/3rapescasub2024-portada.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/11\/3rapescasub2024-portada.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/11\/3rapescasub2024-portada.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/11\/3rapescasub2024-portada.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":70441,"url":"https:\/\/www.sportalsub.net\/blog\/1-valida-pescasub-fvas-venezuela-2024","url_meta":{"origin":21990,"position":4},"title":"\ud83c\uddfb\ud83c\uddea Resultados &#8211; 1era V\u00e1lida Nacional de Pesca Submarina FVAS Venezuela 2024, La Guaira","author":"Sportalsub.net","date":"22 abril 2024","format":false,"excerpt":"(Sportalsub.net \/ FVAS) La\u00a01ra V\u00e1lida Nacional de Pesca Submarina\u00a0de la Federaci\u00f3n Venezolana de Actividades Subacuaticas\u00a0\u201cCopa DAEX 2024\u201d se llev\u00f3 a cabo el s\u00e1bado 20 de abril 2024 en Chichiriviche de la Costa, Estado La Guaira. El evento ser\u00e1 organizado por\u00a0P\u00e9scalo a Pulm\u00f3n. \u00a0RESULTADOS\u00a0(publicados el 28 de abril 2024) \u00a0CONVOCATORIA OFICIAL\u00a0(actualizada\u2026","rel":"","context":"En \u00abPesca Submarina\u00bb","block_context":{"text":"Pesca Submarina","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/pesca-submarina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/03\/1erpescasubfvas2024-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/03\/1erpescasubfvas2024-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/03\/1erpescasubfvas2024-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/03\/1erpescasubfvas2024-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":19198,"url":"https:\/\/www.sportalsub.net\/blog\/pescasub-huanchaco-2014","url_meta":{"origin":21990,"position":5},"title":"\ud83c\udde8\ud83c\uddf1 Chile conquista el oro en la Pesca Submarina de los II Juegos Bolivarianos de Playa Huanchaco Per\u00fa 2014","author":"Sportalsub.net","date":"11 diciembre 2014","format":false,"excerpt":"(Sportalsub.net \/ II Juegos Bolivarianos de Playa Huanchaco 2014) La Selecci\u00f3n Chilena de Pesca Submarina se llev\u00f3 la medalla de oro en los\u00a0II Juegos Bolivarianos de Playa Huanchaco 2014 en Per\u00fa, luego de dominar en las 2 jornadas de competencia, realizadas este mi\u00e9rcoles 10 y jueves 11 de diciembre en\u2026","rel":"","context":"En \u00abChile\u00bb","block_context":{"text":"Chile","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/chile\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/12\/bolivarianosplaya2014-pescasub.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/12\/bolivarianosplaya2014-pescasub.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/12\/bolivarianosplaya2014-pescasub.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/09\/IMG-20150907-WA0002.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/21990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=21990"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/21990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/21991"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=21990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=21990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=21990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}