{"id":22750,"date":"2015-11-27T22:10:34","date_gmt":"2015-11-28T02:40:34","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=22750"},"modified":"2019-08-30T20:26:51","modified_gmt":"2019-08-31T00:26:51","slug":"video-hellen-gonzalez-y-luis-ramirez-de-venezuela-en-campeonato-panpacific-de-apnea-australia","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/video-luis-hellen-venezuela-australia","title":{"rendered":"\ud83c\uddfb\ud83c\uddea Videos: Hellen Gonzalez y Luis Ramirez de Venezuela en Campeonato PanPacific de Apnea Australia"},"content":{"rendered":"<p><a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/video-luis-hellen2.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-22756\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/video-luis-hellen2.jpg\" alt=\"video-luis-hellen2\" width=\"900\" height=\"626\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/video-luis-hellen2.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/video-luis-hellen2-768x534.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/video-luis-hellen2-300x209.jpg 300w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>Especial Sportalsub.net \/ Brisbane, Australia<\/p>\n<p>Hellen Gonz\u00e1lez, nueva Juez Internacional AIDA y Luis Ramirez env\u00edan un saludo a Venezuela y a Sportalsub.net luego de su participaci\u00f3n en el <a href=\"http:\/\/www.sportalsub.net\/blog\/pan-pacific-freediving-2015\">Campeonato Pan Pacific 2015 realizado en Brisbane, Australia<\/a>.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/lXorb-KYBzM\" width=\"420\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/9rUZZTTO1GE\" width=\"420\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Especial Sportalsub.net \/ Brisbane, Australia Hellen Gonz\u00e1lez, nueva Juez Internacional AIDA y Luis Ramirez env\u00edan un saludo a Venezuela y a Sportalsub.net luego de su participaci\u00f3n en el Campeonato Pan Pacific 2015 realizado en Brisbane, Australia.<\/p>\n","protected":false},"author":1,"featured_media":22756,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,230,153,8],"tags":[400],"class_list":["post-22750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-australia","category-entrevistas","category-venezuela","tag-pan-pacific-2015"],"modified_by":"Sportalsub.net","views":5839,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/video-luis-hellen2.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-5UW","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":22740,"url":"https:\/\/www.sportalsub.net\/blog\/hellen-juez-apnea-aida-internacional","url_meta":{"origin":22750,"position":0},"title":"\ud83c\uddfb\ud83c\uddea Hellen Gonz\u00e1lez de Venezuela nueva Juez Internacional de Apnea AIDA","author":"Sportalsub.net","date":"27 noviembre 2015","format":false,"excerpt":"(Especial Sportalsub.net) La venezolana Hellen Gonz\u00e1lez, co-fundadora en 2014 del movimiento Somos Apnea (con Jhon Dur\u00e1n) ha obtenido su certificaci\u00f3n como Juez Internacional AIDA Nivel E, luego de haber realizado el curso de jueces que se llev\u00f3 a cabo del 22 al 24 de noviembre previo al Campeonato de Apnea\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/hellenjuez1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/hellenjuez1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/hellenjuez1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/hellenjuez1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":22672,"url":"https:\/\/www.sportalsub.net\/blog\/pan-pacific-freediving-2015","url_meta":{"origin":22750,"position":1},"title":"\ud83c\uddfb\ud83c\uddea Luis Ramirez de Venezuela en Campeonato de Apnea PanPacifico 2015 Australia + Resultados y Fotos","author":"Sportalsub.net","date":"28 noviembre 2015","format":false,"excerpt":"Sportalsub.net \/\u00a0Read in English El\u00a0Campeonato de Apnea Pan Pac\u00edfico \"Pan Pacific Championship 2015\" se realiz\u00f3 del 25 al 28 de noviembre en Brisbane, Australia. Evento organizado por la Asociaci\u00f3n de Apnea de Australia con el aval de la Asociaci\u00f3n Internacional para el Desarrollo de la Apnea (AIDA) en las modalidades\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/australia41.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/australia41.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/australia41.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/australia41.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/australia41.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/australia41.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":25996,"url":"https:\/\/www.sportalsub.net\/blog\/venezuela-presente-en-campeonato-nacional-de-apnea-2017-en-australia\/","url_meta":{"origin":22750,"position":2},"title":"\ud83c\uddfb\ud83c\uddea Venezuela estuvo presente en Campeonato Nacional de Apnea en piscina 2017 en Australia","author":"Sportalsub.net","date":"5 mayo 2017","format":false,"excerpt":"(Especial Sportalsub.net \/ Hellen Gonzalez) El fin de semana del 29 de abril al 1 de mayo, Venezuela estuvo\u00a0presente en el Campeonato Nacional de Freediving en Australia realizado en Brisbane, con la representaci\u00f3n de 2 atletas venezolanos en competencia Luis Eduardo Ramirez Fernandez y Jes\u00fas Montilla y dos m\u00e1s (Hellen\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/04\/luisramirez1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/04\/luisramirez1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/04\/luisramirez1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/04\/luisramirez1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24145,"url":"https:\/\/www.sportalsub.net\/blog\/luis-ramirez-campeonatos-nacionales-de-apnea-en-piscina-2016-en-australia\/","url_meta":{"origin":22750,"position":3},"title":"\ud83c\uddfb\ud83c\uddea Luis Ramirez de Venezuela destaca en Campeonatos Nacionales de Apnea en piscina 2016 en Australia","author":"Sportalsub.net","date":"11 mayo 2016","format":false,"excerpt":"(Especial Sportalsub.net) - English Version El apneista venezolano Luis Eduardo Ramirez Fernandez\u00a0compiti\u00f3 el pasado fin de semana 6, 7 y 8 de mayo en la ciudad de Sidney, en el \u00a0Campeonato Nacional de Apnea en Piscina de la Asociaci\u00f3n Australiana de Apnea (AFA)\u00a0en donde se ubic\u00f3 en el 4to lugar\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/luis-estatica-feat2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/luis-estatica-feat2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/luis-estatica-feat2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/luis-estatica-feat2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/luis-estatica-feat2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":22896,"url":"https:\/\/www.sportalsub.net\/blog\/pan-pacific-uwrugby-australia-2016","url_meta":{"origin":22750,"position":4},"title":"\ud83c\udde6\ud83c\uddfa Resultados Copa Pan Pac\u00edfico 2016 de Rugby Subacu\u00e1tico en Australia","author":"Sportalsub.net","date":"1 junio 2016","format":false,"excerpt":"(Sportalsub.net \/ PanPacific Cup 2016) - Read in English GAULS, en colaboraci\u00f3n con UNIDIVE y AUF organizaron la Pan Pacific Cup 2016 de Rugby subacu\u00e1tico, torneo que se realiz\u00f3 en Brisbane, Australia del 27 al 30 de mayo de 2016. El torneo fue\u00a0abierto para todos los clubes y equipos nacionales\u2026","rel":"","context":"En \u00abAustralia\u00bb","block_context":{"text":"Australia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/oceania\/australia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/panpacificresults.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/panpacificresults.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/panpacificresults.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/panpacificresults.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":20408,"url":"https:\/\/www.sportalsub.net\/blog\/campeonato-australia-panpacific-2015-rugby-subacuatico","url_meta":{"origin":22750,"position":5},"title":"\ud83c\udde6\ud83c\uddfa Campeonato Nacional de Australia y PanPacific Cup 2015 de Rugby Subacu\u00e1tico","author":"Sportalsub.net","date":"6 abril 2015","format":false,"excerpt":"(Sportalsub.net \/ Underwater Rugby Australia) - Read in English El 4 \u00a0y 5 de abril de 2015 se realiz\u00f3\u00a0en Brisbane\u00a0el Campeonato Nacional de Australia y la PanPacific Cup de Rugby Subacu\u00e1tico Todos los equipos de Australia participaron en el Campeonato Nacional. UWR UNSW de\u00a0Sidney se titul\u00f3 Campe\u00f3n del Torneo por\u2026","rel":"","context":"En \u00abAustralia\u00bb","block_context":{"text":"Australia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/oceania\/australia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/04\/ppc.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/04\/ppc.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/04\/ppc.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/04\/ppc.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/22750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=22750"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/22750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/22756"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=22750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=22750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=22750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}