{"id":23494,"date":"2016-02-26T13:37:25","date_gmt":"2016-02-26T18:07:25","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=23494"},"modified":"2021-01-09T11:46:40","modified_gmt":"2021-01-09T15:46:40","slug":"buceo-profesional-y-buceo-comercial-por-jorge-barbosa","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/buceo-profesional-buceo-comercial-jorge-barbosa","title":{"rendered":"\ud83c\uddfb\ud83c\uddea Buceo Profesional y Buceo Comercial, por Jorge Barbosa"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-23497\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceo-jorgebarbosa.jpg\" alt=\"buceo-jorgebarbosa\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceo-jorgebarbosa.jpg 960w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceo-jorgebarbosa-300x225.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceo-jorgebarbosa-768x576.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceo-jorgebarbosa-320x240.jpg 320w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><br \/>\nFoto de Joxmer Scott de Biosub. En la foto Daglis chac\u00f3n y\u00a0Jorge Barbosa<\/p>\n<p>(Sportalsub.net \/ Jorge Barbosa)<\/p>\n<p>Mi nombre, Jorge Barbosa, Instructor de buceo SNSI 23686 de la escuela Chichidive, en Chichiriviche de la Costa, Estado Vargas. En esta oportunidad escribiendo sobre el Buceo Comercial y el Buceo T\u00e9cnico.<\/p>\n<p>Mi inicio en las actividades subacu\u00e1ticas empez\u00f3 a muy temprana edad, queriendo competir a ver qui\u00e9n aguantaba m\u00e1s la respiraci\u00f3n bajo el agua o buscando la moneda lanzada al fondo de una piscina que frecuentaba, emp\u00edricamente un inicio totalmente recreativo y de alguna manera competitivo. Cuando por fin cumpl\u00ed la edad para iniciar seriamente mi formaci\u00f3n como buzo, empiezan a presentarse para m\u00ed, oportunidades a participar en diferentes tipos de inmersiones, principalmente con fines cient\u00edficos, deportivos, recreativos y un par de veces, durante aquellos a\u00f1os, me llamaron a participar en alguna inspecci\u00f3n o limpieza del casco de embarcaciones.<\/p>\n<p>El submarinismo, o buceo, es una actividad que ha cautivado al hombre desde siempre. Como lo indican los hallazgos arqueol\u00f3gicos que datan de alrededor del a\u00f1o 4.500 A.C. en Egipto y Asia Menor.<\/p>\n<p>Si bien, en la historia, inicialmente el buceo se empleaba para la extracci\u00f3n de recursos con inter\u00e9s comercial y suntuario, ya para el siglo VII A.C. encontramos relieves del\u00a0 Rey de Asiria Assurbanipal disfrutando bajo el agua de una inmersi\u00f3n recreativa usando una especie de saco respirador con una boquilla.<\/p>\n<p>Tambi\u00e9n fue usado el buceo con fines guerreristas, y es el Griego Tuc\u00eddides qui\u00e9n en el 460 A.C. nos cuenta historias de buzos que despejaban de obst\u00e1culos el fondo marino para permitir el paso de naves durante su \u201cHistoria de la Guerra del Peloponeso\u201d.<\/p>\n<p>Esta breve proleg\u00f3meno pretende hacernos una idea general de los diferentes tipos de buceo que existen; hoy nos centraremos diferenciando el Buceo Comercial del Buceo Profesional.<\/p>\n<p>Para esto es importante deshilar un poco el concepto que tenemos del buceo y observar desde un punto de vista finalista, el objetivo de cada inmersi\u00f3n, para as\u00ed, poder clasificarlo. Tambi\u00e9n mencionaremos, la clasificaci\u00f3n de los buzos seg\u00fan las principales agencias de buceo. Finalmente concluiremos estableciendo las caracter\u00edsticas del buceo profesional y del comercial.<\/p>\n<h2>DEFINICIONES<\/h2>\n<h3>****Buceo = Cualquier Actividad bajo el agua****<\/h3>\n<p>Muy bien, vamos a empezar definiendo submarinismo, tambi\u00e9n llamado buceo o escafandrismo \u2013 este \u00faltimo t\u00e9rmino es muy poco usado \u2013 son todo el conjunto de actividades que se realizan bajo la superficie del mar. El concepto se ampl\u00eda al denominarse actualmente Actividades Subacu\u00e1ticas, debido a que estas actividades pueden realizarse en piscinas, lagos, r\u00edos y otros cuerpos de agua dulce diferentes al mar.<\/p>\n<p>Estas actividades bajo el agua pueden ser:<\/p>\n<h3>****Buceo Recreativo = Diversi\u00f3n bajo el Agua ****<\/h3>\n<p>Buceo Recreativo: Son los buceos a pulm\u00f3n o con equipo SCUBA (del ingl\u00e9s Self-Contained Underwater Breathing Apparatus), con la finalidad de ofrecer al buzo el disfrute de la actividad que realice bajo el agua. Siempre regidos por los est\u00e1ndares de la WRSTC (sigl\u00e1s en Ingles del Consejo Mundial para el Entrenamiento del Buceo Recreativo).<\/p>\n<h3>****Buceo Deportivo = Deporte bajo el Agua ****<\/h3>\n<p>Buceo Deportivo: Son las inmersiones a pulm\u00f3n o con equipo Scuba, en donde se prueba en competici\u00f3n o no de las habilidades y destrezas adquiridas durante un entrenamiento.<\/p>\n<h3>****Buceo Cient\u00edfico = Investigaci\u00f3n bajo el Agua ****<\/h3>\n<p>Buceo Cient\u00edfico: es el que se utiliza el submarinismo como herramienta de investigaci\u00f3n cient\u00edfica, principalmente en \u00e1reas como la Biolog\u00eda, Oceanograf\u00eda, Geolog\u00eda, Qu\u00edmica, F\u00edsica o cualquier otra de las denominadas Ciencias de la Tierra.<\/p>\n<h3>****Buceo Militar = Actividades Castrenses bajo el Agua****<\/h3>\n<p>Buceo Militar: es realizado por personal entrenado en artes y ciencias militares, en donde tambi\u00e9n se usan los conocimientos del buceo para sus inmersiones. Es curioso que \u2013 por lo menos en Venezuela &#8211; son muy pocos los buzos que despu\u00e9s de recibir entrenamiento de buceo militar, disfruten del buceo recreativo.<\/p>\n<h3>****Buceo T\u00e9cnico = Buceo por contrato o buceos m\u00e1s all\u00e1 de los l\u00edmites****<\/h3>\n<p>Buceo T\u00e9cnico: se le llama a cualquier buceo en donde se recicle el aire, se use mezcla de gases, se realice a profundidades o tiempos que excedan los l\u00edmites de no descompresi\u00f3n, en fin, es un buceo que requiere mayor preparaci\u00f3n especial te\u00f3rica y pr\u00e1ctica. Normalmente este tipo de buceo es empleado con fines comerciales, es en la mayor\u00eda de los casos, un buceo remunerado en el que se realizan trabajos de inspecci\u00f3n, ingenier\u00eda civil, buceos para el sector petrolero y gas\u00edfero, reparaciones y mantenimiento de embarcaciones, de presas y otras obras hidr\u00e1ulicas, y cualquier otra actividad que requiera equipo y entrenamiento especial.<\/p>\n<div id=\"attachment_23498\" style=\"width: 490px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-23498\" class=\"size-full wp-image-23498\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceotecnico.jpg\" alt=\"Buceo T\u00e9cnico. Foto: Hetulio Mendoza\" width=\"480\" height=\"269\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceotecnico.jpg 480w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceotecnico-300x168.jpg 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><p id=\"caption-attachment-23498\" class=\"wp-caption-text\">Buceo T\u00e9cnico. Foto: Hetulio Mendoza<\/p><\/div>\n<h3>****Espeleobuceo = Buceo t\u00e9cnico + Espeleolog\u00eda ****<\/h3>\n<p>Espeleobuceo: Es un tipo de inmersi\u00f3n que combina el buceo t\u00e9cnico con la espeleolog\u00eda, bien sea en cavernas subacu\u00e1ticas o en aquellas cuevas cegadas en sifones, cuya exploraci\u00f3n requiera, buceo, equipo especial de buceo como el Side Mount, muchas veces mezcla de gases, redundar los sistemas de seguridad, mucho equipo especializado y pericia tanto como espele\u00f3logos y como buzos.<\/p>\n<h3>****Buceo Profesional = Buceo de Instrucci\u00f3n****<\/h3>\n<p>Buceo Profesional: Son las inmersiones en las que el buzo ense\u00f1a y prueba los fundamentos te\u00f3ricos y pr\u00e1cticos, las destrezas y habilidades necesarias para que cualquier persona obtenga la certificaci\u00f3n en el nivel y tipo de buceo requerido. Para ello el buzo instructor debe haber cumplido con los requisitos acad\u00e9micos y pr\u00e1cticos que certifican que ha hecho carrera en buceo al haber tomado las especialidades que ahora puede impartir. A este tipo de Buceo se le llama Buceo Profesional.<\/p>\n<div id=\"attachment_23499\" style=\"width: 650px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-23499\" class=\"size-full wp-image-23499\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceoprofesional.jpg\" alt=\"Buceo Profesional\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceoprofesional.jpg 640w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceoprofesional-300x225.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceoprofesional-320x240.jpg 320w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><p id=\"caption-attachment-23499\" class=\"wp-caption-text\">Buceo Profesional<\/p><\/div>\n<h2>CLASIFICACI\u00d3N SEG\u00daN LAS PRINCIPALES AGENCIAS DE SUBMARINISMO<\/h2>\n<p>Hay muchas Agencias que certifican buzos y son reconocidas mundialmente, nosotros vamos a mencionar la clasificaci\u00f3n seg\u00fan algunas de ellas.<\/p>\n<h3>SNSI &#8211; SCUBA &amp; NITROX SAFETY INTERNATIONAL:<\/h3>\n<p>Tiene programas <strong>SNSI REC<\/strong> para buzos Recreativos, <strong>SNSI TEK<\/strong> para que despu\u00e9s de ser buzos recreativos desean ir mas all\u00e1 de los l\u00edmites y, <strong>SNSI PRO<\/strong> para aquellos que ya completaron todos los cursos recreativos y desean hacerse profesionales de buceo.<\/p>\n<h3>PADI \u2013 PROFESSIONAL ASSOCIATIONS OF DIVING INSTRUCTORS:<\/h3>\n<p>Los cursos Padi pueden ser tambi\u00e9n Recreativos, Profesionales y los cursos t\u00e9cnicos llamados PADI TEC\/REC.<\/p>\n<h3>SSI \u2013 SCUBA SCHOOL INTERNATIONAL:<\/h3>\n<p>En esta agencia, los cursos tambi\u00e9n se les llama Recreativos, XR o Extended Range a los cursos T\u00e9cnicos y Profesionales a quienes desean llegar a Divemaster o a Instructor.<\/p>\n<h3>CMAS \u2013 CONFEDERACI\u00d3N MUNDIAL DE ACTIVIDADES SUBACUATICAS:<\/h3>\n<p>Forma buzos con un perfil muy completo, sobre todo a nivel deportivo. Tiene programas recreativos y profesionales. Los cursos t\u00e9cnicos son dictados como especialidades y tienen nombres espec\u00edficos para mezcla de gases o uso de equipo especial.<\/p>\n<p>En resumen la mayor\u00eda de las Agencias de ense\u00f1anza de buceo clasifican sus programas de entrenamiento en Recreativos, T\u00e9cnicos o Profesionales.<\/p>\n<h2>BUCEO PROFESIONAL Y BUCEO COMERCIAL<\/h2>\n<div id=\"attachment_23500\" style=\"width: 408px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-23500\" class=\"size-full wp-image-23500\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceocomercial.jpg\" alt=\"Buceo Comercial. Foto: Hetulio Mendoza\" width=\"398\" height=\"272\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceocomercial.jpg 398w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceocomercial-300x205.jpg 300w\" sizes=\"auto, (max-width: 398px) 100vw, 398px\" \/><p id=\"caption-attachment-23500\" class=\"wp-caption-text\">Buceo Comercial. Foto: Hetulio Mendoza<\/p><\/div>\n<p>Actualmente, es com\u00fan encontrar art\u00edculos en los que se mencione al Buceo T\u00e9cnico Remunerado como Buceo Profesional. En Espa\u00f1a por ejemplo, existe legislaci\u00f3n que regula este tipo de Buceo Remunerado llam\u00e1ndolo Buceo Profesional.<\/p>\n<p>Aunque la tendencia indica que este tipo de buceo debe llamarse Buceo Comercial, el t\u00e9rmino Profesional denota seriedad en la labor que realizan y disipa un poco la idea de que el Buceo Comercial lo realiza una especie de Buzo Mercenario que cobrar\u00e1 por realizar una tarea y deja a un lado la preparaci\u00f3n que este debe tener para llevarla a cabo.<\/p>\n<p>El Buzo Profesional que es como en el mundo del Submarinismo se le conoce a los que forman a todos los submarinistas principiantes o avanzados, incluso hay profesionales que forman los buzos Comerciales o T\u00e9cnicos, no solo han tenido la preparaci\u00f3n para realizar la labor docente como instructores, sino que tambi\u00e9n deben tener la experiencia pr\u00e1ctica del programa que imparten. Por tanto, el profesional del buceo que desea ser instructor de Buceo T\u00e9cnico, debe tener experiencia en esa especialidad que normalmente es remunerada y la llaman buceo Comercial.<\/p>\n<p><em><strong>\u00bfCreen ustedes entonces que el Buceo Comercial y el Buceo Profesional significan lo mismo?. Espero sus comentarios y opiniones.<\/strong><\/em><\/p>\n<p>\u00abEl mar, una vez que te hechiza, te engancha en su maravillosa red para toda la eternidad\u00bb<br \/>\n<b>Jacques Cousteau<\/b><br \/>\n<strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-23496\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/photo.jpg\" alt=\"photo\" width=\"90\" height=\"90\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/photo.jpg 90w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/photo-65x65.jpg 65w\" sizes=\"auto, (max-width: 90px) 100vw, 90px\" \/>Jorge Barbosa<\/strong><br \/>\n<strong><a href=\"https:\/\/www.facebook.com\/jorgesubmarinismo\/?fref=photo\" target=\"_blank\">Facebook<\/a>\u00a0\/ <a href=\"https:\/\/twitter.com\/JorgeChichidive\/\" target=\"_blank\">Twitter<\/a><br \/>\n<a href=\"mailto:jorge.chichidive@gmail.com\">jorge.chichidive<wbr \/>@gmail.com<\/a><br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Foto de Joxmer Scott de Biosub. En la foto Daglis chac\u00f3n y\u00a0Jorge Barbosa (Sportalsub.net \/ Jorge Barbosa) Mi nombre, Jorge Barbosa, Instructor de buceo SNSI 23686 de la escuela Chichidive, en Chichiriviche de la Costa, Estado Vargas. En esta oportunidad escribiendo sobre el Buceo Comercial y el Buceo T\u00e9cnico. Mi inicio en las actividades subacu\u00e1ticas empez\u00f3 a muy temprana edad, [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":23497,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[151,17,16,94,347,8],"tags":[],"class_list":["post-23494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buceo-autonomo","category-buceo-comercial","category-buceo-profesional","category-buceo-tecnico","category-destacados","category-venezuela"],"modified_by":"Sportalsub.net","views":16325,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/02\/buceo-jorgebarbosa.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-66W","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":23292,"url":"https:\/\/www.sportalsub.net\/blog\/curso-buceo-snsi-open-water-diver-venezuela","url_meta":{"origin":23494,"position":0},"title":"\ud83c\uddfb\ud83c\uddea Curso de Buceo SNSI Open Water Diver en Venezuela","author":"Sportalsub.net","date":"27 enero 2016","format":false,"excerpt":"(Sportalsub.net \/ ChichiDive \/ SNSI \/Inst Jorge Barbosa) Sportalsub.net y\u00a0ChichiDive Scuba Center ofrecen el\u00a0Curso de Buceo SNSI Open Water Diver en Venezuela\u00a0con nuestro\u00a0instructor asociado Jorge Barbosa La Escuela ubicada en Chichiriviche de la Costa, Estado Vargas imparte cursos tanto recreativos como\u00a0profesionales. El SNSI Open Water Diver es un curso completo\u2026","rel":"","context":"En \u00abBuceo\u00bb","block_context":{"text":"Buceo","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/01\/cursobuceosnsijorgebarbosa.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/01\/cursobuceosnsijorgebarbosa.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/01\/cursobuceosnsijorgebarbosa.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/01\/cursobuceosnsijorgebarbosa.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":41117,"url":"https:\/\/www.sportalsub.net\/blog\/centro-de-actividades-subacuaticas-biosub-ucv-charlas\/","url_meta":{"origin":23494,"position":1},"title":"\ud83c\uddfb\ud83c\uddea Centro de Actividades Subacu\u00e1ticas BIOSUB UCV de Venezuela lleva a cabo su 1er Ciclo de Charlas 2020","author":"Sportalsub.net","date":"2 julio 2020","format":false,"excerpt":"(Sportalsub.net \/ BIOSUB UCV) El Centro de Actividades Subacu\u00e1ticas BIOSUB de la Facultad de Ciencias de la Universidad Central de Venezuela lleva a cabo un interesante ciclo de charlas on-line relacionadas con el buceo y el ambiente marino. Cronograma: 1. El Buceo como herramienta para la Ciencia y la Conservaci\u00f3n.\u2026","rel":"","context":"En \u00abBuceo\u00bb","block_context":{"text":"Buceo","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/charlas-biosub.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/charlas-biosub.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/charlas-biosub.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/charlas-biosub.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/charlas-biosub.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":43598,"url":"https:\/\/www.sportalsub.net\/blog\/re-encuentro-casa-ucv-2020","url_meta":{"origin":23494,"position":2},"title":"\ud83c\uddfb\ud83c\uddea Centro de Actividades Subacu\u00e1ticas de la Universidad Central de Venezuela organiza Re-Encuentro Virtual Hist\u00f3rico","author":"Sportalsub.net","date":"2 diciembre 2020","format":false,"excerpt":"(Sportalsub.net \/ CASA-UCV) El Centro de Actividades Subacu\u00e1ticas de la Universidad Central de Venezuela (CASA-UCV) luego de invitar a todos los miembros que han formado y forman parte de este club, llev\u00f3 a cabo con todo \u00e9xito el \u00abRe-Encuentro CASA-UCV 2020. M\u00e1s de 45 a\u00f1os de historia subacu\u00e1tica en Venezuela\u2026\u2026","rel":"","context":"En \u00abActividades Subacu\u00e1ticas\u00bb","block_context":{"text":"Actividades Subacu\u00e1ticas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/12\/video-re-encuentro-casaucv2020.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/12\/video-re-encuentro-casaucv2020.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/12\/video-re-encuentro-casaucv2020.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/12\/video-re-encuentro-casaucv2020.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":44141,"url":"https:\/\/www.sportalsub.net\/blog\/nueva-acreditadora-internacional-de-buceo-nace-en-america-latina-pdi-internacional\/","url_meta":{"origin":23494,"position":3},"title":"\ud83c\udf0e Nueva Acreditadora Internacional de Buceo nace en Am\u00e9rica Latina: PDI","author":"Sportalsub.net","date":"8 enero 2021","format":false,"excerpt":"(Sportalsub.net\/ PDI Internacional) La Nueva Acreditadora Internacional de Buceo PDI INTERNACIONAL tiene como objetivo el promover el desarrollo profesional educativo de las actividades subacu\u00e1ticas en Am\u00e9rica Latina. Cu\u00e1les son las caracter\u00edsticas y ventajas de esta nueva acreditadora profesional de buceo que promete. 1. El lenguaje MATERNO espa\u00f1ol 2. Los Planes\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/pdi-international.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/pdi-international.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/pdi-international.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/pdi-international.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3093,"url":"https:\/\/www.sportalsub.net\/blog\/seminario-taller-para-instructores-de-buceo-cmas-en-colombia\/","url_meta":{"origin":23494,"position":4},"title":"\ud83c\udde8\ud83c\uddf4 Seminario Taller para instructores de Buceo CMAS en Colombia","author":"Sportalsub.net","date":"5 noviembre 2009","format":false,"excerpt":"Foto: Ronald Laurens @ Sportalsub.net El curso se realizar\u00e1 en la ciudad de Cali, entre el lunes\u00a023 de noviembre\u00a0y el jueves\u00a02 de diciembre de 2009, el cual ser\u00e1 dictado por el instructor 3 Estrellas espa\u00f1ol Mariano Crespo, vicepresidente de la Federaci\u00f3n Espa\u00f1ola de Actividades Subacu\u00e1ticas y gestor del cambio pedag\u00f3gico\u2026","rel":"","context":"En \u00abBuceo Comercial\u00bb","block_context":{"text":"Buceo Comercial","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/buceo-comercial\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/11\/buceocmascolombia.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":18189,"url":"https:\/\/www.sportalsub.net\/blog\/buceo-atolon-diver","url_meta":{"origin":23494,"position":5},"title":"\ud83c\uddfb\ud83c\uddea Bucea con Atolon Dive. Curso Open Water Diver en Caracas, Venezuela","author":"Sportalsub.net","date":"31 julio 2014","format":false,"excerpt":"(Especial Sportalsub.net \/ AtolonDive) A muchos nos ha intrigado que hay bajo la superficie del agua, una respuesta com\u00fan a esta pregunta es ALGO HERMOSO Y UNICO, paz, armon\u00eda, vida. Cada buzo inicia por motivos diferentes en la actividad, sin embargo todos se siguen sumergiendo despu\u00e9s de\u00a0los a\u00f1os\u00a0con un mismo\u2026","rel":"","context":"En \u00abBuceo\u00bb","block_context":{"text":"Buceo","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/07\/jorge-atolon.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/07\/jorge-atolon.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/07\/jorge-atolon.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/07\/jorge-atolon.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/23494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=23494"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/23494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/23497"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=23494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=23494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=23494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}