{"id":25535,"date":"2016-12-11T11:55:31","date_gmt":"2016-12-11T14:55:31","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=25535"},"modified":"2024-01-04T05:54:35","modified_gmt":"2024-01-04T09:54:35","slug":"1er-torneo-natacion-con-aletas-el-bosque-en-santiago-de-chile-diciembre-2016","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/1er-torneo-natacion-con-aletas-el-bosque-en-santiago-de-chile\/","title":{"rendered":"\ud83c\udde8\ud83c\uddf1 Resultados 1er Torneo Nataci\u00f3n con Aletas El Bosque en Santiago de Chile Diciembre 2016"},"content":{"rendered":"<p><a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/12\/aletas-elbosque.jpg\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-25536\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/12\/aletas-elbosque.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/12\/aletas-elbosque.jpg 960w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/12\/aletas-elbosque-300x225.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/12\/aletas-elbosque-768x576.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/12\/aletas-elbosque-320x240.jpg 320w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><\/p>\n<p>(Sportalsub.net \/ Club de Actividades Subacu\u00e1ticas El Bosque)<\/p>\n<p>El Club de Actividades Subacu\u00e1ticas y Salvamento Deportivo El Bosque\u00a0organiz\u00f3\u00a0el\u00a0primer torneo de Nataci\u00f3n con Aletas\u00a0realizado en su comuna el\u00a0d\u00eda <strong>S\u00e1bado 10 de diciembre del presente a\u00f1o<\/strong> en la\u00a0 Piscina (25 metros) temperada Lo Blanco Av. Lo Blanco #550, El Bosque, Santiago de Chile.<\/p>\n<p>El evento incluy\u00f3 pruebas desde los 25 hasta los 200 metros con bialetas en categor\u00edas desde los 8 a\u00f1os hasta 55 o m\u00e1s en los que participaron m\u00e1s de 70 nadadores.<\/p>\n<p><a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/12\/RESULTADOS-EL-BOSQUE-2016.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>RESULTADOS OFICIALES<\/strong><\/a><\/p>\n<p><strong>Clasificaci\u00f3n Final por equipos<\/strong><\/p>\n<ol>\n<li>Subacu\u00e1ticos San Bernardo<\/li>\n<li>Club de Actividades Subacu\u00e1ticas y Salvamento Deportivo El Bosque<\/li>\n<li>Club Azul Profundo<\/li>\n<li>Escuela Sportsub<\/li>\n<\/ol>\n<p><a href=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/12\/convocatoria-el-bosque.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Convocatoria Oficial y m\u00e1s informaci\u00f3n<\/strong><\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/z-1-scontent.fsst1-1.fna.fbcdn.net\/v\/t31.0-8\/14876645_1774743996076331_5259644358282016557_o.jpg?oh=5033c679571c4497afff96e3dceff790&amp;oe=58F59601\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ Club de Actividades Subacu\u00e1ticas El Bosque) El Club de Actividades Subacu\u00e1ticas y Salvamento Deportivo El Bosque\u00a0organiz\u00f3\u00a0el\u00a0primer torneo de Nataci\u00f3n con Aletas\u00a0realizado en su comuna el\u00a0d\u00eda S\u00e1bado 10 de diciembre del presente a\u00f1o en la\u00a0 Piscina (25 metros) temperada Lo Blanco Av. Lo Blanco #550, El Bosque, Santiago de Chile. El evento incluy\u00f3 pruebas desde los 25 hasta los [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":25536,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"no","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[83,12,120],"tags":[477],"class_list":["post-25535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chile","category-natacion-con-aletas","category-resultados","tag-miguelsportsub"],"modified_by":"Sportalsub.net","views":5216,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-6DR","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":29158,"url":"https:\/\/www.sportalsub.net\/blog\/2do-campeonato-el-bosque-chile-2018","url_meta":{"origin":25535,"position":0},"title":"\ud83c\udde8\ud83c\uddf1 Resultados &#8211; 2\u00b0 Campeonato de Nataci\u00f3n con Aletas y Salvamento Deportivo El Bosque &#8211; Chile","author":"Sportalsub.net","date":"19 noviembre 2018","format":false,"excerpt":"(Sportalsub.net \/\u00a0Club de Actividades Subacu\u00e1ticas y Salvamento Deportivo El Bosque) El Club de Actividades Subacu\u00e1ticas y Salvamento Deportivo El\u00a0Bosque, llev\u00f3 a cabo el \u201c2do Campeonato de\u00a0Nataci\u00f3n con Aletas y Salvamento Deportivo\u201d; con el objetivo de fomentar la sana\u00a0competencia en los ni\u00f1os, j\u00f3venes y adultos, adem\u00e1s de estrechar lazos entre los\u00a0nadadores\u2026","rel":"","context":"En \u00abChile\u00bb","block_context":{"text":"Chile","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/chile\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/11\/resultadoselbosque.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/11\/resultadoselbosque.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/11\/resultadoselbosque.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/11\/resultadoselbosque.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/11\/resultadoselbosque.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":30276,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-nadosub-asosub-chile-2019","url_meta":{"origin":25535,"position":1},"title":"\ud83c\udde8\ud83c\uddf1 Resultados &#8211; Control de Nataci\u00f3n con Aletas ASOSUB Santiago de Chile Marzo 2019","author":"Sportalsub.net","date":"22 marzo 2019","format":false,"excerpt":"(Sportalsub.net \/ ASOSUB Santiago de Chile) El pasado s\u00e1bado 16 de marzo 2019 se llev\u00f3 a cabo en la piscina ol\u00edmpica exterior del Complejo Acu\u00e1tico del Estadio Nacional en la ciudad de Santiago de Chile, el primer control y liguilla de Nataci\u00f3n con Aletas de la Asociaci\u00f3n Deportiva Regional Metropolitana\u2026","rel":"","context":"En \u00abChile\u00bb","block_context":{"text":"Chile","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/chile\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/03\/asosub1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/03\/asosub1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/03\/asosub1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/03\/asosub1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24738,"url":"https:\/\/www.sportalsub.net\/blog\/1er-torneo-natacion-con-aletas-san-bernardo-chile-agosto-2016\/","url_meta":{"origin":25535,"position":2},"title":"\ud83c\udde8\ud83c\uddf1 Resultados 1er Torneo Nataci\u00f3n con Aletas San Bernardo, Chile &#8211; Agosto 2016","author":"Sportalsub.net","date":"17 agosto 2016","format":false,"excerpt":"(Sportalsub.net \/ Deportes\u00a0San Bernardo) La Ilustre Municipalidad de San Bernardo y Departamento de deportes y recreaci\u00f3n de San Bernardo, conjuntamente con el Club de Aletas San Bernardo, organizaron el\u00a0Primer Campeonato de Nataci\u00f3n con Aletas de su\u00a0comuna. El torneo se llev\u00f3 a cabo el d\u00eda s\u00e1bado 13 de agosto del 2016\u2026","rel":"","context":"En \u00abChile\u00bb","block_context":{"text":"Chile","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/chile\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/08\/torneo-san-bernardo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/08\/torneo-san-bernardo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/08\/torneo-san-bernardo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/08\/torneo-san-bernardo.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/08\/torneo-san-bernardo.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":21482,"url":"https:\/\/www.sportalsub.net\/blog\/final-copa-fedesub-2015-aletas-chile","url_meta":{"origin":25535,"position":3},"title":"\ud83c\udde8\ud83c\uddf1 Resultados Copa FEDESUB 2015 de Nataci\u00f3n con Aletas en Santiago de Chile","author":"Sportalsub.net","date":"30 septiembre 2015","format":false,"excerpt":"(Sportalsub.net \/ FEDESUB \/ Foto: Luis Rossel) El pasado domingo 27 de septiembre se llev\u00f3 a cabo en el\u00a0Centro Acu\u00e1tico del Estadio Nacional de Santiago de Chile la Copa FEDESUB 2015 de Nataci\u00f3n con Aletas, organizada por la\u00a0Federaci\u00f3n Chilena de Deportes Submarinos y Nataci\u00f3n con aletas en la cual participaron\u00a0aproximadamente\u2026","rel":"","context":"En \u00abChile\u00bb","block_context":{"text":"Chile","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/chile\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/12000921_908179715916737_6090207728450695717_o.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/12000921_908179715916737_6090207728450695717_o.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/12000921_908179715916737_6090207728450695717_o.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/12000921_908179715916737_6090207728450695717_o.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/12000921_908179715916737_6090207728450695717_o.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/11\/12000921_908179715916737_6090207728450695717_o.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":83970,"url":"https:\/\/www.sportalsub.net\/blog\/indoor-fedesub-2025","url_meta":{"origin":25535,"position":4},"title":"\ud83c\udde8\ud83c\uddf1 Resultados &#8211; Campeonato Indoor Interclubes Apnea, Nataci\u00f3n con Aletas, Rugby Subacu\u00e1tico FEDESUB 2025 &#8211; Santiago de Chile","author":"Sportalsub.net","date":"14 diciembre 2025","format":false,"excerpt":"(Sportalsub.net \/ FEDESUB \/ CMAS Chile) La Federaci\u00f3n Deportiva Nacional de Actividades Subacu\u00e1ticas y Salvamento Acu\u00e1tico de Chile ( FEDESUB \/ CMAS Chile) organiz\u00f3 el Campeonato Indoor Interclubes de Actividades Subacu\u00e1ticas 2025, un encuentro nacional e internacional que reuni\u00f3 a deportistas de Rugby Subacu\u00e1tico, Nataci\u00f3n con Aletas y Apnea, y\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/11\/resultados-fedesub-diciembre-2025.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/11\/resultados-fedesub-diciembre-2025.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/11\/resultados-fedesub-diciembre-2025.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/11\/resultados-fedesub-diciembre-2025.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":25961,"url":"https:\/\/www.sportalsub.net\/blog\/2do-campeonato-nacional-indoor-de-actividades-subacuaticas-santiago-2017\/","url_meta":{"origin":25535,"position":5},"title":"\ud83c\udde8\ud83c\uddf1 Resultados &#8211; 2do Campeonato Nacional Indoor de Actividades Subacu\u00e1ticas FEDESUB Chile Santiago 2017","author":"Sportalsub.net","date":"1 mayo 2017","format":false,"excerpt":"(Sportalsub.net \/ FEDESUB) -\u00a0Foto principal por: Laura Babahekian \/ deaquavivo.com La Federaci\u00f3n Deportiva Nacional de Actividades Subacu\u00e1ticas y Salvamento Acu\u00e1tico (FEDESUB) realiz\u00f3 el 2do Campeonato Nacional Indoor, el cual incluy\u00f3 Apnea, Nataci\u00f3n con Aletas y Salvamento Deportivo, el cual se desarroll\u00f3 los d\u00edas 28, 29 y 30 de Abril de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/04\/fotolaura.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/04\/fotolaura.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/04\/fotolaura.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/04\/fotolaura.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/04\/fotolaura.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/04\/fotolaura.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/12\/aletas-elbosque.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/25535","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=25535"}],"version-history":[{"count":1,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/25535\/revisions"}],"predecessor-version":[{"id":68790,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/25535\/revisions\/68790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/25536"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=25535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=25535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=25535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}