{"id":26991,"date":"2017-11-28T09:38:44","date_gmt":"2017-11-28T12:38:44","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=26991"},"modified":"2019-08-31T22:22:13","modified_gmt":"2019-09-01T02:22:13","slug":"espana-arrasa-en-el-xvi-campeonato-mundial-de-fotografia-submarina-cmas-2017-en-la-paz-mexico","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/espana-arrasa-en-el-mundial-de-fotografia-submarina-de-mexico-2017\/","title":{"rendered":"\ud83c\uddea\ud83c\uddf8 Espa\u00f1a arrasa en el XVI Campeonato Mundial de Fotograf\u00eda Submarina CMAS 2017 en La Paz, M\u00e9xico + Galer\u00eda de Fotos"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26992\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/2017MUNFOT1.jpg\" alt=\"\" width=\"1000\" height=\"666\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/2017MUNFOT1.jpg 1000w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/2017MUNFOT1-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/2017MUNFOT1-768x511.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/2017MUNFOT1-177x118.jpg 177w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>(Sportalsub.net \/ FEDAS)<\/p>\n<p>La semana del 22 al 27 de noviembre se ha celebrado el <a href=\"http:\/\/www.sportalsub.net\/blog\/mundial-de-fotografia-subacuatica-cmas-2017-mexico\/\">16\u00ba Campeonato del Mundo de Fotograf\u00eda Submarina en La Paz, M\u00e9xico<\/a>.<\/p>\n<p>La Selecci\u00f3n Espa\u00f1ola se concentr\u00f3 en el lugar para comenzar con sus entrenamientos el d\u00eda 7 de noviembre y durante los d\u00edas previos al Campeonato estuvieron reconociendo las 12 zonas elegidas por la organizaci\u00f3n del evento.<\/p>\n<p>Tras recibir las noticias de los cambios en los reglamentos y otras cuestiones que complicaban considerablemente a la competici\u00f3n, el equipo espa\u00f1ol consigui\u00f3 adaptarse perfectamente a las nuevas condiciones del Campeonato.<\/p>\n<p>Una vez seleccionadas las fotograf\u00edas se procedi\u00f3 al fallo del jurado compuesto por 7 miembros de distintos pa\u00edses.<\/p>\n<p>El equipo compuesto por Jes\u00fas Yeray Delgado Dorta y Abigail Mart\u00edn Hern\u00e1ndez obtuvo las medallas de plata en las categor\u00edas de Pez, Angular sin Buceador y medalla de plata en la general absoluta por equipos.<\/p>\n<p>La otra pareja compuesta por Rafael Fern\u00e1ndez Caballero y \u00d3scar Luna Romero han conseguido la medalla de plata en Close Up Tema (Le\u00f3n Marino), y medallas de oro en Pez y Angular sin Modelo, proclam\u00e1ndose Campeones del Mundo absolutos en esta edici\u00f3n.<\/p>\n<p>El Seleccionador Nacional y Capit\u00e1n del equipo, ha sido el actual Presidente del Comit\u00e9 de Imagen de la Federaci\u00f3n Espa\u00f1ola de Actividades Subacu\u00e1tica, Juan \u00c1ngel Cano C\u00e1rceles con el apoyo del Vicepresidente del citado Comit\u00e9, Jos\u00e9 Antonio Garc\u00eda Garc\u00eda.<\/p>\n<p>Esto supone un hito, ya que por un lado se ha logrado el Campeonato de Europa y el Mundial seguidos por un mismo equipo y adem\u00e1s obtener tambi\u00e9n la 1\u00aa y 2\u00aa posici\u00f3n de una misma selecci\u00f3n en un Mundial.<\/p>\n<p>Queda demostrado el potencial de los fot\u00f3grafos submarinos espa\u00f1oles a nivel Mundial, siendo un gran referente para el resto de selecciones.<\/p>\n<p>El Presidente del Comit\u00e9 de Imagen ha solicitado organizar el pr\u00f3ximo Campeonato del Mundo en la Reserva Marina de Cabo de Palos, Murcia, para el a\u00f1o 2019 y esperamos ganar la candidatura al resto de pa\u00edses para as\u00ed acercar a los mejores fot\u00f3grafos mundiales a las costas espa\u00f1olas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5363\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT1.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT1.jpg 1000w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT1-300x200.jpg 300w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT1-768x511.jpg 768w\" alt=\"2017MUNFOT1\" width=\"1000\" height=\"666\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5364\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT2.jpg\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT2.jpg 666w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT2-200x300.jpg 200w\" alt=\"2017MUNFOT2\" width=\"666\" height=\"1000\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5365\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT3.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT3.jpg 1000w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT3-300x200.jpg 300w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT3-768x511.jpg 768w\" alt=\"2017MUNFOT3\" width=\"1000\" height=\"666\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5366\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT4.jpg\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT4.jpg 666w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT4-200x300.jpg 200w\" alt=\"2017MUNFOT4\" width=\"666\" height=\"1000\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5367\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT5.jpg\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT5.jpg 666w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT5-200x300.jpg 200w\" alt=\"2017MUNFOT5\" width=\"666\" height=\"1000\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5368\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT6.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT6.jpg 1000w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT6-300x199.jpg 300w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT6-768x510.jpg 768w\" alt=\"2017MUNFOT6\" width=\"1000\" height=\"664\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5369\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT7.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT7.jpg 1000w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT7-300x200.jpg 300w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT7-768x511.jpg 768w\" alt=\"2017MUNFOT7\" width=\"1000\" height=\"666\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5370\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT8.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT8.jpg 1000w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT8-300x200.jpg 300w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT8-768x511.jpg 768w\" alt=\"2017MUNFOT8\" width=\"1000\" height=\"666\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5371\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT9.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT9.jpg 1000w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT9-300x200.jpg 300w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT9-768x511.jpg 768w\" alt=\"2017MUNFOT9\" width=\"1000\" height=\"666\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5372\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT10.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT10.jpg 1000w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT10-300x199.jpg 300w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT10-768x510.jpg 768w\" alt=\"2017MUNFOT10\" width=\"1000\" height=\"664\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5373\" src=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT11.jpg\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" srcset=\"http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT11.jpg 1000w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT11-300x200.jpg 300w, http:\/\/fedas.es\/wp-content\/uploads\/2017\/11\/2017MUNFOT11-768x512.jpg 768w\" alt=\"2017MUNFOT11\" width=\"1000\" height=\"667\" \/><\/p>\n<p>Juan \u00c1ngel Cano C\u00e1rceles &#8211;\u00a0Presidente Comit\u00e9 de Imagen FEDAS<\/p>\n<p>Fuente: <a href=\"http:\/\/fedas.es\/espana-arrasa-en-el-mundial-de-fotografia-submarina-de-mexico-2017\/\" target=\"_blank\">FEDAS<\/a><\/p>\n<p><a href=\"http:\/\/www.sportalsub.net\/blog\/mundial-de-fotografia-subacuatica-cmas-2017-mexico\/\">Pr\u00f3ximamente Resultados Completos del Campeonato<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ FEDAS) La semana del 22 al 27 de noviembre se ha celebrado el 16\u00ba Campeonato del Mundo de Fotograf\u00eda Submarina en La Paz, M\u00e9xico. La Selecci\u00f3n Espa\u00f1ola se concentr\u00f3 en el lugar para comenzar con sus entrenamientos el d\u00eda 7 de noviembre y durante los d\u00edas previos al Campeonato estuvieron reconociendo las 12 zonas elegidas por la organizaci\u00f3n [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":26993,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[347,10,19,120],"tags":[],"class_list":["post-26991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-espana","category-fotografia-submarina","category-resultados"],"modified_by":"Sportalsub.net","views":3492,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/2017MUNFOT10.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-71l","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":25639,"url":"https:\/\/www.sportalsub.net\/blog\/mundial-de-fotografia-subacuatica-cmas-2017-mexico\/","url_meta":{"origin":26991,"position":0},"title":"\ud83c\uddf2\ud83c\uddfd Resultados y Fotos. XVI Campeonato Mundial de Fotograf\u00eda Subacu\u00e1tica CMAS Noviembre 2017 \u2013 La Paz, M\u00e9xico","author":"Sportalsub.net","date":"4 diciembre 2017","format":false,"excerpt":"(Sportalsub.net \/ CMAS \/ CMAS Zona Am\u00e9rica \/ FMAS) - Read in English El 16to Campeonato Mundial de Fotograf\u00eda Subacu\u00e1tica de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas CMAS se llev\u00f3 a cabo del 22 al 27 de noviembre 2017 en La Paz \u2013 Baja California, M\u00e9xico Con profesionales de la\u2026","rel":"","context":"En \u00abAlemania\u00bb","block_context":{"text":"Alemania","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/alemania\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/24852581_1543952412337082_5605884843737740618_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/24852581_1543952412337082_5605884843737740618_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/24852581_1543952412337082_5605884843737740618_n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/11\/24852581_1543952412337082_5605884843737740618_n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24365,"url":"https:\/\/www.sportalsub.net\/blog\/fotosub-la-paz-2016","url_meta":{"origin":26991,"position":1},"title":"\ud83c\uddf2\ud83c\uddfd Resultados y Fotos &#8211; 4to Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica FMAS La Paz, M\u00e9xico","author":"Sportalsub.net","date":"10 noviembre 2016","format":false,"excerpt":"(Sportalsub.net \/ FMAS \/ Fotosub La Paz) La Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas llev\u00f3\u00a0a cabo el 4\u00b0 Campeonato Nacional de Fotograf\u00eda Subacu\u00e1tica, del 4\u00a0al 8\u00a0de Noviembre del 2016. Este evento fue preparatorio para el XVI Campeonato Mundial de Fotograf\u00eda Submarina CMAS\u00a02017. Resultados y Fotos Ganadoras, cortes\u00eda Ulises Portugal M\u00e1s info:\u2026","rel":"","context":"En \u00abFotograf\u00eda Submarina\u00bb","block_context":{"text":"Fotograf\u00eda Submarina","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/fotografia-submarina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/10\/fotosubmexico.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/10\/fotosubmexico.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/10\/fotosubmexico.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/10\/fotosubmexico.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9398,"url":"https:\/\/www.sportalsub.net\/blog\/espana-destaca-en-campeonato-mundial-de-fotografia-submarina-cmas-turquia-2011\/","url_meta":{"origin":26991,"position":2},"title":"\ud83c\uddea\ud83c\uddf8 Espa\u00f1a destaca en Campeonato Mundial de Fotograf\u00eda Submarina CMAS Turqu\u00eda 2011","author":"Sportalsub.net","date":"1 junio 2011","format":false,"excerpt":"(Especial Sportalsub.net \/ FEDAS) Una vez m\u00e1s el equipo espa\u00f1ol, esta vez formado por Arturo Telle\/Montserrat Grillo y David Barrio\/M\u00aa Luisa Quintanilla, han demostrado el gran nivel de la fotograf\u00eda submarina en Espa\u00f1a, consiguiendo dos medallas de oro de las cinco posibles y un bronce en el Campeonato Mundial de\u2026","rel":"","context":"En \u00abCMAS\u00bb","block_context":{"text":"CMAS","link":"https:\/\/www.sportalsub.net\/blog\/category\/mas\/organizaciones\/cmas-organizaciones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/06\/Spain-David-Barrio-Oro-Ambiente-sin-modelo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/06\/Spain-David-Barrio-Oro-Ambiente-sin-modelo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/06\/Spain-David-Barrio-Oro-Ambiente-sin-modelo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":45200,"url":"https:\/\/www.sportalsub.net\/blog\/cmas-fotovideosub-portugal-2021","url_meta":{"origin":26991,"position":3},"title":"\ud83c\uddf5\ud83c\uddf9 Resultados &#8211; Campeonatos Mundiales de Fotograf\u00eda y Video Submarino CMAS &#8211; Madeira, Portugal 2021","author":"Sportalsub.net","date":"12 octubre 2021","format":false,"excerpt":"(Sportalsub.net \/ CMAS \/ FPAS) - Read in English El 18\u00b0 Campeonato Mundial de Fotograf\u00eda Submarina y el 4\u00b0 Campeonato Mundial de Video Submarino de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS) se realizaron del 4 al 9 de octubre 2021 en Madeira, Porto Santo en Portugal. El evento fue\u2026","rel":"","context":"En \u00abChile\u00bb","block_context":{"text":"Chile","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/chile\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/10\/resultadosimagensubportugal2021.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/10\/resultadosimagensubportugal2021.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/10\/resultadosimagensubportugal2021.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/10\/resultadosimagensubportugal2021.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10996,"url":"https:\/\/www.sportalsub.net\/blog\/campeonato-de-espana-de-fotografia-submarina-nafosub-2011-5-al-9-de-octubre-en-murcia\/","url_meta":{"origin":26991,"position":4},"title":"\ud83c\uddea\ud83c\uddf8 Campeonato de Espa\u00f1a de Fotograf\u00eda Submarina NAFOSUB 2011 se realizar\u00e1 del 5 al 9 de octubre en Murcia","author":"Sportalsub.net","date":"3 octubre 2011","format":false,"excerpt":"(Especial Sportalsub.net \/ NAFOSUB-11) Desde el 5 al 9 de octubre, la Reserva Marina de Cabo Palos- Islas Hormigas\u00a0convertir\u00e1 en el escenario de este importante evento, patrocinado por el Plan de Competitividad Tur\u00edstica, La Manga-Turismo N\u00e1utico. El Campeonato de Espa\u00f1a Fotograf\u00eda Submarina, NAFOSUB-11, organizado por\u00a0la Federaci\u00f3n de Actividades Subacu\u00e1ticas de\u2026","rel":"","context":"En \u00abEspa\u00f1a\u00bb","block_context":{"text":"Espa\u00f1a","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/espana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/10\/nafosub2011.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6327,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-del-campeonato-de-espana-de-fotografia-submarina-nafosub-2010\/","url_meta":{"origin":26991,"position":5},"title":"\ud83c\uddea\ud83c\uddf8 Resultados del Campeonato de Espa\u00f1a de Fotograf\u00eda Submarina NAFOSUB 2010","author":"Sportalsub.net","date":"8 octubre 2010","format":false,"excerpt":"(Especial Sportalsub.net) Del 22 al 25 de septiembre se realiz\u00f3 en Tazacorte - La Palma, Espa\u00f1a, el Campeonato de Espa\u00f1a de Fotograf\u00eda Submarina 2010 con la participaci\u00f3n de 24 fot\u00f3grafos subacu\u00e1ticos de varias Federaciones Auton\u00f3micas espa\u00f1olas. El primer lugar lo obtuvo Luis Garc\u00eda de la Federaci\u00f3n Madrile\u00f1a. Resultados Oficiales Completos","rel":"","context":"En \u00abEspa\u00f1a\u00bb","block_context":{"text":"Espa\u00f1a","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/espana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/0111.gif?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/0111.gif?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/0111.gif?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/0111.gif?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/26991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=26991"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/26991\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/26993"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=26991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=26991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=26991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}