{"id":27965,"date":"2018-04-26T10:10:08","date_gmt":"2018-04-26T14:10:08","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=27965"},"modified":"2019-08-31T23:16:09","modified_gmt":"2019-09-01T03:16:09","slug":"cmas-zona-america-presente-en-la-asamblea-general-cmas-2018-en-tailandia","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/cmas-zona-america-asamblea-cmas-2018","title":{"rendered":"\ud83c\uddf9\ud83c\udded CMAS Zona Am\u00e9rica presente en la Asamblea General CMAS 2018 en Tailandia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-27966\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/cmas-tailandia-2018.jpg\" alt=\"\" width=\"960\" height=\"720\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/cmas-tailandia-2018.jpg 960w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/cmas-tailandia-2018-300x225.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/cmas-tailandia-2018-768x576.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/cmas-tailandia-2018-320x240.jpg 320w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/p>\n<p>(Sportalsub.net \/ CMAS Zona Am\u00e9rica)<\/p>\n<p>Del 25 al 27 de abril de 2018 se lleva a cabo en Phuket, Tailandia, la Asamblea General Ordinaria Anual de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS), en la que el m\u00e1ximo ente rector de las Actividades Subacu\u00e1ticas ofrece el\u00a0Informe de las actividades del Consejo de Administraci\u00f3n presentado por su\u00a0Presidenta, as\u00ed como se presentan los\u00a0Informes de los Presidentes de los Comit\u00e9s:\u00a0Cient\u00edfico,\u00a0Deportivo y T\u00e9cnico, adem\u00e1s de toda la gesti\u00f3n financiera y administrativa de la organizaci\u00f3n.<\/p>\n<p>CMAS Zona Am\u00e9rica tendr\u00e1 presencia en esta Asamblea con el Presidente:\u00a0<strong>William Pe\u00f1a<\/strong>\u00a0de Colombia, el Secretario General:\u00a0<strong>Francisco Lacase<\/strong>\u00a0de Argentina y el Director del Comit\u00e9 T\u00e9cnico:\u00a0<strong>Juan Jos\u00e9 Maldonado<\/strong>\u00a0de Chile, quienes tambi\u00e9n tienen previsto reunirse en marco del evento para tratar asuntos de inter\u00e9s de la organizaci\u00f3n a nivel continental en los pa\u00edses de Am\u00e9rica, as\u00ed como reunirse con las Federaciones de Espa\u00f1a y Portugal pertenecientes tambi\u00e9n a la Uni\u00f3n Iberoamericana de Federaciones de Actividades Subacu\u00e1ticas (UIFAS).<\/p>\n<p>Tambi\u00e9n asiste a esta Asamblea\u00a0<strong>Nelson D\u00edaz<\/strong>, tesorero de la Federaci\u00f3n de Chile<\/p>\n<figure id=\"attachment_1631\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1631 size-full\" src=\"http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/anna-cmas-zona-america.jpg\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" srcset=\"http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/anna-cmas-zona-america.jpg 1280w, http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/anna-cmas-zona-america-300x225.jpg 300w, http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/anna-cmas-zona-america-768x576.jpg 768w, http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/anna-cmas-zona-america-1024x768.jpg 1024w, http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/anna-cmas-zona-america-100x75.jpg 100w\" alt=\"\" width=\"1280\" height=\"960\" \/><figcaption class=\"wp-caption-text\">Reuni\u00f3n de CMAS Zona Am\u00e9rica con la Presidenta de CMAS \u2013 Anna Arzhanova \u2013 Jueves 26 de Abril<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1633 size-full\" src=\"http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/uifas.jpg\" sizes=\"auto, (max-width: 1328px) 100vw, 1328px\" srcset=\"http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/uifas.jpg 1328w, http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/uifas-300x169.jpg 300w, http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/uifas-768x432.jpg 768w, http:\/\/www.cmasamerica.org\/wp-content\/uploads\/2018\/04\/uifas-1024x576.jpg 1024w\" alt=\"\" width=\"1328\" height=\"747\" \/>Reuni\u00f3n UIFAS. Federaciones de pa\u00edses iberoamericanos con Presidenta de CMAS Anna Arzhanova \u2013 Jueves 26 de Abril<\/p>\n<p>Pr\u00f3ximamente m\u00e1s informaci\u00f3n.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.cmasamerica.org\/cmas-zona-america-presente-en-la-asamblea-general-cmas-2018-en-tailandia\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">CMAS Zona Am\u00e9rica<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ CMAS Zona Am\u00e9rica) Del 25 al 27 de abril de 2018 se lleva a cabo en Phuket, Tailandia, la Asamblea General Ordinaria Anual de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS), en la que el m\u00e1ximo ente rector de las Actividades Subacu\u00e1ticas ofrece el\u00a0Informe de las actividades del Consejo de Administraci\u00f3n presentado por su\u00a0Presidenta, as\u00ed como se presentan [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":27966,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[117,356,317],"tags":[],"class_list":["post-27965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-modalidades","category-america","category-tailandia"],"modified_by":"Sportalsub.net","views":2727,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/04\/cmas-tailandia-2018.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-7h3","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":25484,"url":"https:\/\/www.sportalsub.net\/blog\/cmas-zona-america-2017-2020","url_meta":{"origin":27965,"position":0},"title":"\ud83c\udf0e CMAS Zona Am\u00e9rica con nuevos directores para el per\u00edodo 2017-2020","author":"Sportalsub.net","date":"29 noviembre 2016","format":false,"excerpt":"(Sportalsub.net \/ CMAS Zona Am\u00e9rica) Este lunes 28 de noviembre de 2016, en el marco de los III Juegos Bolivarianos de Playa Iquique 2016 en Chile, se realiz\u00f3 la\u00a0Asamblea General Ordinaria y\u00a0Elecciones del nuevo Consejo Directivo para el per\u00edodo 2017-2020 de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas CMAS Zona Am\u00e9rica.\u2026","rel":"","context":"En \u00abActividades Subacu\u00e1ticas\u00bb","block_context":{"text":"Actividades Subacu\u00e1ticas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/11\/asamblea-cmaszona-america.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/11\/asamblea-cmaszona-america.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/11\/asamblea-cmaszona-america.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/11\/asamblea-cmaszona-america.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/11\/asamblea-cmaszona-america.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":4481,"url":"https:\/\/www.sportalsub.net\/blog\/realizada-asamblea-2010-y-conformada-nueva-junta-directiva-cmas-zona-america\/","url_meta":{"origin":27965,"position":1},"title":"\ud83c\udde8\ud83c\uddfa Realizada Asamblea 2010 y Conformada Nueva Junta Directiva CMAS Zona Am\u00e9rica","author":"Sportalsub.net","date":"11 abril 2010","format":false,"excerpt":"Parte de la Nueva Directiva de CMAS Zona Am\u00e9rica 2010-2014 Especial Sportalsub.net -\u00a0Domingo\u00a011 de Abril de 2010. En el d\u00eda de ayer, s\u00e1bado 10 de abril, en el Hotel Copacabana sede de la Asamblea General de CMAS Zona Am\u00e9rica, se di\u00f3 inauguraci\u00f3n a tan importante evento con las palabras de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/04\/cmasamerica2010.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":16768,"url":"https:\/\/www.sportalsub.net\/blog\/nueva-directiva-de-confederacion-mundial-de-actividades-subacuaticas-en-america-2014-2017\/","url_meta":{"origin":27965,"position":2},"title":"\ud83c\udf0e Nuevas Directivas de Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas en Am\u00e9rica y Uni\u00f3n Iberoamericana de Actividades Subacu\u00e1ticas 2014-2017","author":"Sportalsub.net","date":"14 noviembre 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ CMAS Am\u00e9rica \/ FMAS) El Presidente de la Federaci\u00f3n M\u00e9xicana de Actividades Subacu\u00e1ticas y Vicepresidente\u00a0de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas en la Zona Am\u00e9rica (CMAS Am\u00e9rica) \u00a0por el per\u00edodo 2009-2013\u00a0, Rogelio Flores, asumir\u00e1 la Presidencia de la organizaci\u00f3n continental, para el per\u00edodo 2014-2017 En la Asamblea\u2026","rel":"","context":"En \u00abArgentina\u00bb","block_context":{"text":"Argentina","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/argentina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/cmas-america-2013.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/cmas-america-2013.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/cmas-america-2013.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/cmas-america-2013.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2049,"url":"https:\/\/www.sportalsub.net\/blog\/asamblea-general-2009-cmas-elije-a-sus-nuevas-autoridades-2009-2012\/","url_meta":{"origin":27965,"position":3},"title":"\ud83c\udf0e Asamblea General 2009. CMAS elije a sus nuevas autoridades","author":"Sportalsub.net","date":"5 mayo 2009","format":false,"excerpt":"Foto: Ronald Laurens @ Sportalsub.net (Martes, 5 de Mayo 2009\u00a0 - Especial Sportalsub.net) La Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS),\u00a0que celebra\u00a0su Asamblea General 2009 del 2 al 9 de Mayo en Puket, Tailandia, ha realizado las elecciones y designaci\u00f3n de sus nuevas autoridades para el ciclo ol\u00edmpico 2009-2012, en donde\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/05\/bari_apneadinamic0002_1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/05\/bari_apneadinamic0002_1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/05\/bari_apneadinamic0002_1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/05\/bari_apneadinamic0002_1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24274,"url":"https:\/\/www.sportalsub.net\/blog\/continuan-las-actividades-subacuaticas-en-el-continente-americano-cmas-zona-america\/","url_meta":{"origin":27965,"position":4},"title":"\ud83c\udf0e Contin\u00faan las Actividades Subacu\u00e1ticas en el Continente Americano  de la mano de CMAS Zona Am\u00e9rica","author":"Sportalsub.net","date":"26 mayo 2016","format":false,"excerpt":"Especial Sportalsub.net \/ CMAS Zona Am\u00e9rica \/ Miguel A. Cede\u00f1o O. La Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas Zona Am\u00e9rica (CMAS Zona Am\u00e9rica), agrupa a las Federaciones Nacionales, Asociaciones u Organismos afiliados a la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (C.M.A.S) en la zona americana y se encarga de fomentar las actividades\u2026","rel":"","context":"En \u00abActividades Subacu\u00e1ticas\u00bb","block_context":{"text":"Actividades Subacu\u00e1ticas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/cmas-zonaamericafeat-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/cmas-zonaamericafeat-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/cmas-zonaamericafeat-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/05\/cmas-zonaamericafeat-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8512,"url":"https:\/\/www.sportalsub.net\/blog\/celebra-asamblea-la-federacion-mexicana-de-actividades-subacuaticas\/","url_meta":{"origin":27965,"position":5},"title":"\ud83c\uddf2\ud83c\uddfd Celebra Asamblea la Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas","author":"Sportalsub.net","date":"7 febrero 2011","format":false,"excerpt":"M\u00e9xico, D.F. A 05 de febrero de 2011.- La Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas (FMAS), al frente de la cual est\u00e1 Rogelio Flores Aguilera, realiz\u00f3 hoy la Asamblea General Ordinaria 2010 al cumplir sus expectativas del programa de actividades en las \u00e1reas deportivas, t\u00e9cnicas y cient\u00edficas, destacando el manejo transparente\u2026","rel":"","context":"En \u00abBuceo Cient\u00edfico\u00bb","block_context":{"text":"Buceo Cient\u00edfico","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/buceo-cientifico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2011\/02\/fmas-asamblea.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/27965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=27965"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/27965\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/27966"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=27965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=27965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=27965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}