{"id":27994,"date":"2018-05-03T16:29:36","date_gmt":"2018-05-03T20:29:36","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=27994"},"modified":"2019-08-31T23:49:28","modified_gmt":"2019-09-01T03:49:28","slug":"el-hockey-subacuatico-argentino-rumbo-al-mundial-canada-2018","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/el-hockey-subacuatico-argentino-rumbo-a-canada-2018\/","title":{"rendered":"\ud83c\udde6\ud83c\uddf7 El Hockey Subacu\u00e1tico Argentino rumbo al Mundial Canad\u00e1 2018"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-27995\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/ahsa1.jpg\" alt=\"\" width=\"900\" height=\"550\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/ahsa1.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/ahsa1-300x183.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/ahsa1-768x469.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>(Sportalsub.net \/ AHSA)<\/p>\n<p>Siguiendo con los lineamientos y la planificaci\u00f3n del Proyecto Argentino,\u00a0 la <a href=\"http:\/\/www.ahsa.org.ar\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Asociaci\u00f3n de Hockey Subacu\u00e1tico Argentina (AHSA)<\/a>,<a href=\"http:\/\/www.cmas.org\/federation-list\/federation-asociacion-de-hockey-subacuatico-de-argentina\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"> asociaci\u00f3n deportiva reconocida por la CMAS<\/a> y por la<a href=\"https:\/\/cad.org.ar\/\" target=\"_blank\"> Confederaci\u00f3n Argentina de Deportes<\/a>, llev\u00f3 a cabo\u00a0 en la ciudad de Neuqu\u00e9n (Patagonia Argentina) durante el mes de abril, la \u00faltima concentraci\u00f3n de pre selecciones. Donde se han definido los integrantes las de las selecciones que competir\u00e1n en el <a href=\"http:\/\/www.sportalsub.net\/blog\/uwhworlds2018\">20\u00b0 Campeonato Mundial de Quebec &#8211; Canad\u00e1 2018<\/a>.<\/p>\n<p>Las actividades, tuvieron como objetivo principal, seleccionar a los jugadores de los equipos que competir\u00e1n en Canad\u00e1 en sus cuatro categor\u00edas, (Elite Femenina, Elite masculina, Master f\u00e9mina, Master masculina). Y el correspondiente cuerpo t\u00e9cnico. El cual ser\u00e1 integrado esta vez, por cuatro DT (Catriel Femenia, Juan L. Lequi, Facundo Suzzara y Mariano Singer) m\u00e1s \u00a0dos asistentes. Tambi\u00e9n, en esta oportunidad, las selecciones contaran con la asistencia de un manager.<\/p>\n<p>Como a lo largo de todo el proceso, el cual comenz\u00f3 en Octubre del a\u00f1o 2016, el encargado de liderar la parte t\u00e9cnica del mismo, fue el Head Coach Sebastian Lugo M\u00e1rquez, quien se encarg\u00f3 de la preparaci\u00f3n, planificaci\u00f3n y selecci\u00f3n tanto de jugadores como t\u00e9cnicos que integraran el plantel definitivo.<\/p>\n<p>Ya habiendo concluido la etapa de selecci\u00f3n, ahora solo resta optimizar la preparaci\u00f3n para afrontar el desaf\u00edo de la competencia. Convencidas de poder lograr los objetivos previstos y con las mejores expectativas, las selecciones, no ven la hora de que llegue el d\u00eda de la competencia para demostrar el trabajo realizado.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-27996\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/ahsa2.jpg\" alt=\"\" width=\"900\" height=\"550\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/ahsa2.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/ahsa2-300x183.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/ahsa2-768x469.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2017\/01\/header.jpg\" \/><\/p>\n<h3 class=\"post-title entry-title\"><a href=\"http:\/\/www.ahsa.org.ar\/presentacion-oficial-de-los-seleccionados-20-mundial-canada-2018\/\" target=\"_blank\">PRESENTACI\u00d3N OFICIAL DE LOS SELECCIONADOS | 20\u00b0 MUNDIAL CANADA 2018<\/a><\/h3>\n<div class=\"entry-content\">\n<p>Estos Jugadores y Cuerpo T\u00e9cnico estar\u00e1n representando a la Argentina en el\u00a020\u00b0 Copa del Mundo a realizarse en Quebec \u2013 Canad\u00e1.<\/p>\n<p>Es un hecho hist\u00f3rico, por primera vez la Argentina presentar\u00e1 4 seleccionados en las categorias: Elite Masculino\/Femenino y Master Masculino\/Femenino.<\/p>\n<p>Viajar\u00e1n 48 deportistas, en los que se incluyen 4 Coachs, 2 Ayudantes, 3\u00a0\u00e1rbitros, Manager y el HeadCoach.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1468\" src=\"http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Elite-Masculino.jpg\" sizes=\"(max-width: 725px) 100vw, 725px\" srcset=\"http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Elite-Masculino.jpg 725w, http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Elite-Masculino-212x300.jpg 212w, http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Elite-Masculino-724x1024.jpg 724w\" alt=\"\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1486\" src=\"http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-ELite-Femenino.jpg\" sizes=\"(max-width: 725px) 100vw, 725px\" srcset=\"http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-ELite-Femenino.jpg 725w, http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-ELite-Femenino-212x300.jpg 212w, http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-ELite-Femenino-724x1024.jpg 724w\" alt=\"\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1484\" src=\"http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Elite_Masculino.jpg\" sizes=\"(max-width: 725px) 100vw, 725px\" srcset=\"http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Elite_Masculino.jpg 725w, http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Elite_Masculino-212x300.jpg 212w, http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Elite_Masculino-724x1024.jpg 724w\" alt=\"\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1469\" src=\"http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Master-Femenino.jpg\" sizes=\"(max-width: 725px) 100vw, 725px\" srcset=\"http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Master-Femenino.jpg 725w, http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Master-Femenino-212x300.jpg 212w, http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Equipo-Master-Femenino-724x1024.jpg 724w\" alt=\"\" \/><\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-1469\" src=\"http:\/\/www.ahsa.org.ar\/wp-content\/uploads\/2018\/04\/Cuerpo-tecnico.jpg\" alt=\"\" \/><\/p>\n<p>Sitio Web Oficial AHSA:\u00a0<a href=\"http:\/\/www.ahsa.org.ar\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.ahsa.org.ar\/<br \/>\n<\/a>Facebook Oficial AHSA:\u00a0<a href=\"https:\/\/www.facebook.com\/AHSA.hockeysub\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/www.facebook.com\/AHSA.hockeysub\/<\/a><br \/>\nInstagram Oficial AHSA:\u00a0<a href=\"https:\/\/www.instagram.com\/argentina.uwh\/\" target=\"_blank\">https:\/\/www.instagram.com\/argentina.uwh\/<\/a><\/p>\n<p>Enviado por: Ariel de Gracia &#8211;\u00a0<a href=\"mailto:aridegracia@hotmail.com.ar\">aridegracia@hotmail.com.ar<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ AHSA) Siguiendo con los lineamientos y la planificaci\u00f3n del Proyecto Argentino,\u00a0 la Asociaci\u00f3n de Hockey Subacu\u00e1tico Argentina (AHSA), asociaci\u00f3n deportiva reconocida por la CMAS y por la Confederaci\u00f3n Argentina de Deportes, llev\u00f3 a cabo\u00a0 en la ciudad de Neuqu\u00e9n (Patagonia Argentina) durante el mes de abril, la \u00faltima concentraci\u00f3n de pre selecciones. Donde se han definido los integrantes [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":27995,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4,2],"tags":[],"class_list":["post-27994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-argentina","category-hockey-subacuatico"],"modified_by":"Sportalsub.net","views":6741,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-7hw","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":25774,"url":"https:\/\/www.sportalsub.net\/blog\/por-primera-vez-argentina-prepara-selecciones-juveniles-de-hockey-subacuatico\/","url_meta":{"origin":27994,"position":0},"title":"\ud83c\udde6\ud83c\uddf7 Por primera vez, Argentina prepara selecciones juveniles de hockey subacu\u00e1tico","author":"Sportalsub.net","date":"10 febrero 2017","format":false,"excerpt":"M\u00e1s de 70 deportistas participaron del primer campamento de preselecciones de hockey subacu\u00e1tico. Buscan hacer historia presentando tres selecciones juveniles en el\u00a04to Campeonato Mundial De Hockey Subacu\u00e1tico Por Grupos De Edades Hobart, Australia 2017 (Sportalsub.net \/ AHSA) Del 21 al 29 de enero se desarroll\u00f3 el primer campamento de preselecciones\u2026","rel":"","context":"En \u00abArgentina\u00bb","block_context":{"text":"Argentina","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/argentina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/argentinahockeysub2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/argentinahockeysub2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/argentinahockeysub2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/02\/argentinahockeysub2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":25750,"url":"https:\/\/www.sportalsub.net\/blog\/argentina-se-prepara-para-figurar-en-los-mundiales-de-hockey-subacuatico\/","url_meta":{"origin":27994,"position":1},"title":"\ud83c\udde6\ud83c\uddf7 Argentina se prepara para figurar en los mundiales de Hockey Subacu\u00e1tico","author":"Sportalsub.net","date":"27 enero 2017","format":false,"excerpt":"(Sportalsub.net \/ AHSA) Cuatro entrenadores y m\u00e1s de 70 deportistas se preparan para hacer historia en Australia y Canad\u00e1. El entrenador colombiano, Sebasti\u00e1n Lugo, lleg\u00f3 al pa\u00eds para fortalecer el proceso. La meta es figurar entre los equipos m\u00e1s destacados en el mundo. Santa Fe, 27 de enero de 2017.\u2026","rel":"","context":"En \u00abArgentina\u00bb","block_context":{"text":"Argentina","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/argentina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/01\/ahsa1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/01\/ahsa1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/01\/ahsa1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/01\/ahsa1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/01\/ahsa1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/01\/ahsa1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":15660,"url":"https:\/\/www.sportalsub.net\/blog\/presentacion-de-seleccionados-argentinos-de-hockey-subacuatico-al-campeonato-mundial-hungria-2013\/","url_meta":{"origin":27994,"position":2},"title":"\ud83c\udde6\ud83c\uddf7 Presentaci\u00f3n de Seleccionados Argentinos de Hockey Subacu\u00e1tico al Campeonato Mundial Hungr\u00eda 2013","author":"Sportalsub.net","date":"19 julio 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ AHSA) La Asociaci\u00f3n de Hockey Subacu\u00e1tico de Argentina presenta los Seleccionados que estar\u00e1n participando en el 18vo Campeonato Mundial CMAS de Hockey Subacu\u00e1tico a realizarse del 23 de agosto al 1ro de septiembre de 2013 en Eger, Hungr\u00eda. Argentina participar\u00e1 con 4 equipos: \u00c9lite Masculino, Master Masculino,\u2026","rel":"","context":"En \u00abArgentina\u00bb","block_context":{"text":"Argentina","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/argentina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/07\/aregentina-hockeysub.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/07\/aregentina-hockeysub.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/07\/aregentina-hockeysub.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/07\/aregentina-hockeysub.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":25907,"url":"https:\/\/www.sportalsub.net\/blog\/primer-torneo-juvenil-hockeysub-argentina-2017","url_meta":{"origin":27994,"position":3},"title":"\ud83c\udde6\ud83c\uddf7 Primer Torneo Nacional Juvenil de Hockey Subacu\u00e1tico AHSA 2017 Santa F\u00e9, Argentina","author":"Sportalsub.net","date":"17 marzo 2017","format":false,"excerpt":"(Sportalsub.net \/ AHSA) El hockey subacu\u00e1tico Argentino sigue creciendo. Se acerca el Primer Torneo Nacional Juvenil de hockey subacu\u00e1tico. Van a competir jugadores de todo el pa\u00eds mientras se preparan para viajar al torneo mundial juvenil en julio 2017. Los d\u00edas 24 y 25 de marzo se realizar\u00e1 el Primer\u2026","rel":"","context":"En \u00abArgentina\u00bb","block_context":{"text":"Argentina","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/argentina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/03\/infantiljuvenilhockeysubargentina2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/03\/infantiljuvenilhockeysubargentina2017.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/03\/infantiljuvenilhockeysubargentina2017.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/03\/infantiljuvenilhockeysubargentina2017.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/03\/infantiljuvenilhockeysubargentina2017.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":25142,"url":"https:\/\/www.sportalsub.net\/blog\/sebastian-lugo-colombia-hockeysub-argentina","url_meta":{"origin":27994,"position":4},"title":"\ud83c\udde6\ud83c\uddf7 Sebasti\u00e1n Lugo de Colombia har\u00e1 parte del proceso de las Selecciones Argentinas de Hockey Subacu\u00e1tico","author":"Sportalsub.net","date":"9 octubre 2016","format":false,"excerpt":"(Sportalsub.net \/ El Estuche \/ AHSA) Sebasti\u00e1n Lugo, quien por casi 10 a\u00f1os ha sido entrenador del Club Cardumen de Actividades Subacu\u00e1ticas en Colombia, se suma este fin de semana al equipo de entrenadores que dirigir\u00e1 a las Selecciones Argentina con miras al Mundial Juvenil de 2017 en Australia y\u2026","rel":"","context":"En \u00abArgentina\u00bb","block_context":{"text":"Argentina","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/argentina\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/10\/sebastianlugo1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/10\/sebastianlugo1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/10\/sebastianlugo1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/10\/sebastianlugo1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/10\/sebastianlugo1.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/10\/sebastianlugo1.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":14452,"url":"https:\/\/www.sportalsub.net\/blog\/seleccion-master-de-argentina-de-hockey-subacuatico-logra-medalla-de-plata-en-copa-america\/","url_meta":{"origin":27994,"position":5},"title":"\ud83c\udde6\ud83c\uddf7 Selecci\u00f3n Master de Argentina de Hockey Subacu\u00e1tico logra medalla de plata en Copa Am\u00e9rica","author":"Sportalsub.net","date":"15 agosto 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ AHSA) La Selecci\u00f3n Master Argentina de Hockey Subacu\u00e1tico logr\u00f3 el segundo puesto en la Copa Am\u00e9rica, realizada en Milwaukee Estados Unidos entre el 7 y 11 de Agosto, siendo superados por Canad\u00e1 y venciendo a Estados Unidos en el cuadro general del evento. Gracias a este buen\u2026","rel":"","context":"En \u00abAmericas Cup Hockeysub 2012\u00bb","block_context":{"text":"Americas Cup Hockeysub 2012","link":"https:\/\/www.sportalsub.net\/blog\/category\/coberturas-especiales\/americas-cup-hockeysub-2012\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/08\/americas_cup.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/08\/americas_cup.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/08\/americas_cup.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/08\/americas_cup.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/ahsa1.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/27994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=27994"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/27994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/27995"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=27994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=27994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=27994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}