{"id":36,"date":"2008-05-14T10:04:21","date_gmt":"2008-05-14T14:04:21","guid":{"rendered":"http:\/\/www.sportalsub.net\/blog\/?p=36"},"modified":"2019-08-30T08:31:33","modified_gmt":"2019-08-30T12:31:33","slug":"espana-obtiene-la-tercera-posicion-en-el-1%c2%ba-cmas-european-junior-cup-de-natacion-con-aletas","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/espana-obtiene-la-tercera-posicion-en-el-1%c2%ba-cmas-european-junior-cup-de-natacion-con-aletas\/","title":{"rendered":"\ud83c\uddea\ud83c\uddf8 Espa\u00f1a obtiene la tercera posici\u00f3n en el 1\u00ba CMAS European Junior Cup de nataci\u00f3n con aletas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.masmar.com\/imagenes\/noticias\/naletes-piscina.jpg\" alt=\"\" width=\"395\" height=\"264\" \/><\/p>\n<p>Fotograf\u00eda: Jaume Minguell\/FECDAS<\/p>\n<p>El pasado 2 de mayo se disput\u00f3 el 1\u00ba CMAS EUROPEAN JUNIOR CUP de la disciplina nataci\u00f3n con aletas. As\u00ed pues, la ciudad italiana de Lignano Sabbiadoro se convirti\u00f3 durante unos d\u00edas en la ciudad del deporte subacu\u00e1tico, donde participantes provinentes de diferentes lugares de Europa se congregaron en la lucha por la primera posici\u00f3n en el campeonato.<\/p>\n<p><!--more--><\/p>\n<p><script type=\"text\/javascript\"><!-- google_ad_client = \"pub-2536780557231974\"; \/* 336x280, creado 7\/05\/08 *\/ google_ad_slot = \"0022130288\"; google_ad_width = 336; google_ad_height = 280; \/\/-->; \/\/ --&gt; \/\/ --&gt; \/\/ --&gt;<\/script><\/p>\n<p><script src=\"http:\/\/pagead2.googlesyndication.com\/pagead\/show_ads.js\" type=\"text\/javascript\"><\/script><\/p>\n<p>Los tres equipos convocados: Italia, Espa\u00f1a i Ucrania lucharon por el oro, en lo que fueron unas intensas jornadas que duraron des del viernes 2 hasta el lunes 5 de mayo.<\/p>\n<p>Los deportistas de la categor\u00eda j\u00fanior compitieron en diferentes pruebas que comprenden des de 50, 100, 200, 400, 1500 metros en superficie hasta la prueba de los 4&#215;200 i 4&#215;100 pasando por escafandra con el fin de ir sumando puntos i asegurarse la primera posici\u00f3n.<\/p>\n<p>Tras la lucha que mantuve el equipo espa\u00f1ol para conseguir el oro, \u00e9ste qued\u00f3 en una merecida tercera posici\u00f3n. El ganador fue Ucrania, seguido del equipo italiano.<\/p>\n<p>Fuente: <a href=\"http:\/\/www.masmar.com\/noticias\/html\/51197.html\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">http:\/\/www.masmar.com\/noticias\/html\/51197.html<\/a><\/p>\n<p class=\"entry\"><a href=\"http:\/\/sportalsub.scubastore.com\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" style=\"border: 0px;\" src=\"http:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2008\/04\/publicidadnadosub.jpg\" alt=\"\" width=\"450\" height=\"200\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fotograf\u00eda: Jaume Minguell\/FECDAS El pasado 2 de mayo se disput\u00f3 el 1\u00ba CMAS EUROPEAN JUNIOR CUP de la disciplina nataci\u00f3n con aletas. As\u00ed pues, la ciudad italiana de Lignano Sabbiadoro se convirti\u00f3 durante unos d\u00edas en la ciudad del deporte subacu\u00e1tico, donde participantes provinentes de diferentes lugares de Europa se congregaron en la lucha por la primera posici\u00f3n en el [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":16349,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[10,12],"tags":[],"class_list":["post-36","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espana","category-natacion-con-aletas"],"modified_by":"Sportalsub.net","views":6830,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-A","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":18945,"url":"https:\/\/www.sportalsub.net\/blog\/copa-mundo-cmas-2015-barcelona-espana","url_meta":{"origin":36,"position":0},"title":"\ud83c\uddea\ud83c\uddf8 Resultados y Video 3ra Ronda Copa Mundo CMAS Nataci\u00f3n con Aletas 2015. Barcelona, Espa\u00f1a","author":"Sportalsub.net","date":"27 marzo 2015","format":false,"excerpt":"(Sportalsub.net \/ CMAS\/FEDAS\/FECDAs\/ Finswimmer) \u2013 Read in English Con todo \u00e9xito culmin\u00f3 la copa del mundo de nataci\u00f3n con aletas celebrada\u00a0en Barcelona, Espa\u00f1a, el 21 y 22 de marzo 2015. Esta competici\u00f3n internacional es una de las pruebas m\u00e1s importantes del calendario de la nataci\u00f3n con aletas a nivel mundial.\u2026","rel":"","context":"En \u00abDestacados\u00bb","block_context":{"text":"Destacados","link":"https:\/\/www.sportalsub.net\/blog\/category\/mas\/destacados\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/02\/barcelona2015.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/02\/barcelona2015.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2015\/02\/barcelona2015.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":37,"url":"https:\/\/www.sportalsub.net\/blog\/los-nadadores-junior-del-cn-babel-brillan-con-espana-en-la-cmas-european-junior-trophy\/","url_meta":{"origin":36,"position":1},"title":"\ud83c\uddea\ud83c\uddf8 Los nadadores j\u00fanior del CN Babel brillan con Espa\u00f1a en la CMAS European Junior Trophy","author":"Sportalsub.net","date":"14 mayo 2008","format":false,"excerpt":"Los nadadores con aletas del Babel Alicante demuestran en cada cita deportiva que se encuentran al nivel de los mejores del mundo. V\u00edctor Alcal\u00e1, Mar\u00eda L\u00f3pez y Lara Garc\u00eda participaron el pasado fin de semana en la primera edici\u00f3n de la CMAS European Junior Trophy como integrantes de la selecci\u00f3n\u2026","rel":"","context":"En \u00abEspa\u00f1a\u00bb","block_context":{"text":"Espa\u00f1a","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/europa\/espana\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/13052008aletas.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12277,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-vii-copa-mundo-natacion-con-aletas-cmas-4ta-ronda-2012-polonia\/","url_meta":{"origin":36,"position":2},"title":"\ud83c\uddf5\ud83c\uddf1 Resultados VII Copa Mundo Nataci\u00f3n con Aletas CMAS \u2013 4ta Ronda 2012 \u2013 Polonia","author":"Sportalsub.net","date":"30 abril 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ CMAS World Cup \/ Finswimmer) Este fin de semana 28 y 29 de abril se realiz\u00f3 en Gliwice, Polonia la 3ra Ronda de la Copa Mundo de Nataci\u00f3n con Aletas CMAS 2012, en la cual se registraron 3 nuevos r\u00e9cords mundiales junior. En la prueba de 50\u2026","rel":"","context":"En \u00abDestacados Anteriores\u00bb","block_context":{"text":"Destacados Anteriores","link":"https:\/\/www.sportalsub.net\/blog\/category\/coberturas-especiales\/destacados-anteriores\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/polonia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/polonia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/polonia.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":12627,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-vii-copa-mundo-natacion-con-aletas-cmas-5ta-ronda-2012-espana\/","url_meta":{"origin":36,"position":3},"title":"\ud83c\uddea\ud83c\uddf8 Resultados VII Copa Mundo Nataci\u00f3n con Aletas CMAS \u2013 5ta Ronda 2012 \u2013 Espa\u00f1a","author":"Sportalsub.net","date":"1 junio 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ FEDAS-FBDAS \/ CMAS) Del 25 al 27 de mayo se realiz\u00f3 en Palma de Mallorca, Espa\u00f1a la 5ta Ronda de la VII Copa del Mundo CMAS de Nataci\u00f3n con Aletas, en la cual Colombia obtuvo un excelente resultando, dominando algunas de las pruebas y con una gran\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/copamundopalma.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/copamundopalma.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/copamundopalma.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":17442,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-ix-copa-mundo-natacion-con-aletas-cmas-2da-ronda-2014-italia\/","url_meta":{"origin":36,"position":4},"title":"\ud83c\uddee\ud83c\uddf9 Resultados IX Copa Mundo Nataci\u00f3n con Aletas CMAS \u2013 2da Ronda 2014 \u2013 Italia","author":"Sportalsub.net","date":"16 marzo 2014","format":false,"excerpt":"Nuevo R\u00e9cord Mundial 200 superficie femenino Valeria Baranovskaya de Rusia (1:27,22) (Especial Sportalsub.net \/ CMAS \/ FIPSAS\/ Finswimmer) Este fin de semana, s\u00e1bado 15 y domingo 16 de marzo se realiz\u00f3 en Lignano Sabbiadoro-Italia,\u00a0\u00a0la 2da Ronda de la IX Copa del Mundo de Nataci\u00f3n con Aletas CMAS, con la presencia\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/03\/ronda-italia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/03\/ronda-italia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/03\/ronda-italia.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":17272,"url":"https:\/\/www.sportalsub.net\/blog\/13er-campeonato-mundial-junior-de-natacion-con-aletas-cmas-grecia-2014\/","url_meta":{"origin":36,"position":5},"title":"\ud83c\uddec\ud83c\uddf7 13er Campeonato Mundial Junior de Nataci\u00f3n con Aletas CMAS Grecia 2014","author":"Sportalsub.net","date":"27 junio 2014","format":false,"excerpt":"(Especial Sportalsub.net \/ CMAS \/ KOE \/ Finswimmer) La Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas y la Federaci\u00f3n Griega de Nataci\u00f3n organizan el 13er Campeonato Mundial Junior de Nataci\u00f3n con Aletas, a realizarse en Chania, Grecia, del 25 al 30 de junio de 2014. En el evento participan las selecciones de\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/01\/junior-grecia.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/01\/junior-grecia.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/01\/junior-grecia.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/11\/naletes-piscina.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/36\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/16349"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=36"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=36"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}