{"id":40125,"date":"2020-03-21T14:39:59","date_gmt":"2020-03-21T18:39:59","guid":{"rendered":"https:\/\/www.sportalsub.net\/blog\/?p=40125"},"modified":"2020-04-02T01:52:27","modified_gmt":"2020-04-02T05:52:27","slug":"%f0%9f%87%ae%f0%9f%87%b9-umberto-pelizzari-comparte-sus-experiencias-en-el-mundo-de-la-apnea-en-facebook-live","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/umberto-pelizzari-apnea-facebook-live","title":{"rendered":"\ud83c\uddee\ud83c\uddf9 Umberto Pelizzari comparte sus experiencias en el mundo de la apnea en Facebook Live"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-40126\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/pelizzari-live.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/pelizzari-live.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/pelizzari-live-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/pelizzari-live-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/pelizzari-live-177x118.jpg 177w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>(Sportalsub.net \/ Umberto Pelizzari) &#8211; <a href=\"https:\/\/www.sportalsub.net\/en\/umberto-pelizzari-apnea-facebook-live\">Read in English<\/a><\/p>\n<p>El reconocido apneista italiano Umberto Pelizzari, varias veces campe\u00f3n, recordista mundial y fundador de <a href=\"https:\/\/apnea.academy\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Apnea Academy<\/a>, ha aprovechado tambi\u00e9n los d\u00edas de cuarentena, producto de la pandemia mundial del coronavirus COVID-19, para compartir a trav\u00e9s de varios videos en facebook live, consejos, tips, an\u00e9cdotas y parte de su amplia y gran experiencia mundial como una de las figuras con mayor trayectoria y trascendencia en la historia de la apnea.<\/p>\n<p>Los videos de las transmisiones realizadas, est\u00e1n disponibles en la <a href=\"https:\/\/www.facebook.com\/umberto.pelizzari.official\/videos\/?ref=page_internal\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">secci\u00f3n de videos<\/a> su p\u00e1gina oficial en facebook: <a href=\"https:\/\/www.facebook.com\/umberto.pelizzari.official\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">facebook.com\/umberto.pelizzari.official.<\/a> De igual forma, Pelizzari estar\u00e1 anunciando sus pr\u00f3ximos videos y transmisiones a trav\u00e9s de esta red social.<\/p>\n<p>Puedes conocer m\u00e1s de Umberto en su p\u00e1gina web oficial <a href=\"https:\/\/www.umbertopelizzari.com\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">www.umbertopelizzari.com<\/a>\u00a0seguirlo en su cuenta en Instagram: <a href=\"https:\/\/www.instagram.com\/umberto_pelizzari\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">@umberto_pelizzari<\/a> y ver sus videos en su <a href=\"https:\/\/www.youtube.com\/channel\/UC8u7fXnOOVKRJxRy-eq371g\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">canal en youtube<\/a><\/p>\n<p>Una gran oportunidad para conocer y aprender m\u00e1s del mundo de la apnea de la mano de este gran #SerSubacuatico<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ Umberto Pelizzari) &#8211; Read in English El reconocido apneista italiano Umberto Pelizzari, varias veces campe\u00f3n, recordista mundial y fundador de Apnea Academy, ha aprovechado tambi\u00e9n los d\u00edas de cuarentena, producto de la pandemia mundial del coronavirus COVID-19, para compartir a trav\u00e9s de varios videos en facebook live, consejos, tips, an\u00e9cdotas y parte de su amplia y gran experiencia [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":40126,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,347,118],"tags":[448],"class_list":["post-40125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-destacados","category-italia","tag-covid-19"],"modified_by":"Sportalsub.net","views":2446,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/pelizzari-live.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-arb","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":40760,"url":"https:\/\/www.sportalsub.net\/blog\/pelizzari-apnea-venezuela-instagram","url_meta":{"origin":40125,"position":0},"title":"\ud83c\uddfb\ud83c\uddea Umberto Pelizzari convers\u00f3 sobre apnea para Venezuela a trav\u00e9s de Instagram Live","author":"Sportalsub.net","date":"19 abril 2020","format":false,"excerpt":"(Sportalsub.net \/ FVAS \/ COV) Como parte del Ciclo de Saberes Ol\u00edmpicos, promovido por el Comit\u00e9 Ol\u00edmpico Venezolano, este s\u00e1bado 18 de abril de 2020 a las 2:00 pm (hora de Venezuela), el reconocido Instructor de Apnea Italiano Umberto Pelizzari estuvo realizando un encuentro en Vivo en espa\u00f1ol, a trav\u00e9s\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/04\/hablemosdeapnea.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/04\/hablemosdeapnea.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/04\/hablemosdeapnea.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/04\/hablemosdeapnea.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3608,"url":"https:\/\/www.sportalsub.net\/blog\/record-de-apnea-de-umberto-pelizzari\/","url_meta":{"origin":40125,"position":1},"title":"\ud83c\uddee\ud83c\uddf9 R\u00e9cord de Apnea de Umberto Pelizzari","author":"Sportalsub.net","date":"15 noviembre 2001","format":false,"excerpt":"Una vez m\u00e1s, Umberto Pelizzari sorprende al mundo de la Apnea, al romper en la localidad Italiana de Capri, el R\u00e9cord Mundial de Apnea en la modalidad de Peso Variable. (Italia \/ Noviembre 2001) A menos de un mes de haber conquistado junto a sus compa\u00f1eros de la selecci\u00f3n Italiana\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.apneamagazine.com\/apnea\/pelo2\/umberto_pelizzari_2.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":60033,"url":"https:\/\/www.sportalsub.net\/blog\/mia-freediving-workshop-2023","url_meta":{"origin":40125,"position":2},"title":"\ud83c\uddfa\ud83c\uddf8 MIA Freediving Workshop taller de apnea con Umberto Pelizzari en Miami, Florida USA Abril 2023","author":"Sportalsub.net","date":"26 marzo 2023","format":false,"excerpt":"(Sportalsub.net \/ MIA SENSE \/ FG0) - Read in english MIA Sense y la Escuela Americana de Apnea Freedive Gravedad Cero anuncian la realizaci\u00f3n del taller de apnea \"MIA Freediving Workshop\" con el italiano Umberto Pelizzari, reconocido apneista, m\u00faltiple recordista y campe\u00f3n mundial, instructor fundador de Apnea Academy y autor\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/01\/miafreedivingworkshop2022.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/01\/miafreedivingworkshop2022.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/01\/miafreedivingworkshop2022.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/01\/miafreedivingworkshop2022.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":44456,"url":"https:\/\/www.sportalsub.net\/blog\/7-libros-sobre-el-buceo-en-apnea-que-todo-apneista-deberia-leer\/","url_meta":{"origin":40125,"position":3},"title":"\ud83d\udcd8 7 libros sobre el buceo en apnea, que todo apneista deber\u00eda leer","author":"Sportalsub.net","date":"11 enero 2021","format":false,"excerpt":"(Especial Sportalsub.net) - Leer en Ingl\u00e9s La apnea es un deporte estimulante y estimulante. Si bien no existe un reemplazo para los cursos y la capacitaci\u00f3n oficiales de buceo libre, hay una serie de libros brillantes que pueden ayudarlo a desarrollar sus habilidades, t\u00e9cnicas y conocimientos. Tanto si eres nuevo\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/freedivingbooks.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/freedivingbooks.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/freedivingbooks.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/freedivingbooks.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":40318,"url":"https:\/\/www.sportalsub.net\/blog\/ocean-men-pelizzari-pipin","url_meta":{"origin":40125,"position":4},"title":"\ud83c\udfa5 Ocean Men: la historia de Umberto Pelizzari y Pipin Ferreras, pel\u00edcula-documental completa online","author":"Sportalsub.net","date":"11 abril 2020","format":false,"excerpt":"(Sportalsub.net \/ Oceanmen) - Read in English OCEAN MEN es una pel\u00edcula - documental estrenada en agosto 2001, en donde aparece Jacques Mayol narrando la forma en que estos dos grandes referentes de la Apnea (Pip\u00edn Ferreras y Umberto Pelizzari) se preparan para realizar sus inmersiones. Un deporte real que\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/04\/oceanmen.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/04\/oceanmen.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/04\/oceanmen.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/04\/oceanmen.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4539,"url":"https:\/\/www.sportalsub.net\/blog\/revista-digital-sportsub-numero-1","url_meta":{"origin":40125,"position":5},"title":"\ud83c\udf0e Revista Digital Sportsub N\u00famero 1 \/ Enero-Febrero 2003","author":"Sportalsub.net","date":"15 enero 2003","format":false,"excerpt":"EDITORIAL Un nuevo Medio\u2026Una nueva etapa\u2026 Hace poco mas de dos a\u00f1os, naci\u00f3 la idea de crear un lugar, un medio, un punto de encuentro para todas aquellas personas interesadas en el maravilloso mundo de las Actividades Subacu\u00e1ticas, en donde pudieran encontrar informaci\u00f3n de inter\u00e9s y poder compartir con otras\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2003\/01\/sportsub1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/40125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=40125"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/40125\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/40126"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=40125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=40125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=40125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}