{"id":41147,"date":"2020-07-12T20:15:32","date_gmt":"2020-07-13T00:15:32","guid":{"rendered":"https:\/\/www.sportalsub.net\/blog\/?p=41147"},"modified":"2020-07-12T20:15:32","modified_gmt":"2020-07-13T00:15:32","slug":"%f0%9f%87%a6%f0%9f%87%b7-entrevista-a-francisco-lacase-en-sersubacuatico-com","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/entrevista-a-francisco-lacase-en-sersubacuatico","title":{"rendered":"\ud83c\udde6\ud83c\uddf7 Entrevista a Francisco Lacase en SerSubacuatico.com"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-41148\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/francisco.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/francisco.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/francisco-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/francisco-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/francisco-450x300.jpg 450w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p><span class=\"style-scope yt-formatted-string\" dir=\"auto\">Entrevista de Miguel Cede\u00f1o a<strong> Francisco Lacase,<\/strong> Secretario General de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas Zona Am\u00e9rica y Presidente de la Federaci\u00f3n Argentina de Actividades Subacu\u00e1ticas.<\/span><\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"860\" height=\"484\" src=\"https:\/\/www.youtube.com\/embed\/yeliLlGimPc?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=es-ES&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/p>\n<p>Estreno: Domingo 12 de Julio de 2020.<br \/>\n19:00 Colombia, Ecuador, M\u00e9xico<br \/>\n20:00 Chile, Venezuela<br \/>\n21:00 Argentina, Uruguay<br \/>\nCanal de Youtube de Sportalsub<\/p>\n<p>Link al Video en Estreno: <a href=\"https:\/\/youtu.be\/yeliLlGimPc\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/youtu.be\/yeliLlGimPc<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrevista de Miguel Cede\u00f1o a Francisco Lacase, Secretario General de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas Zona Am\u00e9rica y Presidente de la Federaci\u00f3n Argentina de Actividades Subacu\u00e1ticas. Estreno: Domingo 12 de Julio de 2020. 19:00 Colombia, Ecuador, M\u00e9xico 20:00 Chile, Venezuela 21:00 Argentina, Uruguay Canal de Youtube de Sportalsub Link al Video en Estreno: https:\/\/youtu.be\/yeliLlGimPc &nbsp;<\/p>\n","protected":false},"author":1,"featured_media":41148,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,4,186,153,19,2,12,18],"tags":[450],"class_list":["post-41147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-argentina","category-buceo-2","category-entrevistas","category-fotografia-submarina","category-hockey-subacuatico","category-natacion-con-aletas","category-pesca-submarina","tag-destacados"],"modified_by":"Sportalsub.net","views":1857,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-aHF","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":43622,"url":"https:\/\/www.sportalsub.net\/blog\/entrevista-a-gilda-rivadeneira-y-roberto-ochoa-en-sersubacuatico-com\/","url_meta":{"origin":41147,"position":0},"title":"\ud83c\uddea\ud83c\udde8 Entrevista a Gilda Rivadeneira y Roberto Ochoa en SerSubacuatico.com","author":"Sportalsub.net","date":"3 diciembre 2020","format":false,"excerpt":"Entrevista de Miguel Cede\u00f1o a los Ecuatorianos: Gilda Rivadeneira, Recordista Mundial, Campeona Panamericana e Instructora de Apnea y a Roberto Ochoa,\u00a0 vide\u00f3grafo subacu\u00e1tico y Presidente de la Federaci\u00f3n Ecuatoriana de Buceo y Actividades Subacu\u00e1ticas (FEDASUB) para SerSubacuatico.com Estreno: Jueves 3 de Diciembre 2020 19:00 M\u00e9xico 20:00 Colombia, Ecuador 21:00 Venezuela\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/12\/gildayroberto.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/12\/gildayroberto.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/12\/gildayroberto.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/12\/gildayroberto.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":45182,"url":"https:\/\/www.sportalsub.net\/blog\/entrevista-a-jeannette-ferraro-en-sersubacuatico","url_meta":{"origin":41147,"position":1},"title":"\ud83c\uddfa\ud83c\uddfe Entrevista a Jeannette Ferraro en SerSubacuatico.com","author":"Sportalsub.net","date":"30 marzo 2021","format":false,"excerpt":"(Sportalsub.net \/ SerSubacuatico.com) Entrevista de Miguel Cede\u00f1o a Jeannette Ferraro, Presidenta de la Federaci\u00f3n Uruguaya de Actividades Subacu\u00e1ticas (FUAS). Estreno: Martes 30 de Marzo de 2021. 18:00 M\u00e9xico 19:00 Colombia, Ecuador, Per\u00fa 20:00 Venezuela 21:00 Argentina, Chile, Uruguay Canal de Youtube de Sportalsub Link al video en estreno: https:\/\/youtu.be\/iaDSTGNKoM0 Fuente:\u2026","rel":"","context":"En \u00abBuceo Adaptado\u00bb","block_context":{"text":"Buceo Adaptado","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/buceo-adaptado\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/03\/jeannette.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/03\/jeannette.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/03\/jeannette.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/03\/jeannette.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":41167,"url":"https:\/\/www.sportalsub.net\/blog\/entrevista-a-juan-jose-maldonado-en-sersubacuatico","url_meta":{"origin":41147,"position":2},"title":"\ud83c\udde8\ud83c\uddf1 Entrevista a Juan Jos\u00e9 Maldonado en SerSubacuatico.com","author":"Sportalsub.net","date":"22 julio 2020","format":false,"excerpt":"(Sportalsub.net \/ SerSubacuatico.com) Entrevista de Miguel Cede\u00f1o a Juan Jos\u00e9 Maldonado, Gerente General de la Federaci\u00f3n Deportiva Nacional de Actividades Subacu\u00e1ticas y Salvamento Acu\u00e1tico de Chile (FEDESUB\/CMAS Chile) y Director del Comit\u00e9 T\u00e9cnico de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas Zona Am\u00e9rica (CMAS Am\u00e9rica). Estreno: Jueves 23 de Julio de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/juanjo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/juanjo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/juanjo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/juanjo.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":50485,"url":"https:\/\/www.sportalsub.net\/blog\/entrevista-a-juan-manuel-gomez-en-sersubacuatico","url_meta":{"origin":41147,"position":3},"title":"\ud83c\uddf2\ud83c\uddfd Entrevista a Juan Manuel G\u00f3mez en SerSubacuatico.com","author":"Sportalsub.net","date":"3 diciembre 2021","format":false,"excerpt":"(Sportalsub.net \/ SerSubacuatico.com) Entrevista de\u00a0Miguel Cede\u00f1o a Juan Manuel G\u00f3mez Valencia, Instructor de Buceo, Presidente de la Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas (FMAS) y miembro del Consejo Directivo de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS) para SerSubacuatico.com Link al Video en Estreno: https:\/\/youtu.be\/ysP78Gn3UUs Estreno: Viernes 3 de Diciembre 2021\u2026","rel":"","context":"En \u00abBuceo\u00bb","block_context":{"text":"Buceo","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/12\/juangomez-web.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/12\/juangomez-web.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/12\/juangomez-web.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/12\/juangomez-web.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":24776,"url":"https:\/\/www.sportalsub.net\/blog\/francisco-lacase-presidente-de-la-federacion-argentina-de-actividades-subacuaticas\/","url_meta":{"origin":41147,"position":4},"title":"\ud83c\udde6\ud83c\uddf7 Conversando con Francisco Lacase, presidente de la Federaci\u00f3n Argentina de Actividades Subacu\u00e1ticas","author":"Sportalsub.net","date":"30 julio 2016","format":false,"excerpt":"(Sportalsub.net \/ FAAS, por Miguel A. Cede\u00f1o O.) El pasado jueves 28 de julio, en la ciudad de Santiago de Chile, tuvimos la oportunidad de compartir una interesante conversaci\u00f3n con Francisco Lacase\u00a0presidente de la Federaci\u00f3n Argentina de Actividades Subacu\u00e1ticas\u00a0quien nos cont\u00f3 sobre el trabajo que ha venido desarrollando al frente\u2026","rel":"","context":"En \u00abActividades Subacu\u00e1ticas\u00bb","block_context":{"text":"Actividades Subacu\u00e1ticas","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/07\/francisco-miguel.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/07\/francisco-miguel.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/07\/francisco-miguel.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/07\/francisco-miguel.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/07\/francisco-miguel.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":40989,"url":"https:\/\/www.sportalsub.net\/blog\/entrevista-a-coty-zeckua-en-sersubacuatico","url_meta":{"origin":41147,"position":5},"title":"\ud83c\uddf2\ud83c\uddfd Entrevista a Coty Zeckua en SerSubacuatico.com","author":"Sportalsub.net","date":"10 junio 2020","format":false,"excerpt":"(Sportalsub.net \/ SerSubacuatico.com) Entrevista de Miguel Cede\u00f1o a Maria Clotilde \"Coty\" Zeckua Ramos, Directora del Comit\u00e9 Cient\u00edfico de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas Zona Am\u00e9rica y de la Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas. Estreno: Mi\u00e9rcoles 10 de Junio de 2020. 7:00pm Hora de M\u00e9xico \/ 8:00pm Hora de Venezuela\u2026","rel":"","context":"En \u00abBuceo Cient\u00edfico\u00bb","block_context":{"text":"Buceo Cient\u00edfico","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/buceo-cientifico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/06\/coty.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/06\/coty.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/06\/coty.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/06\/coty.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/07\/francisco.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/41147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=41147"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/41147\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/41148"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=41147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=41147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=41147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}