{"id":41318,"date":"2020-10-22T07:44:36","date_gmt":"2020-10-22T11:44:36","guid":{"rendered":"https:\/\/www.sportalsub.net\/blog\/?p=41318"},"modified":"2020-11-03T08:07:22","modified_gmt":"2020-11-03T12:07:22","slug":"%f0%9f%8c%8e-cmas-zona-america-y-fmas-dictaran-curso-de-estrategias-de-comunicacion-y-consolidacion-de-reputacion-para-sus-federaciones-afiliadas","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/cmas-america-fmas-curso-comunicaciones","title":{"rendered":"\ud83c\udf0e CMAS Zona Am\u00e9rica y FMAS dictaron curso de estrategias de comunicacio\u0301n para Federaciones de actividades subacu\u00e1ticas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-42873\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/realizadocursocomunicaciones.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/realizadocursocomunicaciones.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/realizadocursocomunicaciones-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/realizadocursocomunicaciones-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/realizadocursocomunicaciones-450x300.jpg 450w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>(Sportalsub.net \/ CMAS Zona Am\u00e9rica \/ FMAS)<\/p>\n<p>La Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas (FMAS), mediante el \u00e1rea de Comunicaci\u00f3n Social y con el aval de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS) Zona Am\u00e9rica realiz\u00f3 el primer encuentro sobre el \u00e1rea de la comunicaci\u00f3n para Federaciones Deportivas.<\/p>\n<p>Durante las sesiones\u00a0impartidas por el consultor en comunicaci\u00f3n y titular de Comunicaci\u00f3n Social de la FMAS; Jos\u00e9 Luis Cruz V., se abordaron temas como la importancia de la comunicaci\u00f3n interna, el plan de desarrollo de relaciones interinstitucionales, relaci\u00f3n con medios de comunicaci\u00f3n, importancia de la imagen p\u00fablica, as\u00ed como la formaci\u00f3n de vocer\u00eda y la identificaci\u00f3n de crisis de reputaci\u00f3n.<\/p>\n<p>Como resultado de la capacitaci\u00f3n, las intervenciones realizadas por parte de los interesados en cada uno de los temas dieron pie a la profundizaci\u00f3n, mismos que incluso han permitido ampliar el panorama de los posibles objetivos a futuro, con la finalidad de unificar las actividades subacu\u00e1ticas a nivel continente, impulsando el desarrollo y continuando con la profesionalizaci\u00f3n de las especialidades que engloba a la CMAS Zona Am\u00e9rica, al frente del colombiano William Pe\u00f1a.<\/p>\n<p>El curso: Estrategias de comunicacio\u0301n y consolidacio\u0301n de reputacio\u0301n para Federaciones afiliadas a la CMAS Zona Ame\u0301rica, se desarroll\u00f3 en la modalidad en linea los d\u00edas 6, 8, 10, 13, 15 y 17 de octubre, al que se dieron cita m\u00e1s de tres decenas de participantes afiliados a las Federaciones de Argentina (FAAS), Colombia (FEDECAS), Venezuela (FVAS) y M\u00e9xico (FMAS).<\/p>\n<p>Al finalizar el encuentro, se procedi\u00f3 formalmente a la clausura, que estuvo acompa\u00f1ada por el Presidente de la CMAS Zona Am\u00e9rica y de la FEDECAS; William Pe\u00f1a, el Presidente de la FAAS; Francisco Lacase, ambos miembros de bur\u00f3 internacional de Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS), as\u00ed como Miguel Cede\u00f1o; miembro de la FVAS y gestor tecnol\u00f3gico de la CMAS Zona Am\u00e9rica, al igual que Juan Manuel G\u00f3mez; Presidente de la FMAS, tambi\u00e9n se cont\u00f3 con la participaci\u00f3n de Maria Clotilde Zeckua Ramos; Directora de Biolog\u00eda y Conservaci\u00f3n de la CMAS, durante el acto oficial se hizo entrega de manera virtual de las constancias de participaci\u00f3n a las organizaciones.<\/p>\n<p>Video Clausura oficial:<\/p>\n<p><iframe loading=\"lazy\" title=\"Clausura del Curso Estrategias de comunicacio\u0301n y consolidacio\u0301n de reputacio\u0301n para Federaciones\" src=\"https:\/\/www.youtube.com\/embed\/8tflx7gyXJ8?feature=oembed\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2292\" src=\"https:\/\/www.fmas.org.mx\/wp-content\/uploads\/2020\/07\/FMAS-VERTICAL-1.png\" alt=\"\" width=\"125\" height=\"96\" \/><\/p>\n<p><a href=\"https:\/\/www.fmas.org.mx\/realiza-fmas-y-cmas-zona-america-primer-encuentro-de-comunicacion-para-federaciones\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\"><strong>Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas, A. C.<\/strong><\/a><\/p>\n<hr \/>\n<p>La Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas, A. C., con el aval de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas Zona Am\u00e9rica, dio inicio este martes 6 de octubre 2020 al:\u00a0<strong>Curso de estrategias de comunicaci\u00f3n y consolidaci\u00f3n de reputaci\u00f3n\u00a0para Federaciones afiliadas a la\u00a0<\/strong><strong>C.M.A.S. Zona Am\u00e9rica<\/strong><\/p>\n<div id=\"gallery-1\" class=\"gallery galleryid-3231 gallery-columns-2 gallery-size-medium\">\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso2.jpg\"class=\"fancyboxforwp\"  data-fancybox=\"gallery\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-medium size-medium\" src=\"https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso2-300x169.jpg\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso2-300x169.jpg 300w, https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso2-1024x576.jpg 1024w, https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso2-768x432.jpg 768w, https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso2.jpg 1080w\" alt=\"\" width=\"300\" height=\"169\" \/><\/a><\/div>\n<\/figure>\n<figure class=\"gallery-item\">\n<div class=\"gallery-icon landscape\"><a href=\"https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso1.jpg\"class=\"fancyboxforwp\"  data-fancybox=\"gallery\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"attachment-medium size-medium\" src=\"https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso1-300x169.jpg\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" srcset=\"https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso1-300x169.jpg 300w, https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso1-1024x576.jpg 1024w, https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso1-768x432.jpg 768w, https:\/\/www.cmasamerica.org\/wp-content\/uploads\/2020\/09\/curso1.jpg 1280w\" alt=\"\" width=\"300\" height=\"169\" \/><\/a><\/div>\n<\/figure>\n<\/div>\n<h3><strong><a href=\"https:\/\/www.fmas.org.mx\/wp-content\/uploads\/2020\/09\/Curso-comunicacio%CC%81n-FMAS-CMAS-.pdf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">CONVOCATORIA<\/a>\u00a0(PDF)<\/strong><\/h3>\n<p><strong>M\u00e1s informaci\u00f3n: <a href=\"https:\/\/www.fmas.org.mx\/curso-de-comunicacion-a-federaciones-cmas-america\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">FMAS<\/a> \/ <a href=\"https:\/\/www.cmasamerica.org\/curso-de-comunicacion-a-federaciones-cmas-america\/\" target=\"_blank\">CMAS Zona Am\u00e9rica<\/a><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-41325\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/curso-comunicacion-cmasamerica.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/curso-comunicacion-cmasamerica.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/curso-comunicacion-cmasamerica-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/curso-comunicacion-cmasamerica-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/curso-comunicacion-cmasamerica-450x300.jpg 450w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ CMAS Zona Am\u00e9rica \/ FMAS) La Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas (FMAS), mediante el \u00e1rea de Comunicaci\u00f3n Social y con el aval de la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS) Zona Am\u00e9rica realiz\u00f3 el primer encuentro sobre el \u00e1rea de la comunicaci\u00f3n para Federaciones Deportivas. Durante las sesiones\u00a0impartidas por el consultor en comunicaci\u00f3n y titular de Comunicaci\u00f3n Social [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":42873,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[117,112,98],"tags":[],"class_list":["post-41318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-modalidades","category-cursos-y-talleres","category-mexico"],"modified_by":"Sportalsub.net","views":2304,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-aKq","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":18587,"url":"https:\/\/www.sportalsub.net\/blog\/8vo-curso-internacional-buceo-cientifico-cmas-america-mexico","url_meta":{"origin":41318,"position":0},"title":"\ud83c\uddf2\ud83c\uddfd Se realiz\u00f3 el 8vo. Curso Internacional de Buceo Cient\u00edfico FMAS \/ CMAS Zona Am\u00e9rica M\u00e9xico 2014","author":"Sportalsub.net","date":"25 noviembre 2014","format":false,"excerpt":"(Especial Sportalsub.net \/ FMAS \/ CMAS Zona Am\u00e9rica) Ciudad de M\u00e9xico. \u00a0Con importante presencia de participantes de Espa\u00f1a, Gran Breta\u00f1a y M\u00e9xico se llev\u00f3 a cabo el 8\u00ba. Curso Internacional de Buceo Cient\u00edfico a trav\u00e9s del Comit\u00e9 Cient\u00edfico de la Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas (CMAS) y el \u00e1rea correspondiente\u2026","rel":"","context":"En \u00abBuceo Cient\u00edfico\u00bb","block_context":{"text":"Buceo Cient\u00edfico","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/buceo-cientifico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/11\/8vo-curso-cientifico.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/11\/8vo-curso-cientifico.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/11\/8vo-curso-cientifico.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/11\/8vo-curso-cientifico.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12743,"url":"https:\/\/www.sportalsub.net\/blog\/federacion-mexicana-de-actividades-subacuaticas-presente-en-el-dia-mundial-de-los-oceanos-2012\/","url_meta":{"origin":41318,"position":1},"title":"\ud83c\uddf2\ud83c\uddfd Federaci\u00f3n Mexicana de Actividades Subacu\u00e1ticas presente en el \u00abD\u00eda Mundial de los Oceanos 2012\u00bb","author":"Sportalsub.net","date":"19 junio 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ FMAS) En el bello Puerto de Acapulco, importante destino tur\u00edstico nacional e internacional y considerado el lugar de origen del Buceo en Am\u00e9rica Latina, el d\u00eda ocho de junio, se celebr\u00f3 el \u201cD\u00eda Mundial de los Oc\u00e9anos 2012\u201d conmemoraci\u00f3n resultante de una iniciativa canadiense en 1992, en\u2026","rel":"","context":"En \u00abBuceo Cient\u00edfico\u00bb","block_context":{"text":"Buceo Cient\u00edfico","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/buceo-cientifico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/FMAS-oceanos1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/FMAS-oceanos1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/06\/FMAS-oceanos1.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":13281,"url":"https:\/\/www.sportalsub.net\/blog\/6to-curso-internacional-de-buceo-cientifico-fmas-cmas-zona-america-mexico-2012\/","url_meta":{"origin":41318,"position":2},"title":"\ud83c\uddf2\ud83c\uddfd Finaliza con \u00e9xito el 6to Curso Internacional de Buceo Cient\u00edfico FMAS-CMAS Zona Am\u00e9rica. M\u00e9xico. 19-25 noviembre 2012","author":"Sportalsub.net","date":"20 diciembre 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ FMAS \/ CMAS Zona Am\u00e9rica) Lleg\u00f3 a buen t\u00e9rmino el 6\u00ba. Curso de Buceo Cient\u00edfico FMAS-CMAS M\u00e9xico, D.F. A 06 de diciembre de 2012. Con la participaci\u00f3n de profesionales e investigadores de M\u00e9xico y Cuba, se desarroll\u00f3 el 6to. Curso Internacional de Buceo Cient\u00edfico FMAS-CMAS Zona Am\u00e9rica,\u2026","rel":"","context":"En \u00abBuceo Cient\u00edfico\u00bb","block_context":{"text":"Buceo Cient\u00edfico","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/buceo-cientifico\/"},"img":{"alt_text":"curso-cientifico-mex","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/12\/curso-cientifico-mex.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":17204,"url":"https:\/\/www.sportalsub.net\/blog\/1er-curso-internacional-de-instructores-de-buceo-subterraneo-cmas-zona-america\/","url_meta":{"origin":41318,"position":3},"title":"\ud83c\udde8\ud83c\uddfa Concluye con \u00e9xito 1er Curso Internacional de Instructores de Buceo Subterr\u00e1neo CMAS Zona Am\u00e9rica","author":"Sportalsub.net","date":"5 junio 2014","format":false,"excerpt":"(Especial Sportalsub.net \/ CMAS Zona Am\u00e9rica \/ FMAS \/ FCAS) Matanzas, Cuba. A 03 de junio de 2014. Por Coty Zeckua Ramos En Playa Gir\u00f3n de esta localidad se desarroll\u00f3 el 1er. Curso Internacional para Instructores de Buceo Subterr\u00e1neo CMAS Zona Am\u00e9rica, del 26 al 31 de mayo, a trav\u00e9s\u2026","rel":"","context":"En \u00abBuceo Cient\u00edfico\u00bb","block_context":{"text":"Buceo Cient\u00edfico","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/buceo-cientifico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/01\/buceo-cuba.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5236,"url":"https:\/\/www.sportalsub.net\/blog\/2do-curso-internacional-de-buceo-cienti%cc%81fico-fmas-cmas-zona-ame%cc%81rica\/","url_meta":{"origin":41318,"position":4},"title":"\ud83c\uddf2\ud83c\uddfd 2do. Curso Internacional de Buceo Cienti\u0301fico FMAS-CMAS Zona Ame\u0301rica","author":"Sportalsub.net","date":"8 junio 2010","format":false,"excerpt":"La Federacio\u0301n Mexicana de Actividades Subacua\u0301ticas (FMAS), con el apoyo y aval de CMAS Zona Ame\u0301rica, convocan al 2do. Curso Internacional de Buceo Cienti\u0301fico de acuerdo a los esta\u0301ndares establecidos por la CMAS para los 3 niveles de Buceador Cienti\u0301fico. El curso se realizara\u0301 en la Reserva de la Bio\u0301sfera\u2026","rel":"","context":"En \u00abBuceo Cient\u00edfico\u00bb","block_context":{"text":"Buceo Cient\u00edfico","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/buceo-cientifico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2010\/06\/curso_buceo_cientifico.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":12227,"url":"https:\/\/www.sportalsub.net\/blog\/culmino-con-exito-el-5to-curso-internacional-de-buceo-cientifico-fmas-cmas-zona-america\/","url_meta":{"origin":41318,"position":5},"title":"\ud83c\uddf2\ud83c\uddfd Culmin\u00f3 con \u00e9xito el 5to. Curso Internacional de Buceo Cient\u00edfico FMAS-CMAS Zona Am\u00e9rica","author":"Sportalsub.net","date":"27 abril 2012","format":false,"excerpt":"(Especial Sportalsub.net \/ FMAS \/ CMAS Am\u00e9rica) M\u00e9xico, D.F. A 24 de Abril de 2012. - En la Reserva de la Bi\u00f3sfera de Banco Chinchorro Quintana Roo M\u00e9xico, uno de los sitios m\u00e1s pr\u00edstinos del Arrecife Mesoamericano, cubriendo las expectativas de participantes y directivos de la Federaci\u00f3n Mexicana de Actividades\u2026","rel":"","context":"En \u00abBuceo Cient\u00edfico\u00bb","block_context":{"text":"Buceo Cient\u00edfico","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/buceo-2\/buceo-cientifico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/curso-cientifico-mexico.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/curso-cientifico-mexico.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2012\/04\/curso-cientifico-mexico.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/09\/realizadocursocomunicaciones.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/41318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=41318"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/41318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/42873"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=41318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=41318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=41318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}