{"id":43758,"date":"2021-01-17T20:05:00","date_gmt":"2021-01-18T00:05:00","guid":{"rendered":"https:\/\/www.sportalsub.net\/blog\/?p=43758"},"modified":"2021-01-20T07:47:25","modified_gmt":"2021-01-20T11:47:25","slug":"%f0%9f%87%b9%f0%9f%87%b3-intento-de-record-mundial-de-walid-boudhiaf-apnea-peso-variable-2021-en-egipto","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/walid-world-records-freediving-egypt-2021","title":{"rendered":"\ud83c\uddf9\ud83c\uddf3 Nuevo R\u00e9cord Mundial de Walid Boudhiaf de T\u00fanez en Apnea Peso Variable en Egipto"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-44717\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021-150.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021-150.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021-150-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021-150-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021-150-450x300.jpg 450w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>(Sportalsub.net \/ Walid Boudhiaf) &#8211; <a href=\"https:\/\/www.sportalsub.net\/en\/world-record-attempt-by-walid-boudhiaf-freediving-variable-weight-2021-in-egypt\/\">Read in English<\/a><\/p>\n<p>Este domingo 17 de enero de 2021, el apneista tunecino <strong><a href=\"https:\/\/www.facebook.com\/walid.boudhiaf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Walid Boudhiaf<\/a>\u00a0<\/strong>implant\u00f3 un nuevo\u00a0r\u00e9cord mundial en la modalidad de peso variable de la Asociaci\u00f3n Internacional para el Desarrollo de la Apnea (<a href=\"https:\/\/www.aidainternational.org\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">AIDA<\/a>), en aguas de Sharm el Sheikh, Egipto.<\/p>\n<p>Walid realiz\u00f3 una inmersi\u00f3n de -150 metros en apnea peso variable, en donde el apneista se sumerge con la ayuda de un trineo o sled y asciende con su propio esfuerzo aleteando o con el impulso de sus brazos, superando la marca anterior de -146m que ten\u00eda el griego Stavros Kastrinakis desde noviembre de 2015.<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/tv\/CKLpd8djbFm\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"13\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Ver esta publicaci\u00f3n en Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a href=\"https:\/\/www.instagram.com\/tv\/CKLpd8djbFm\/?utm_source=ig_embed&amp;utm_campaign=loading\"style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\"  target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Una publicaci\u00f3n compartida por \ud835\udc13\ud835\udc11\ud835\udc08\ud835\udc13\ud835\udc0e\ud835\udc0d Freediving|Spearfishing (@tritonsub)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<div class=\"fb-post\" data-href=\"https:\/\/www.facebook.com\/permalink.php?story_fbid=3670586453035652&#038;id=346237892137208\" data-width=\"552\" style=\"background-color: #fff; display: inline-block;\"><\/div>\n<hr \/>\n<h4 class=\"entry-title post-title\"><strong>\ud83c\uddf9\ud83c\uddf3\u00a0Intento de R\u00e9cords Mundiales de Walid Boudhiaf Apnea Peso Variable e Inmersi\u00f3n Libre 2021 en Egipto<\/strong><\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-43759\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021-450x300.jpg 450w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>Del 17 al 26 de Enero de 2021 el apneista de origen Tunecino <strong><a href=\"https:\/\/www.facebook.com\/walid.boudhiaf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Walid Boudhiaf<\/a><\/strong> estar\u00e1 intentando dos nuevos r\u00e9cord mundiales en las modalidades de peso variable e inmersi\u00f3n libre de la Asociaci\u00f3n Internacional para el Desarrollo de la Apnea (<a href=\"https:\/\/www.aidainternational.org\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">AIDA<\/a>), en aguas de Sharm el Sheikh, Egipto.<\/p>\n<p>El r\u00e9cord vigente en peso variable, en donde el apneista se sumerge con la ayuda de un trineo o sled y asciende con su propio esfuerzo, aleteando o con el impulso de sus brazos, se encuentra en -146m y fue registrado por el griego Stavros Kastrinakis en noviembre de 2015 y ser\u00e1 la marca a superar por Walid, quien en su \u00faltima inmersi\u00f3n de entrenamiento de 2020 registr\u00f3 un descenso de -137 metros, como lo public\u00f3 en su <a href=\"https:\/\/www.facebook.com\/walid.boudhiaf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">p\u00e1gina oficial en Facebook<\/a>.<\/p>\n<p><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=308&amp;href=https%3A%2F%2Fwww.facebook.com%2Fwalid.boudhiaf%2Fvideos%2F427696745044767%2F&amp;show_text=true&amp;width=560\" width=\"560\" height=\"423\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>Igualmente Walid estar\u00e1 intentando superar el r\u00e9cord mundial en la modalidad de inmersi\u00f3n libre, en donde deber\u00e1 descender y ascender sin aletas, usando s\u00f3lo la fuerza de sus brazos para halar la cuerda y poder desplazarse. Este r\u00e9cord se encuentra en -125 metros por el ruso Alexey Molchanov desde julio de 2018.<\/p>\n<p>La informaci\u00f3n oficial del anuncio de los r\u00e9cords mundiales se encuentra publicada en el sitio web de AIDA Internacional\u00a0<a href=\"https:\/\/events.aidainternational.org\/Eventdetails-2877\" target=\"_blank\">WR Attempt Sharm FIM<\/a> <a href=\"https:\/\/events.aidainternational.org\/Eventdetails-2856\" target=\"_blank\">WR Attempt Sharm VWT<\/a><\/p>\n<p>El evento ser\u00e1 organizado con el apoyo de Freediving World, Tritonsub y las autoridades deportivas del Gobierno de T\u00fanez.<\/p>\n<p>Sigue a Walid en sus redes sociales oficiales:<br \/>\nFacebook: <a href=\"https:\/\/www.facebook.com\/walid.boudhiaf\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/www.facebook.com\/walid.boudhiaf<\/a><br \/>\nInstagram: <a href=\"https:\/\/www.instagram.com\/walidboudhiaf\/\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">https:\/\/www.instagram.com\/walidboudhiaf\/<\/a><\/p>\n<p><a href=\"https:\/\/worldrecords.aidainternational.org\/VariableWeight\" target=\"_blank\" rel=\"noopener noreferrer\" target=\"_blank\">Hist\u00f3rico de r\u00e9cords mundiales de Peso Variable<\/a><br \/>\n<a href=\"https:\/\/worldrecords.aidainternational.org\/FreeImmersion\" target=\"_blank\">Hist\u00f3rico de r\u00e9cords mundiales Inmersi\u00f3n Libre<\/a><\/p>\n<p>Sportalsub.net estar\u00e1 realizando seguimiento a este intento y posible r\u00e9cord mundial de Walid, quien ha desarrollado gran parte de su carrera como apneista en Colombia y en aguas del Caribe, San Andr\u00e9s y Curazao y a quien deseamos el mayor de los \u00e9xitos en este evento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ Walid Boudhiaf) &#8211; Read in English Este domingo 17 de enero de 2021, el apneista tunecino Walid Boudhiaf\u00a0implant\u00f3 un nuevo\u00a0r\u00e9cord mundial en la modalidad de peso variable de la Asociaci\u00f3n Internacional para el Desarrollo de la Apnea (AIDA), en aguas de Sharm el Sheikh, Egipto. Walid realiz\u00f3 una inmersi\u00f3n de -150 metros en apnea peso variable, en donde [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":44717,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,263,120,267],"tags":[450],"class_list":["post-43758","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-egipto","category-resultados","category-tunez","tag-destacados"],"modified_by":"Sportalsub.net","views":8993,"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/01\/walid-vwt-2021-150.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-bnM","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":45007,"url":"https:\/\/www.sportalsub.net\/blog\/entrevista-al-apneista-walid-boudhiaf-por-paola-arce-de-peru-para-pdi-internacional\/","url_meta":{"origin":43758,"position":0},"title":"\ud83d\udcfa Entrevista al apneista recordista mundial Walid Boudhiaf por Paola Arce de Per\u00fa para PDI Internacional","author":"Sportalsub.net","date":"3 marzo 2021","format":false,"excerpt":"(Sportalsub.net \/ PDI Internacional) El martes 2 de marzo, la reconocida presentadora de TV peruana Paola Arce @paolitadelperu sostuvo una interesante entrevista con el Apneista tunecino-franc\u00e9s, radicado actualmente en Colombia: Walid Boudhiaf quien el mes de enero\u00a0implant\u00f3 un nuevo R\u00e9cord Mundial en Apnea Peso Variable en Egipto La entrevista fue\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/03\/portada-walid-entrevista-pdi-peru.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/03\/portada-walid-entrevista-pdi-peru.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/03\/portada-walid-entrevista-pdi-peru.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/03\/portada-walid-entrevista-pdi-peru.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":28012,"url":"https:\/\/www.sportalsub.net\/blog\/record-mundial-peso-constante-alessia-zecchini-italia","url_meta":{"origin":43758,"position":1},"title":"\ud83c\uddee\ud83c\uddf9 Nuevo R\u00e9cord Mundial AIDA en Apnea Peso Constante de Alessia Zecchini de Italia","author":"Sportalsub.net","date":"5 mayo 2018","format":false,"excerpt":"(Especial Sportalsub.net) - Read in English Este s\u00e1bado 5 de mayo, durante la Competencia Internacional de Apnea\u00a0Nirvana Oceanquest 2018, que se lleva a cabo en San Andr\u00e9s, Colombia del 3 al 9 de mayo, la apneista italiana\u00a0Alessia Zecchini impuso un nuevo r\u00e9cord mundial en la modalidad de Peso Constante (con\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/alessiaworldrecord1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/alessiaworldrecord1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/alessiaworldrecord1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/05\/alessiaworldrecord1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":15331,"url":"https:\/\/www.sportalsub.net\/blog\/iru-balic-de-venezuela-y-alejandro-lemus-de-mexico-con-nuevos-records-nacionales-en-la-caribbean-cup-2013-de-apnea-en-roatan-honduras\/","url_meta":{"origin":43758,"position":2},"title":"\ud83c\udded\ud83c\uddf3 Iru Balic de Venezuela y Alejandro Lemus de M\u00e9xico con nuevos R\u00e9cords Nacionales en la \u00abCaribbean Cup 2013\u00bb de Apnea en Roatan, Honduras","author":"Sportalsub.net","date":"24 mayo 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ Caribbean Cup \/ Fotos: Lia Barret \/ Prawno Apparel) Este viernes 24 de mayo se realiz\u00f3 la segunda jornada de la competencia de apnea de profundidad \u201cCaribbean Cup 2013\u2033 Roatan Freediving Competition, evento que se lleva a cabo en Roatan, Honduras, organizado por el grupo Inner Sea\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/05\/caribbean_cup_sportalsub_dia31.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/05\/caribbean_cup_sportalsub_dia31.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/05\/caribbean_cup_sportalsub_dia31.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":22819,"url":"https:\/\/www.sportalsub.net\/blog\/nirvana-oceanquest-apnea-colombia-2016","url_meta":{"origin":43758,"position":3},"title":"\ud83c\udde8\ud83c\uddf4 Resultados Nirvana Oceanquest 2016. Competencia Internacional de Apnea en San Andr\u00e9s, Colombia","author":"Sportalsub.net","date":"15 junio 2016","format":false,"excerpt":"Foto:\u00a0Laura Babahekian (Sportalsub.net \/ Innersea) - Read in English Luego del \u00e9xito de la primera edici\u00f3n realizada en 2015, el Grupo Innersea realiz\u00f3\u00a0la\u00a0Nirvana Oceanquest 2016. Competencia Internacional de Apnea de profundidad, la cual se llev\u00f3 a cabo\u00a0en la isla de San Andr\u00e9s, Colombia del 4 al 10 de junio 2016,\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/resultados-nirvana.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/resultados-nirvana.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/resultados-nirvana.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/resultados-nirvana.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2016\/06\/resultados-nirvana.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":28603,"url":"https:\/\/www.sportalsub.net\/blog\/oceanquest-curacao-freediving-center-se-instala-en-el-caribe-con-walid-boudhiaf\/","url_meta":{"origin":43758,"position":4},"title":"\ud83c\udde8\ud83c\uddfc Realizada con \u00e9xito 1ra edici\u00f3n del OceanQuest Cura\u00e7ao Freediving Contest &#8211; Training Camp y Competencia de Apnea con Walid Boudhiaf","author":"Sportalsub.net","date":"9 noviembre 2018","format":false,"excerpt":"(Sportalsub.net \/ Oceanquest Curazao) - Read in English\u00a0- Foto: Alex St Jean El reconocido apneista tunecino, radicado por muchos a\u00f1os en Colombia, Walid Boudhiaf, inicia su nuevo centro de ense\u00f1anza de apnea en la Isla de Curazao en aguas del Mar Caribe, denominado\u00a0Oceanquest Cura\u00e7ao \"Me alegra mucho anunciar la apertura\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/10\/finaloceanquestcurazao2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/10\/finaloceanquestcurazao2018.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/10\/finaloceanquestcurazao2018.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/10\/finaloceanquestcurazao2018.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":56073,"url":"https:\/\/www.sportalsub.net\/blog\/aida-roatan-2022","url_meta":{"origin":43758,"position":5},"title":"\ud83c\udded\ud83c\uddf3 Resultados &#8211; Campeonato Mundial Individual de Apnea de profundidad AIDA 2022 \u2013 Roat\u00e1n, Honduras","author":"Sportalsub.net","date":"25 agosto 2022","format":false,"excerpt":"(Sportalsub.net \/ AIDA International) - Read in English 29\u00b0 Campeonato Mundial AIDA de Apnea en Roat\u00e1n, Honduras del 16 al 25 de agosto 2022; en las modalidades de profundidad: Peso Constante con Bialetas CWTB, Inmersi\u00f3n Libre FIM, Peso constante sin aletas CNF y Peso Constante CWT RESULTADOS Y VIDEOS DIA\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/08\/aidaroatan2022-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/08\/aidaroatan2022-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/08\/aidaroatan2022-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/08\/aidaroatan2022-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/43758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=43758"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/43758\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/44717"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=43758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=43758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=43758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}