{"id":52492,"date":"2022-02-20T07:17:54","date_gmt":"2022-02-20T11:17:54","guid":{"rendered":"https:\/\/www.sportalsub.net\/blog\/?p=52492"},"modified":"2022-03-03T08:03:04","modified_gmt":"2022-03-03T12:03:04","slug":"%f0%9f%87%a6%f0%9f%87%b7-competencia-de-apnea-profunda-faas-puerto-madryn-argentina-febrero-2022","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/competencia-apnea-profunda-puerto-madryn-argentina-febrero-2022","title":{"rendered":"\ud83c\udde6\ud83c\uddf7 Realizada Competencia de Apnea Profunda FAAS Puerto Madryn, Argentina \u2013 Febrero 2022"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-52493\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/competenciaapnefaas2022.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/competenciaapnefaas2022.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/competenciaapnefaas2022-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/competenciaapnefaas2022-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/competenciaapnefaas2022-450x300.jpg 450w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>(Sportalsub.net \/ FAAS \/ Freediving Patagonia)<\/p>\n<p>El pasado 19 de Febrero en las aguas del Golfo Nuevo, Puerto Madryn se llev\u00f3 a cabo la tercera edici\u00f3n de la competencia de apnea profunda Deep Patagonia competencia en la cual se realizan descensos en el mar a pulm\u00f3n libre.<\/p>\n<p>Dicha competencia cont\u00f3 con la organizaci\u00f3n a cargo de la subcomisi\u00f3n de buceo del Club N\u00e1utico Atl\u00e1ntico Sud y la log\u00edstica de Alejandro Andr\u00e9s, instructor de buceo libre y director de la comisi\u00f3n de apnea de la Federaci\u00f3n Argentina de Actividades Subacu\u00e1ticas. Se hicieron presentes competidores de distintos puntos del pa\u00eds y se cont\u00f3 con la participaci\u00f3n de diversas escuelas de apnea de Argentina.<\/p>\n<p>En esta nueva edici\u00f3n adem\u00e1s de la categor\u00eda general se incorpor\u00f3 una categor\u00eda promocional donde nuevos competidores pudieron dar sus primeros pasos en esta disciplina, logrando alcanzar profundidades de entre 20 y 25 metros y de esta manera sumando al crecimiento constante de la actividad. Dentro de la categor\u00eda promocional se not\u00f3 un excelente desempe\u00f1o de los competidores y las competidoras con una importante presencia de competidoras en la categor\u00eda femenina.<\/p>\n<p>Es interesante destacar las brillantes performances de los alumnos de la escuela municipal de buceo Malevo Medina los cuales alcanzaron los objetivos planteados y con mucha alegr\u00eda en sus rostros dieron a entender cu\u00e1nto disfrutaban esta nueva experiencia.<\/p>\n<p>El Club N\u00e1utico Atl\u00e1ntico Sud felicita a los competidores y las competidoras que participaron de esta edici\u00f3n logrando alcanzar profundidades que van desde los 20 a los 50 m. Felicitamos especialmente a los deportistas de la categor\u00eda general qu\u00e9 lograron el podio en el primer lugar Alejandro Andr\u00e9s con una marca de -50 metros, en segundo lugar Mario Robert con una marca de -45 m y en tercer lugar podio compartido entre Adri\u00e1n Mart\u00ednez y Jos\u00e9 Mar\u00eda Rold\u00e1n logrando la marca de -32 metros.<\/p>\n<p>Queremos hacer llegar nuestro agradecimiento a qui\u00e9nes se desempe\u00f1aron como buzos de seguridad por su impecable labor en el cuidado incondicional de cada apneista y hacemos extensivo el agradecimiento a Prefectura Naval Argentina, Alejandro Andr\u00e9s y a la Subcomisi\u00f3n de Actividades Subacu\u00e1ticas del Club N\u00e1utico Atl\u00e1ntico Sud por organizar y desarrollar la competencia e invitamos al p\u00fablico general a acercarse a las actividades que se desarrollan y animarse a descubrir el incre\u00edble mundo subacu\u00e1tico.<\/p>\n<p>Los d\u00edas 18, 19 y 20 de Febrero se realiza nuevamente en Puerto Madryn, la Competencia de Apnea Profunda y primera del a\u00f1o 2022, avalada por la Federaci\u00f3n Argentina de Actividades Subacu\u00e1ticas, bajo la organizaci\u00f3n del Club N\u00e1utico Atl\u00e1ntico Sud y la Escuela Freediving Patagonia.<\/p>\n<p>Categor\u00eda general en 3 modalidades INMERSION LIBRE, PESO CONSTANTE SIN ALETAS Y PESO CONSTANTE CON ALETAS e inaugurando la categor\u00eda promocional (hasta 25 metros)<\/p>\n<blockquote class=\"instagram-media\" style=\"background: #FFF; border: 0; border-radius: 3px; box-shadow: 0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width: 540px; min-width: 326px; padding: 0; width: calc(100% - 2px);\" data-instgrm-captioned=\"\" data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/CZw8bzCpwvq\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\">\n<div style=\"padding: 16px;\">\n<p>&nbsp;<\/p>\n<div style=\"display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display: block; height: 50px; margin: 0 auto 12px; width: 50px;\"><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\"color: #3897f0; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: 550; line-height: 18px;\">Ver esta publicaci\u00f3n en Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #f4f4f4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg);\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\"width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\"background-color: #f4f4f4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\"width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\"background-color: #f4f4f4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; line-height: 17px; margin-bottom: 0; margin-top: 8px; overflow: hidden; padding: 8px 0 7px; text-align: center; text-overflow: ellipsis; white-space: nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/CZw8bzCpwvq\/?utm_source=ig_embed&amp;utm_campaign=loading\"style=\"color: #c9c8cd; font-family: Arial,sans-serif; font-size: 14px; font-style: normal; font-weight: normal; line-height: 17px; text-decoration: none;\"  target=\"_blank\" rel=\"noopener\" target=\"_blank\">Una publicaci\u00f3n compartida por Buceo CNAS (@buceocnas)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n<p>M\u00e1s informaci\u00f3n:\u00a0<a href=\"https:\/\/www.facebook.com\/FAASFederacionArgentina\/\" target=\"_blank\" rel=\"noopener\" target=\"_blank\">FAAS<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/www.instagram.com\/buceocnas\" target=\"_blank\" rel=\"noopener\" target=\"_blank\">CNAS<\/a>\u00a0\u2013\u00a0<a href=\"https:\/\/www.instagram.com\/freedivingpatagonia\" target=\"_blank\" rel=\"noopener\" target=\"_blank\">Freediving Patagonia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ FAAS \/ Freediving Patagonia) El pasado 19 de Febrero en las aguas del Golfo Nuevo, Puerto Madryn se llev\u00f3 a cabo la tercera edici\u00f3n de la competencia de apnea profunda Deep Patagonia competencia en la cual se realizan descensos en el mar a pulm\u00f3n libre. Dicha competencia cont\u00f3 con la organizaci\u00f3n a cargo de la subcomisi\u00f3n de buceo [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":52493,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,4],"tags":[],"class_list":["post-52492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-argentina"],"modified_by":"Sportalsub.net","views":5291,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-dEE","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":44914,"url":"https:\/\/www.sportalsub.net\/blog\/competencia-de-apnea-profunda-faas-puerto-madryn-argentina-febrero-2021\/","url_meta":{"origin":52492,"position":0},"title":"\ud83c\udde6\ud83c\uddf7 Resultados &#8211; Competencia de Apnea Profunda FAAS Puerto Madryn, Argentina &#8211; Febrero 2021","author":"Sportalsub.net","date":"21 febrero 2021","format":false,"excerpt":"(Sportalsub.net \/ FAAS \/ Freediving Patagonia) Los d\u00edas 19, 20 y 21 de Febrero se realiz\u00f3 en Puerto Madryn, la 3\u00b0 Competencia de Apnea Profunda y primera del a\u00f1o 2021, avalada por la Federaci\u00f3n Argentina de Actividades Subacu\u00e1ticas, bajo la organizaci\u00f3n del Club N\u00e1utico Atl\u00e1ntico Sud y la Escuela Freediving\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/02\/apnea-argentina2021feat.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/02\/apnea-argentina2021feat.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/02\/apnea-argentina2021feat.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2021\/02\/apnea-argentina2021feat.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":61544,"url":"https:\/\/www.sportalsub.net\/blog\/deep-patagonia-2023","url_meta":{"origin":52492,"position":1},"title":"\ud83c\udde6\ud83c\uddf7 Deep Patagonia 2023. Competencia de Apnea Profunda FAAS &#8211; Puerto Madryn &#8211; Cancelado","author":"Sportalsub.net","date":"10 febrero 2023","format":false,"excerpt":"(Sportalsub.net \/ FAAS \/ CNAS) La Competencia de Apnea Profunda de la Federaci\u00f3n Argentina de Actividades Subacu\u00e1ticas (FAAS) \"Deep Patagonia\" se realizar\u00e1 en Puerto Madryn, Chubut los d\u00edas 22 y 23 de Abril de 2023 con la organizaci\u00f3n de la Escuela Freediving Patagonia EVENTO SUSPENDIDO M\u00e1s informaci\u00f3n e inscripciones: Freediving\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/02\/deep-patagonia-2023.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/02\/deep-patagonia-2023.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/02\/deep-patagonia-2023.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/02\/deep-patagonia-2023.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17424,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-1ra-competencia-de-descenso-en-apnea-en-argentina-faas-cmas-abismo-patagonia\/","url_meta":{"origin":52492,"position":2},"title":"\ud83c\udde6\ud83c\uddf7 Resultados 1ra Competencia de descenso en apnea en Argentina FAAS \/ CMAS \u00abAbismo Patagonia\u00bb","author":"Sportalsub.net","date":"12 marzo 2014","format":false,"excerpt":"(Especial Sportalsub.net \/ Freediving Patagonia \/ FAAS) Se desarroll\u00f3 satisfactoriamente los d\u00edas 08 y 09 de Marzo en la ciudad de Puerto Madryn la competencia de apnea ABISMO PATAGONIA, primer competencia que incluye descenso en apnea en aguas abiertas en nuestro pa\u00eds. La competencia fue organizada por la escuela de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/03\/apnea-argentina.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/03\/apnea-argentina.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2014\/03\/apnea-argentina.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":80316,"url":"https:\/\/www.sportalsub.net\/blog\/2da-apnea-argentina-faas-2025","url_meta":{"origin":52492,"position":3},"title":"\ud83c\udde6\ud83c\uddf7 Resultados \u2013 2da Competencia 2025 de Apnea Indoor FAAS \u2013 Puerto Madryn, Argentina","author":"Sportalsub.net","date":"26 mayo 2025","format":false,"excerpt":"(Sportalsub.net \/ FAAS) Segunda fecha del calendario de competencias de apnea de la Federaci\u00f3n Argentina de Actividades Subacu\u00e1ticas (FAAS) organizada por Freediving Patagonia y el club Ferrocarril Patag\u00f3nico los dias 24 y 25 de mayo de 2025 en el natatorio ubicado en la calle Pedro Derbes 280 de Puerto Madryn\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/06\/2da-argentina-faas-2025.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/06\/2da-argentina-faas-2025.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/06\/2da-argentina-faas-2025.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/06\/2da-argentina-faas-2025.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":17070,"url":"https:\/\/www.sportalsub.net\/blog\/1ra-competencia-de-descenso-en-apnea-en-argentina-faas-cmas\/","url_meta":{"origin":52492,"position":4},"title":"\ud83c\udde6\ud83c\uddf7 1ra Competencia de descenso en apnea en Argentina FAAS \/ CMAS","author":"Sportalsub.net","date":"3 diciembre 2013","format":false,"excerpt":"(Especial Sportalsub.net \/ FAAS \/ Freediving Patagonia) El pr\u00f3ximo 8 y 9 de Marzo de 2014 se realizar\u00e1 en Puerto Madryn, Argentina, la 1ra Competencia de Descenso en Apnea \"Abismo Patagonia\" avalada por la Federaci\u00f3n Argentina de Actividades Subacu\u00e1ticas afiliada a la Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas y ser\u00e1 organizada\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"patagonia","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2013\/12\/patagonia.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":65217,"url":"https:\/\/www.sportalsub.net\/blog\/resultados-competencia-de-apnea-indoor-faas-puerto-madryn-argentina-2023\/","url_meta":{"origin":52492,"position":5},"title":"\ud83c\udde6\ud83c\uddf7 Resultados \u2013 Competencia de Apnea Indoor FAAS \u2013 Puerto Madryn, Argentina 2023","author":"Sportalsub.net","date":"12 septiembre 2023","format":false,"excerpt":"(Sportalsub.net \/ FAAS \/ Club de Regatas Santa Fe) Los d\u00edas 9 y 10 de septiembre de 2023, el Club Ferrocarril Patag\u00f3nico de Puerto Madryn y la comisi\u00f3n de apnea de la FAAS organizaron una competencia nacional de apnea en piscina de 25mts en las siguientes modalidades, con sus respectivos\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/09\/indoorpuertomadryn2023.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/09\/indoorpuertomadryn2023.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/09\/indoorpuertomadryn2023.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/09\/indoorpuertomadryn2023.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/competenciaapnefaas2022.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/52492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=52492"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/52492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/52493"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=52492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=52492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=52492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}