{"id":52503,"date":"2022-03-06T16:00:55","date_gmt":"2022-03-06T20:00:55","guid":{"rendered":"https:\/\/www.sportalsub.net\/blog\/?p=52503"},"modified":"2022-03-06T17:00:27","modified_gmt":"2022-03-06T21:00:27","slug":"%f0%9f%87%a8%f0%9f%87%b4-campeonato-nacional-interclubes-de-natacion-con-aletas-fedecas-barranquilla-colombia-2022","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/interclubes-nadosub-barranquilla-colombia-2022","title":{"rendered":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211; Campeonato Nacional Interclubes de Nataci\u00f3n con Aletas FEDECAS \u2013 Barranquilla, Colombia 2022"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-52535\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/nadosub-bqlla-2022-1.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/nadosub-bqlla-2022-1.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/nadosub-bqlla-2022-1-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/nadosub-bqlla-2022-1-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/nadosub-bqlla-2022-1-450x300.jpg 450w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>(Sportalsub.net \/ FEDECAS)<\/p>\n<p>La Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas \u2013 (FEDECAS), convoc\u00f3 a las Ligas del pa\u00eds para que sus Clubes afiliados participaran en el \u201cCampeonato Nacional Interclubes de Nataci\u00f3n con Aletas Piscina, Categor\u00eda Juvenil B-CD y Mayores\u201d (Clasificatorio al Mundial Piscina Mayores Cali 2022), realizado en la ciudad de Barranquilla del 3 al 6 de marzo de 2022.<\/p>\n<p>La Organizaci\u00f3n del Campeonato estuvo a cargo de La Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas \u2013 (FEDECAS), con la coordinaci\u00f3n de la Liga del Atl\u00e1ntico.<\/p>\n<p>Las competencias se desarrollaron en el Complejo Acu\u00e1tico Distrital Eduardo Movilla Cra. 55 # 52 \u2013 48 de Barranquilla \u2013 Atl\u00e1ntico.<\/p>\n<h2><a href=\"https:\/\/colombiaacuatica.com\/backtun\/torneos\/resultados\/pdf\/2022\/20220303resultados.pdf\" target=\"_blank\">Resultados completos (pdf)<\/a><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-52584\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/03\/IMG_20220306_131511_963.webp\" alt=\"\" width=\"802\" height=\"711\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/03\/IMG_20220306_131511_963.webp 802w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/03\/IMG_20220306_131511_963-300x266.webp 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/03\/IMG_20220306_131511_963-768x681.webp 768w\" sizes=\"auto, (max-width: 802px) 100vw, 802px\" \/><\/p>\n<h3><a href=\"https:\/\/www.colombiaacuatica.com\/c\/240661\"style=\"font-size: 1.25em; font-weight: bold;\"  target=\"_blank\"><strong>Resultados<\/strong><\/a><\/h3>\n<h4><a href=\"https:\/\/www.colombiaacuatica.com\/backtun\/torneos\/2022\/convocatorias\/convocatoria20220303.pdf\" target=\"_blank\"><strong>Convocatoria Oficial<\/strong><\/a><\/h4>\n<h4><a href=\"https:\/\/www.colombiaacuatica.com\/backtun\/torneos\/2022\/20220303\/programa03438.pdf\" target=\"_blank\" rel=\"noopener\" target=\"_blank\"><strong>Programaci\u00f3n (Start List)<\/strong><\/a><\/h4>\n<p>&nbsp;<\/p>\n<p>Participan 174 deportistas de 18 equipos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ FEDECAS) La Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas \u2013 (FEDECAS), convoc\u00f3 a las Ligas del pa\u00eds para que sus Clubes afiliados participaran en el \u201cCampeonato Nacional Interclubes de Nataci\u00f3n con Aletas Piscina, Categor\u00eda Juvenil B-CD y Mayores\u201d (Clasificatorio al Mundial Piscina Mayores Cali 2022), realizado en la ciudad de Barranquilla del 3 al 6 de marzo de 2022. La [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":52535,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,12,120],"tags":[450],"class_list":["post-52503","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colombia","category-natacion-con-aletas","category-resultados","tag-destacados"],"modified_by":"Sportalsub.net","views":3020,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-dEP","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":69819,"url":"https:\/\/www.sportalsub.net\/blog\/interclubes-nadosub-barranquilla-2024","url_meta":{"origin":52503,"position":0},"title":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211; Campeonato Nacional Nataci\u00f3n con Aletas FEDECAS 2024 &#8211; Barranquilla, Colombia","author":"Sportalsub.net","date":"24 marzo 2024","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS) La Federaci\u00f3n Colombiana de Actividades convoc\u00f3 a las Ligas del pa\u00eds para que sus Clubes afiliados participaran en el \u201cCampeonato Nacional Interclubes por Categor\u00edas (Juvenil Abierta y Mayores) de Nataci\u00f3n con Aletas, en Piscina\u201d con invitaci\u00f3n internacional, realizado en la ciudad de Barranquilla del 21 al 24\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/02\/interclubesaletasbarranquilla2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/02\/interclubesaletasbarranquilla2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/02\/interclubesaletasbarranquilla2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/02\/interclubesaletasbarranquilla2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":52677,"url":"https:\/\/www.sportalsub.net\/blog\/campeonato-nacional-interclubes-natacion-con-aletas-aguas-abiertas-fedecas-santa-marta-colombia-2022\/","url_meta":{"origin":52503,"position":1},"title":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211; Campeonato Nacional Interclubes Nataci\u00f3n con Aletas Aguas Abiertas FEDECAS \u2013 Santa Marta, Colombia 2022","author":"Sportalsub.net","date":"27 marzo 2022","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS) Resultados del Campeonato Nacional Interclubes de Nataci\u00f3n con Aletas Aguas Abiertas por Categor\u00edas Juvenil B-C-D, Mayores y M\u00e1ster 2022 de la Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas realizado del 24 al 26 de Marzo en Barranquilla, Magdalena. Resultados Oficiales","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/03\/santamarta2022.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/03\/santamarta2022.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/03\/santamarta2022.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/03\/santamarta2022.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30908,"url":"https:\/\/www.sportalsub.net\/blog\/interligas-nadosub-barranquilla-colombia-2019","url_meta":{"origin":52503,"position":2},"title":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211;  Campeonato Nacional Interligas de Nataci\u00f3n con Aletas FEDECAS &#8211; Barranquilla, Colombia 2019","author":"Sportalsub.net","date":"18 junio 2019","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS) La Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas FEDECAS organiz\u00f3 con todo \u00e9xito el Campeonato Nacional Interligas Pre - Juegos Nacionales Categor\u00eda Abierta en Piscina y Aguas Abiertas de Nataci\u00f3n con Aletas, en la ciudad de Barranquilla, del 10 al 16 de junio de 2019. El evento fue el\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/11\/e064a4476b8a99054a736180a96397a1ac9e6122.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/11\/e064a4476b8a99054a736180a96397a1ac9e6122.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/11\/e064a4476b8a99054a736180a96397a1ac9e6122.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/11\/e064a4476b8a99054a736180a96397a1ac9e6122.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/11\/e064a4476b8a99054a736180a96397a1ac9e6122.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":54530,"url":"https:\/\/www.sportalsub.net\/blog\/nacional-interclubes-nadosub-2022-cali-colombia\/","url_meta":{"origin":52503,"position":3},"title":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211; Campeonato Nacional Interclubes de Nataci\u00f3n con Aletas Piscina, Categor\u00eda Abierta FEDECAS 2022. Cali, Colombia","author":"Sportalsub.net","date":"1 mayo 2022","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS \/ LIVAS) La Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas \u2013 (FEDECAS), convoc\u00f3 a las Ligas del pa\u00eds para que sus Clubes afiliados participaran en el \u201cCampeonato Nacional Interclubes de Nataci\u00f3n con Aletas Piscina, Categor\u00eda Abierta\u201d (Clasificatorio al Mundial Piscina Mayores Cali 2022), realizado en la ciudad de Cali\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/nacional-fedecas-livas-2022.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/nacional-fedecas-livas-2022.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/nacional-fedecas-livas-2022.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/nacional-fedecas-livas-2022.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":53754,"url":"https:\/\/www.sportalsub.net\/blog\/master-interclubes-aletas-pereira-colombia-2022","url_meta":{"origin":52503,"position":4},"title":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211; Campeonato Nacional Interclubes Nataci\u00f3n con Aletas M\u00e1ster FEDECAS \u2013 Pereira, Colombia 2022","author":"Sportalsub.net","date":"11 abril 2022","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS \/ LASER) La Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas \u2013 (FEDECAS), convoc\u00f3 a las ligas del pa\u00eds para que sus Clubes afiliados participaran en el \u201cCampeonato Nacional Interclubes de Nataci\u00f3n con Aletas, Categor\u00eda M\u00e1ster\u201d (I Evaluativo al Mundial M\u00e1ster Piscina Cali 2022), realizado en la ciudad de Pereira\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/campeonatomasterpereira2022.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/campeonatomasterpereira2022.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/campeonatomasterpereira2022.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/campeonatomasterpereira2022.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":55749,"url":"https:\/\/www.sportalsub.net\/blog\/campeonato-nacional-interclubes-de-natacion-con-aletas-aguas-abiertas-fedecas-camedagua-colombia-2022\/","url_meta":{"origin":52503,"position":5},"title":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211; Campeonato Nacional Interclubes Nataci\u00f3n con Aletas Aguas Abiertas FEDECAS. Camedagua, Colombia 2022","author":"Sportalsub.net","date":"12 junio 2022","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS \/ LASCA) La Federaci\u00f3n Colombiana de Actividades Subacu\u00e1ticas \u2013 (FEDECAS), convoc\u00f3 a las Ligas del pa\u00eds para que sus Clubes afiliados participaran en el \u201cCampeonato Nacional Interclubes Aguas Abiertas Cameguadua - Juvenil - Mayores y Master\u201d (II Clasificatorio Mundial Larga Distancia - Italia 2022 \u2013 II Clasificatorio\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/06\/3kbialetascolombia-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/06\/3kbialetascolombia-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/06\/3kbialetascolombia-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/06\/3kbialetascolombia-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/02\/nadosub-bqlla-2022-1.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/52503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=52503"}],"version-history":[{"count":0,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/52503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/52535"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=52503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=52503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=52503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}