{"id":56064,"date":"2022-08-01T04:58:47","date_gmt":"2022-08-01T08:58:47","guid":{"rendered":"https:\/\/www.sportalsub.net\/blog\/?p=56064"},"modified":"2024-01-04T04:43:02","modified_gmt":"2024-01-04T08:43:02","slug":"%f0%9f%87%bb%f0%9f%87%aa-resultados-2do-campeonato-nacional-fvas-2022-de-apnea-en-piscina-por-clubes-venezuela","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/2do-nacional-apnea-fvas-venezuela-2022","title":{"rendered":"\ud83c\uddfb\ud83c\uddea Resultados \u2013 2do Campeonato Nacional FVAS 2022 de Apnea en piscina por Clubes &#8211; Venezuela"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-56066\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/08\/2donacionalapneafvas2022.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/08\/2donacionalapneafvas2022.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/08\/2donacionalapneafvas2022-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/08\/2donacionalapneafvas2022-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/08\/2donacionalapneafvas2022-450x300.jpg 450w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<p>(Sportalsub.net \/ FVAS)<\/p>\n<p>La <strong>Asociaci\u00f3n de Actividades Subacu\u00e1ticas de Distrito Capital y la Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas<\/strong>, organizaron el II CAMPEONATO NACIONAL POR CLUBES DE APNEA INDOOR 2022 realizado los d\u00edas <strong>s\u00e1bado 30 y domingo 31 de julio de 2022<\/strong>, en la piscina \u201cRafael Vidal\u201d IND \u2013 Caracas. Evento contemplado en calendario FVAS 2022 y que tuvo car\u00e1cter selectivo nacional para los Apneistas de Clubes inscritos en el Registro Nacional del Deporte del IND con el aval de jueces de la Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas (FVAS).<\/p>\n<p><strong>Fecha del Evento:<\/strong> s\u00e1bado 30 y domingo 31 de julio de 2022<br \/>\n<strong>Lugar del Evento: \u00a0<\/strong>Piscina \u00abRafael Vidal\u00bb IND &#8211; Caracas<\/p>\n<p><span style=\"font-size: 14pt;\"><strong><img decoding=\"async\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2009\/10\/pdf.gif\" \/> <a href=\"https:\/\/www.fvas.com.ve\/wp-content\/uploads\/2022\/07\/RESULTADOS-2DO-NACIONAL-APNEA-FVAS-IND.pdf\" target=\"_blank\" rel=\"noopener\" target=\"_blank\">RESULTADOS OFICIALES<\/a><\/strong><\/span><\/p>\n<p><strong>Fuente: <a href=\"https:\/\/www.fvas.com.ve\/2do-campeonato-nacional-fvas-2022-de-apnea-en-piscina-por-clubes\/\" target=\"_blank\" rel=\"noopener\" target=\"_blank\">Sitio Web Oficial FVAS<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ FVAS) La Asociaci\u00f3n de Actividades Subacu\u00e1ticas de Distrito Capital y la Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas, organizaron el II CAMPEONATO NACIONAL POR CLUBES DE APNEA INDOOR 2022 realizado los d\u00edas s\u00e1bado 30 y domingo 31 de julio de 2022, en la piscina \u201cRafael Vidal\u201d IND \u2013 Caracas. Evento contemplado en calendario FVAS 2022 y que tuvo car\u00e1cter selectivo [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":56066,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"no","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,120,8],"tags":[450,477],"class_list":["post-56064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-resultados","category-venezuela","tag-destacados","tag-miguelsportsub"],"modified_by":"Sportalsub.net","views":1520,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-eAg","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":54536,"url":"https:\/\/www.sportalsub.net\/blog\/1er-nacional-apnea-nadosub-fvas-venezuela-2022","url_meta":{"origin":56064,"position":0},"title":"\ud83c\uddfb\ud83c\uddea Resultados &#8211; 1er Campeonato Nacional 2022 Apnea y Nataci\u00f3n con Aletas en piscina por Clubes FVAS &#8211; Caracas, Venezuela","author":"Sportalsub.net","date":"17 mayo 2022","format":false,"excerpt":"(Sportalsub.net \/ FVAS) 1er Campeonato Nacional de Apnea y Nataci\u00f3n con Aletas en Piscina (Pre-Selectivo nacional) de la Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas, d\u00edas: viernes 13, s\u00e1bado 14 y domingo 15 de mayo del 2022 en la piscina \u201cRafael Vidal\u201d IND \u2013Caracas. Evento contemplado en el calendario 2022 con car\u00e1cter\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/campeonatoclubesfvas2022.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/campeonatoclubesfvas2022.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/campeonatoclubesfvas2022.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/04\/campeonatoclubesfvas2022.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":27583,"url":"https:\/\/www.sportalsub.net\/blog\/1er-campeonato-nacional-por-clubes-de-apnea-en-piscina-fvas-venezuela-2018\/","url_meta":{"origin":56064,"position":1},"title":"\ud83c\uddfb\ud83c\uddea Resultados &#8211; 1er Campeonato Nacional por Clubes de Apnea en piscina FVAS Venezuela 2018","author":"Sportalsub.net","date":"19 marzo 2018","format":false,"excerpt":"(Sportalsub.net \/ FVAS) La Comisi\u00f3n Nacional de Apnea de la Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas llev\u00f3 a cabo el CAMPEONATO NACIONAL POR CLUBES DE APNEA en piscina realizado los d\u00edas viernes 16 s\u00e1bado 17 y domingo 18 de marzo 2018 en la piscina \u201cRafael Vidal\u201d\u00a0IND \u2013Caracas. Evento contemplado en calendario\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/03\/apneafvassportalsub.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/03\/apneafvassportalsub.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/03\/apneafvassportalsub.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/03\/apneafvassportalsub.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":37940,"url":"https:\/\/www.sportalsub.net\/blog\/chequeo-apnea-indoor-fvas-venezuela-2020","url_meta":{"origin":56064,"position":2},"title":"\ud83c\uddfb\ud83c\uddea Resultados &#8211; I Chequeo Nacional de Apnea Indoor FVAS Venezuela 2020","author":"Sportalsub.net","date":"1 marzo 2020","format":false,"excerpt":"(Sportalsub.net \/ FVAS) La Federaci\u00f3n Venezolana de Actividades Subacu\u00e1ticas y la Comisi\u00f3n Nacional de Apnea, llevaron a cabo con todo \u00e9xito el I CHEQUEO NACIONAL DE APNEA INDOOR 2020 realizado los d\u00edas: viernes 28, s\u00e1bado 29 de febrero y domingo 1 de marzo 2020 en la piscina \u201cRafael Vidal\u201d IND\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/chequeoapneafvas2020.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/chequeoapneafvas2020.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/chequeoapneafvas2020.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2020\/03\/chequeoapneafvas2020.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":29839,"url":"https:\/\/www.sportalsub.net\/blog\/1er-chequeo-nacional-de-apnea-en-piscina-fvas-venezuela-2019\/","url_meta":{"origin":56064,"position":3},"title":"\ud83c\uddfb\ud83c\uddea Resultados &#8211; 1er Chequeo Nacional de Apnea en piscina FVAS Venezuela 2019","author":"Sportalsub.net","date":"12 febrero 2019","format":false,"excerpt":"(Sportalsub.net \/ FVAS) Los d\u00edas viernes 8, s\u00e1bado 9 y domingo 10 de\u00a0febrero 2019 se llev\u00f3 a cabo en la piscina \u201cRafael Vidal\u201d IND \u2013Caracas el\u00a01er CHEQUEO NACIONAL DE\u00a0APNEA INDOOR, evento contemplado en\u00a0calendario 2019 y que tuvo car\u00e1cter de Chequeo Nacional para los Apneistas de\u00a0Clubes inscritos en el Registro Nacional\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/01\/chequeoapnea2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/01\/chequeoapnea2018.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/01\/chequeoapnea2018.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/01\/chequeoapnea2018.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":30149,"url":"https:\/\/www.sportalsub.net\/blog\/i-campeonato-nacional-e-invitacional-por-clubes-de-apnea-indoor-fvas-venezuela-2019\/","url_meta":{"origin":56064,"position":4},"title":"\ud83c\uddfb\ud83c\uddea Resultados &#8211; I Campeonato Nacional e Invitacional por Clubes de Apnea Indoor FVAS Venezuela 2019","author":"Sportalsub.net","date":"19 abril 2019","format":false,"excerpt":"(Sportalsub.net \/ FVAS) Los d\u00edas viernes 12, s\u00e1bado 13 y domingo 14 de abril 2019 se llev\u00f3 a cabo en la piscina \u201cRafael Vidal\u201d IND \u2013Caracas el I CAMPEONATO NACIONAL E INVITACIONAL POR CLUBES DE APNEA INDOOR COPA TRITONS WARRIORS, evento contemplado en calendario 2019 y que tuvo car\u00e1cter de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/04\/resultadosapneafvas2019.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/04\/resultadosapneafvas2019.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/04\/resultadosapneafvas2019.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/04\/resultadosapneafvas2019.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":26293,"url":"https:\/\/www.sportalsub.net\/blog\/apnea-fvas-venezuela-agosto-2017","url_meta":{"origin":56064,"position":5},"title":"\ud83c\uddfb\ud83c\uddea Resultados Campeonato Nacional de Apnea en piscina FVAS Venezuela Agosto 2017","author":"Sportalsub.net","date":"10 agosto 2017","format":false,"excerpt":"\u00a0 (Sportalsub.net \/ FVAS) Los d\u00edas 5 y 6 de Agosto se realiz\u00f3 el 2do Campeonato Nacional de Apnea en las Instalaciones del Vel\u00f3dromo Teo Capriles en Montalban, en la piscina Rafael Vidal del IND en Caracas, Venezuela Con la participaci\u00f3n de: Distrito Capital, Miranda, Monagas, Lara y Vargas se\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/08\/20590064_157014891517848_5247621691139424256_n.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/08\/20590064_157014891517848_5247621691139424256_n.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/08\/20590064_157014891517848_5247621691139424256_n.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2017\/08\/20590064_157014891517848_5247621691139424256_n.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/08\/2donacionalapneafvas2022.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/56064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=56064"}],"version-history":[{"count":1,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/56064\/revisions"}],"predecessor-version":[{"id":68750,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/56064\/revisions\/68750"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/56066"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=56064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=56064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=56064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}