{"id":74050,"date":"2024-07-05T10:02:52","date_gmt":"2024-07-05T14:02:52","guid":{"rendered":"https:\/\/www.sportalsub.net\/blog\/?p=74050"},"modified":"2024-07-05T10:02:52","modified_gmt":"2024-07-05T14:02:52","slug":"%f0%9f%87%b2%f0%9f%87%bd-ivonne-rodriguez-representa-a-mexico-en-el-campeonato-mundial-de-apnea-en-piscina-cmas-belgrado-serbia-2024","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/mexico-apnea-cmas-belgrado-2024","title":{"rendered":"\ud83c\uddf2\ud83c\uddfd Ivonne Rodriguez representa a M\u00e9xico en el Campeonato Mundial de Apnea en piscina CMAS \u2013 Belgrado, Serbia 2024"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-74052\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apneamexicoserbia2024.jpg\" alt=\"\" width=\"860\" height=\"573\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apneamexicoserbia2024.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apneamexicoserbia2024-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apneamexicoserbia2024-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apneamexicoserbia2024-450x300.jpg 450w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/p>\n<p>(Sportalsub.net \/ FMAS)<\/p>\n<p>La Apneista Mexicana <strong>Ivonne Rodriguez Estrada<\/strong> es la \u00fanica representante de su pa\u00eds\u00a0 en el <a href=\"https:\/\/www.sportalsub.net\/blog\/cmasfreedivingindoor2024\" rel=\"bookmark\">14to Campeonato Mundial CMAS de Apnea en piscina 2024 \u2013 Belgrado, Serbia<\/a> que se realiza del 4 al 10 de julio.<\/p>\n<p>Ivonne est\u00e1 acompa\u00f1ada en el evento por el entrenador <strong>Jos\u00e9 Juan Jim\u00e9nez, <\/strong>as\u00ed lo inform\u00f3 Juan Manuel G\u00f3mez, vicepresidente de la Federaci\u00f3n Mexicana de Actividades Subacuaticas (FMAS).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-74051\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/mexicoapnea2.jpg\" alt=\"\" width=\"900\" height=\"675\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/mexicoapnea2.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/mexicoapnea2-300x225.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/mexicoapnea2-768x576.jpg 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n<hr \/>\n<p><a href=\"https:\/\/www.sportalsub.net\/blog\/tag\/cmas-belgrado-2024\/\"><strong>Sigue la Cobertura Especial de los Campeonatos Mundiales de Apnea y Nataci\u00f3n con Aletas CMAS en Belgrado, Serbia por Sportalsub.net #sersubacuatico<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.sportalsub.net\/blog\/tag\/cmas-belgrado-2024\/\"><strong><img decoding=\"async\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/02\/cmasbelgrade2024-450x300.jpg\" \/><\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ FMAS) La Apneista Mexicana Ivonne Rodriguez Estrada es la \u00fanica representante de su pa\u00eds\u00a0 en el 14to Campeonato Mundial CMAS de Apnea en piscina 2024 \u2013 Belgrado, Serbia que se realiza del 4 al 10 de julio. Ivonne est\u00e1 acompa\u00f1ada en el evento por el entrenador Jos\u00e9 Juan Jim\u00e9nez, as\u00ed lo inform\u00f3 Juan Manuel G\u00f3mez, vicepresidente de la [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":74052,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"no","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[9,98],"tags":[481,450],"class_list":["post-74050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apnea","category-mexico","tag-cmas-belgrado-2024","tag-destacados"],"modified_by":"Sportalsub.net","views":3060,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-jgm","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":74054,"url":"https:\/\/www.sportalsub.net\/blog\/colombia-apnea-cmas-belgrado-2024","url_meta":{"origin":74050,"position":0},"title":"\ud83c\udde8\ud83c\uddf4 Selecci\u00f3n Colombia en el Campeonato Mundial de Apnea en piscina CMAS \u2013 Belgrado, Serbia 2024","author":"Sportalsub.net","date":"5 julio 2024","format":false,"excerpt":"(Sportalsub.net \/ FEDECAS) La Selecci\u00f3n Colombia se presenta en el\u00a014to Campeonato Mundial CMAS de Apnea en piscina 2024 \u2013 Belgrado, Serbia del 4 al 10 de julio. Con los deportistas: Sof\u00eda G\u00f3mez Uribe, Vanessa Tamayo, Federico Ruiz y Mateo Rodas, acompa\u00f1ados del delegado oficial Diego Le\u00f3n Rodriguez y el Jefe\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apnecolombiaserbia2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apnecolombiaserbia2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apnecolombiaserbia2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apnecolombiaserbia2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":74105,"url":"https:\/\/www.sportalsub.net\/blog\/cuba-apnea-cmas-belgrado-2024","url_meta":{"origin":74050,"position":1},"title":"\ud83c\udde8\ud83c\uddfa Equipo Cubano de Apnea presente en el Campeonato Mundial CMAS en piscina \u2013 Belgrado, Serbia 2024","author":"Sportalsub.net","date":"8 julio 2024","format":false,"excerpt":"(Sportalsub.net) El equipo de apnea de Cuba participa en el 14to Campeonato Mundial CMAS de Apnea en piscina 2024 \u2013 Belgrado, Serbia del 4 al 10 de julio. El equipo est\u00e1 conformado por los atletas senior: Rolando Salgado, Roylin D\u00edaz y los atletas m\u00e1ster: Lemay Gutierrez y Andy Cabrera quienes\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/cubabelgrado2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/cubabelgrado2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/cubabelgrado2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/cubabelgrado2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":74065,"url":"https:\/\/www.sportalsub.net\/blog\/chile-apnea-cmas-belgrado-2024","url_meta":{"origin":74050,"position":2},"title":"\ud83c\udde8\ud83c\uddf1 Team Chile de Apnea en el Campeonato Mundial CMAS en piscina \u2013 Belgrado, Serbia 2024","author":"Sportalsub.net","date":"6 julio 2024","format":false,"excerpt":"(Sportalsub.net \/ FEDESUB) El Team Chile tiene dos representantes en el 14to Campeonato Mundial CMAS de Apnea en piscina 2024 \u2013 Belgrado, Serbia\u00a0del 4 al 10 de julio. Los deportistas: Carol Carrasco y Rodrigo Pichun, fueron los seleccionados por la Federaci\u00f3n Deportiva Nacional de Actividades Subacu\u00e1ticas y Salvamento Acu\u00e1tico de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/teamchileapnea.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/teamchileapnea.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/teamchileapnea.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/teamchileapnea.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":69951,"url":"https:\/\/www.sportalsub.net\/blog\/cmas-belgrade-2024","url_meta":{"origin":74050,"position":3},"title":"\ud83c\uddf7\ud83c\uddf8 CMAS confirma Campeonatos Mundiales de Apnea y Nataci\u00f3n con Aletas en piscina en Belgrado, Serbia en Julio 2024","author":"Sportalsub.net","date":"28 febrero 2024","format":false,"excerpt":"(Sportalsub.net \/ CMAS) - Read in English La Confederaci\u00f3n Mundial de Actividades Subacu\u00e1ticas (CMAS) ha confirmado las fechas de los Campeonatos Mundiales de Apnea y Nataci\u00f3n con Aletas en piscina a realizarse en la ciudad de Belgrado, Serbia del 4 al 17 de Julio de 2024. As\u00ed mismo se ha\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/02\/cmasbelgrade2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/02\/cmasbelgrade2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/02\/cmasbelgrade2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/02\/cmasbelgrade2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":74038,"url":"https:\/\/www.sportalsub.net\/blog\/ecuador-apnea-cmas-belgrado-2024","url_meta":{"origin":74050,"position":4},"title":"\ud83c\uddea\ud83c\udde8 Team Ecuador presente en el Campeonato Mundial de Apnea en piscina CMAS &#8211; Belgrado, Serbia 2024","author":"Sportalsub.net","date":"4 julio 2024","format":false,"excerpt":"(Sportalsub.net \/ FEDASUB) La Selecci\u00f3n de Apnea de Ecuador participar\u00e1 en el 14to Campeonato Mundial CMAS de Apnea en piscina 2024 \u2013 Belgrado, Serbia a realizarse del 4 al 10 de julio. El equipo est\u00e1 conformado por las dos atletas de\u00a0Categor\u00eda Junior: Sabine M\u00e4nz y Mar\u00eda Emilia Segarra y dos\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apneaecuadorserbia2024.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apneaecuadorserbia2024.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apneaecuadorserbia2024.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apneaecuadorserbia2024.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":74080,"url":"https:\/\/www.sportalsub.net\/blog\/venezuela-apnea-cmas-belgrado-2024","url_meta":{"origin":74050,"position":5},"title":"\ud83c\uddfb\ud83c\uddea Jos\u00e9 Plaza lleva la Bandera de Venezuela al Campeonato Mundial CMAS en piscina \u2013 Belgrado, Serbia 2024","author":"Sportalsub.net","date":"6 julio 2024","format":false,"excerpt":"(Sportalsub.net \/ FVAS) El apneista venezolano Jos\u00e9 Plaza es el \u00fanico deportista de su pa\u00eds en el 14to Campeonato Mundial CMAS de Apnea en piscina 2024 \u2013 Belgrado, Serbia\u00a0que se realiza del 4 al 10 de julio. Jos\u00e9 participa en el Campeonato Mundial en representaci\u00f3n de la Federaci\u00f3n Venezolana de\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/joseplazavenezuela.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/joseplazavenezuela.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/joseplazavenezuela.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/joseplazavenezuela.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/07\/apneamexicoserbia2024.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/74050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=74050"}],"version-history":[{"count":1,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/74050\/revisions"}],"predecessor-version":[{"id":74053,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/74050\/revisions\/74053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/74052"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=74050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=74050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=74050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}