{"id":75557,"date":"2024-10-28T20:18:33","date_gmt":"2024-10-29T00:18:33","guid":{"rendered":"https:\/\/www.sportalsub.net\/blog\/?p=75557"},"modified":"2024-11-03T09:45:22","modified_gmt":"2024-11-03T13:45:22","slug":"%f0%9f%87%a8%f0%9f%87%b4-3ra-copa-calypso-rural-y-urbana-de-natacion-con-aletas-risaralda-colombia","status":"publish","type":"post","link":"https:\/\/www.sportalsub.net\/blog\/3ra-copa-calypso-rural-y-urbana-de-natacion-con-aletas-risaralda-colombia\/","title":{"rendered":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211; 3ra Copa Calypso Rural y Urbana de Nataci\u00f3n con Aletas, Risaralda &#8211; Colombia"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/calypso.com.co\/wp-content\/uploads\/2024\/10\/resultadoscopacalypso2024-730x350.jpg\" alt=\"\" width=\"730\" height=\"350\" \/><\/p>\n<p>(Sportalsub.net \/ Club Subacu\u00e1tico Calypso)<\/p>\n<div class=\"entry-content\">\n<div>Con una excelente participaci\u00f3n de 180 deportistas de 10 equipos del pa\u00eds, se realiz\u00f3 con todo \u00e9xito la 3ra edici\u00f3n de la la Copa CALYPSO 2024 de Nataci\u00f3n Con Aletas con invitaci\u00f3n regional y nacional, realizada en la ciudad de PEREIRA , en el Complejo Acu\u00e1tico de la Villa Ol\u00edmpica , durante los d\u00edas del 25 al 27 de Octubre de 2024. El evento cont\u00f3 con el apoyo y autorizaci\u00f3n de la Liga Risaralda de Actividades Subacu\u00e1ticas \u2013 LASER.<\/div>\n<div class=\"shapely-content \">\n<p>Felicitaciones y agradecimiento a todos los que participaron y apoyaron la realizaci\u00f3n del evento.<\/p>\n<p><strong><a href=\"https:\/\/calypso.com.co\/wp-content\/uploads\/2024\/10\/Resultados-Torneo-Copa-Calypso.pdf\" target=\"_blank\" rel=\"noopener\" target=\"_blank\">RESULTADOS OFICIALES (PDF)<\/a><\/strong><br \/>\n<strong><a href=\"https:\/\/calypso.com.co\/wp-content\/uploads\/2024\/10\/Mejor-Marca-Tecnica-x-Tiempos.pdf\" target=\"_blank\" rel=\"noopener\" target=\"_blank\">MEJOR MARCA T\u00c9CNICA (PDF)<\/a><\/strong><br \/>\n<strong><a href=\"https:\/\/calypso.com.co\/wp-content\/uploads\/2024\/10\/Medalleria.pdf\" target=\"_blank\">MEDALLER\u00cdA (PDF)<\/a><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-671\" src=\"https:\/\/calypso.com.co\/wp-content\/uploads\/2024\/10\/prensacalypso.jpg\" sizes=\"auto, (max-width: 1542px) 100vw, 1542px\" srcset=\"https:\/\/calypso.com.co\/wp-content\/uploads\/2024\/10\/prensacalypso.jpg 1542w, https:\/\/calypso.com.co\/wp-content\/uploads\/2024\/10\/prensacalypso-289x300.jpg 289w, https:\/\/calypso.com.co\/wp-content\/uploads\/2024\/10\/prensacalypso-987x1024.jpg 987w, https:\/\/calypso.com.co\/wp-content\/uploads\/2024\/10\/prensacalypso-768x797.jpg 768w, https:\/\/calypso.com.co\/wp-content\/uploads\/2024\/10\/prensacalypso-1480x1536.jpg 1480w\" alt=\"\" width=\"1542\" height=\"1600\" \/><\/p>\n<\/div>\n<\/div>\n<p><a href=\"https:\/\/calypso.com.co\/\" target=\"_blank\" rel=\"noopener\" target=\"_blank\"><strong>CONVOCATORIA OFICIAL (PDF)<\/strong><\/a><\/p>\n<p>Fuente: <a href=\"https:\/\/calypso.com.co\/\" target=\"_blank\">www.calypso.com.co<\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-75558\" src=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/10\/3racopacalypsosportalsub.jpg\" alt=\"\" width=\"900\" height=\"600\" srcset=\"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/10\/3racopacalypsosportalsub.jpg 900w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/10\/3racopacalypsosportalsub-300x200.jpg 300w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/10\/3racopacalypsosportalsub-768x512.jpg 768w, https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/10\/3racopacalypsosportalsub-450x300.jpg 450w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Sportalsub.net \/ Club Subacu\u00e1tico Calypso) Con una excelente participaci\u00f3n de 180 deportistas de 10 equipos del pa\u00eds, se realiz\u00f3 con todo \u00e9xito la 3ra edici\u00f3n de la la Copa CALYPSO 2024 de Nataci\u00f3n Con Aletas con invitaci\u00f3n regional y nacional, realizada en la ciudad de PEREIRA , en el Complejo Acu\u00e1tico de la Villa Ol\u00edmpica , durante los d\u00edas del [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":75558,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_lmt_disableupdate":"no","_lmt_disable":"no","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"3ra Copa Calypso Rural y Urbana de Nataci\u00f3n con Aletas, Risaralda - Colombia","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,12,120],"tags":[450],"class_list":["post-75557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-colombia","category-natacion-con-aletas","category-resultados","tag-destacados"],"modified_by":"Sportalsub.net","views":1460,"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pf9lN-jEF","jetpack_likes_enabled":false,"jetpack-related-posts":[{"id":83917,"url":"https:\/\/www.sportalsub.net\/blog\/4ta-copa-calypso-yubarta-de-natacion-con-aletas-risaralda-colombia\/","url_meta":{"origin":75557,"position":0},"title":"\ud83c\udde8\ud83c\uddf4 Resultados 4ta Copa Calypso Yubarta de Nataci\u00f3n con Aletas, Pereira \u2013 Colombia","author":"Sportalsub.net","date":"28 octubre 2025","format":false,"excerpt":"(Sportalsub.net \/ Club Subacu\u00e1tico Calypso) Con una excelente participaci\u00f3n de m\u00e1s de 175 deportistas de 14 equipos se realiz\u00f3 con todo \u00e9xito la 4ta edici\u00f3n de la la Copa CALYPSO 2025 con invitaci\u00f3n regional, nacional e internacional, realizada el s\u00e1bado 25 y\u00a0 domingo 26 de Octubre de 2025 en el\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/10\/resultados-calypso-2025-sportalsub.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/10\/resultados-calypso-2025-sportalsub.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/10\/resultados-calypso-2025-sportalsub.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2025\/10\/resultados-calypso-2025-sportalsub.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":65120,"url":"https:\/\/www.sportalsub.net\/blog\/1ra-copa-calypso-rural-natacion-aletas-2023","url_meta":{"origin":75557,"position":1},"title":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211; 1ra Copa Calypso Rural de Nataci\u00f3n con Aletas. La Florida, Risaralda &#8211; Colombia 2023","author":"Sportalsub.net","date":"5 septiembre 2023","format":false,"excerpt":"(Sportalsub.net \/ Club Subacu\u00e1tico Calypso) El Club Deportivo de Actividades Subacu\u00e1ticas CALYPSO, unido a los objetivos de promoci\u00f3n y desarrollo de Nataci\u00f3n con Aletas de la Liga de Actividades Subacu\u00e1ticas de Risaralda \u201cLASER\u201d, organiz\u00f3 el CAMPEONATO DEPARTAMENTAL \u201c 1 PRIMERA COPA CALYPSO RURAL \u201c FESTIVAL DE ESTILOS \u201c FIESTAS DE\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/08\/copacalypsorural2023resultados.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/08\/copacalypsorural2023resultados.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/08\/copacalypsorural2023resultados.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2023\/08\/copacalypsorural2023resultados.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":55906,"url":"https:\/\/www.sportalsub.net\/blog\/copa-calypso-nadosub-2022","url_meta":{"origin":75557,"position":2},"title":"\ud83c\udde8\ud83c\uddf4 Resultados &#8211; Copa Calypso 30 a\u00f1os Campeonato Departamental de Nataci\u00f3n con Aletas 2022 &#8211; Pereira, Colombia","author":"Sportalsub.net","date":"21 agosto 2022","format":false,"excerpt":"(Sportalsub.net \/ Club Subacu\u00e1tico Calypso) El Club Deportivo de Actividades Subacu\u00e1ticas CALYPSO, con aval de la Liga de Actividades Subacu\u00e1ticas de Risaralda \u201cLASER\u201d, organiz\u00f3 la COPA COLOMBIA TEMATICA CALYPSO 30 A\u00d1OS, CAMPEONATO DEPARTAMENTAL por categor\u00edas\u00a0 Infantil, Juvenil, Mayores y Master \u00a0En las \u00a0Piscina \u00a0ol\u00edmpicas\u00a0 de la\u00a0 ciudad de Pereira\u00a0 \u201cEsta\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/07\/copacalypso2022web.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/07\/copacalypso2022web.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/07\/copacalypso2022web.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2022\/07\/copacalypso2022web.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":86389,"url":"https:\/\/www.sportalsub.net\/blog\/5ta-copa-calypso-aletas-pereira-colombia","url_meta":{"origin":75557,"position":3},"title":"\ud83c\udde8\ud83c\uddf4 5ta Copa Calypso de Nataci\u00f3n con Aletas y Festival de Estilos 2026, Pereira \u2013 Colombia","author":"Sportalsub.net","date":"7 agosto 2026","format":false,"excerpt":"(Sportalsub.net \/ Club Subacu\u00e1tico Calypso) El \u00f3rgano de Administraci\u00f3n del Club Deportivo Calypso, con el apoyo, el compromiso y debidamente autorizado por la Liga de Actividades Subacu\u00e1ticas de Risaralda \u2013 LASER, se permite invitar a la 5\u00aaversion de la COPA CALYPSO de \u201cNataci\u00f3n con Aletas y Festival de Estilos \u201c\u2026","rel":"","context":"En \u00abColombia\u00bb","block_context":{"text":"Colombia","link":"https:\/\/www.sportalsub.net\/blog\/category\/paises\/america\/colombia\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2026\/07\/5ta-copa-calypso.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2026\/07\/5ta-copa-calypso.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2026\/07\/5ta-copa-calypso.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2026\/07\/5ta-copa-calypso.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":28348,"url":"https:\/\/www.sportalsub.net\/blog\/diplomado-de-natacion-y-o-subacuatica-en-pereira-colombia\/","url_meta":{"origin":75557,"position":4},"title":"\ud83c\udde8\ud83c\uddf4 Diplomado de Nataci\u00f3n y\/o Subacu\u00e1tica Te\u00f3rico, Pr\u00e1ctico en Pereira, Colombia","author":"Sportalsub.net","date":"16 julio 2018","format":false,"excerpt":"(Sportalsub.net \/ Club Subacu\u00e1tico Calypso) El Club Deportivo Subacu\u00e1tico Calypso, de la ciudad de Pereira, Colombia ha dise\u00f1ado el 1er diplomado de Nataci\u00f3n y\/o Subacu\u00e1tica a realizarse durante casi 5 meses, del Viernes 27 de junio hasta el s\u00e1bado 1 de diciembre de 2018. El Diplomado de\u00a0\u00a0Nataci\u00f3n y\/o Subacu\u00e1tica tiene\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/07\/diplomado-dest.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/07\/diplomado-dest.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/07\/diplomado-dest.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2018\/07\/diplomado-dest.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":29797,"url":"https:\/\/www.sportalsub.net\/blog\/club-subacuatico-desde-1992-en-pereira-colombia\/","url_meta":{"origin":75557,"position":5},"title":"\ud83c\udde8\ud83c\uddf4 Club Subacu\u00e1tico Calypso, desde 1992 desarrollando las Actividades Subacu\u00e1ticas en Pereira, Colombia","author":"Sportalsub.net","date":"4 febrero 2020","format":false,"excerpt":"(Sportalsub.net \/ Club Subacu\u00e1tico Calypso) El Club Subacu\u00e1tico Calypso, fundado en 1992, es uno de los pioneros en las actividades subacu\u00e1ticas en la ciudad de Pereira, en el Departamento de Risaralda en Colombia y cuenta con un amplio staff de Monitores, Entrenadores e Instructores. Bajo la direcci\u00f3n de la Lcda.\u2026","rel":"","context":"En \u00abApnea\u00bb","block_context":{"text":"Apnea","link":"https:\/\/www.sportalsub.net\/blog\/category\/modalidades\/apnea\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/01\/clubsubacuaticocalypso.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/01\/clubsubacuaticocalypso.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/01\/clubsubacuaticocalypso.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.sportalsub.net\/blog\/wp-content\/uploads\/2019\/01\/clubsubacuaticocalypso.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_featured_media_url":"https:\/\/www.sportalsub.net\/blog\/wp-content\/uploads\/2024\/10\/3racopacalypsosportalsub.jpg","_links":{"self":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/75557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/comments?post=75557"}],"version-history":[{"count":5,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/75557\/revisions"}],"predecessor-version":[{"id":76179,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/posts\/75557\/revisions\/76179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media\/75558"}],"wp:attachment":[{"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/media?parent=75557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/categories?post=75557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sportalsub.net\/blog\/wp-json\/wp\/v2\/tags?post=75557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}